{"id":9665,"date":"2019-04-08T07:05:14","date_gmt":"2019-04-08T10:05:14","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=9665"},"modified":"2019-04-08T07:10:40","modified_gmt":"2019-04-08T10:10:40","slug":"precio-al-productor-mejora-en-febrero-respecto-al-mes-anterior","status":"publish","type":"post","link":"https:\/\/lahoradelcampo.com.uy\/site\/precio-al-productor-mejora-en-febrero-respecto-al-mes-anterior\/","title":{"rendered":"Precio al productor: mejora en febrero respecto al mes anterior"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Lecheria.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9667\" data-permalink=\"https:\/\/lahoradelcampo.com.uy\/site\/precio-al-productor-mejora-en-febrero-respecto-al-mes-anterior\/lecheria-11\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Lecheria.jpg?fit=880%2C440&amp;ssl=1\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Lecheria\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Lecheria.jpg?fit=810%2C405&amp;ssl=1\" class=\"aligncenter size-full wp-image-9667\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Lecheria.jpg?resize=810%2C405\" alt=\"\" width=\"810\" height=\"405\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Lecheria.jpg?w=880&amp;ssl=1 880w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Lecheria.jpg?resize=300%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Lecheria.jpg?resize=768%2C384&amp;ssl=1 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Lecheria.jpg?resize=820%2C410&amp;ssl=1 820w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/p>\n<p>El precio al productor estimado para febrero es de $ 9,61 por litro (US$ 0,29) registrando un valor 2% superior al de enero (en pesos y d\u00f3lares).<\/p>\n<p>El precio por kilo de s\u00f3lidos fue de $ 133 por kilo, valor que se mantuvo comparado con el mes anterior. Comparado con el precio de un a\u00f1o atr\u00e1s es un 2% inferior en pesos y en d\u00f3lares el descenso fue de 14%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El precio al productor estimado para febrero es de $ 9,61 por litro (US$ 0,29) registrando un valor 2% superior al de enero (en pesos y d\u00f3lares). El precio por [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":9667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,11],"tags":[111,513,25,441,693],"class_list":["post-9665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-lecheria","tag-inale","tag-instituto-nacional-de-la-leche","tag-lecheria","tag-precio","tag-productor"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Lecheria.jpg?fit=880%2C440&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-2vT","jetpack-related-posts":[{"id":1729,"url":"https:\/\/lahoradelcampo.com.uy\/site\/precio-recibido-por-el-tambero-cayo-un-1-en-agosto\/","url_meta":{"origin":9665,"position":0},"title":"Precio recibido por el tambero cay\u00f3 un 1% en agosto","author":"La Hora del Campo","date":"25 septiembre, 2017","format":false,"excerpt":"Durante el mes de agosto, seg\u00fan las estimaciones realizadas por el Instituto Nacional de la Leche en base a las declaraciones de la industria l\u00e1ctea, el precio promedio recibido por el productor lechero descendi\u00f3 un 1% respecto al mes de julio, medido tanto en pesos uruguayos como en d\u00f3lares. El\u2026","rel":"","context":"En \u00abLecher\u00eda\u00bb","block_context":{"text":"Lecher\u00eda","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/lecheria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Lecheria.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Lecheria.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Lecheria.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Lecheria.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":20292,"url":"https:\/\/lahoradelcampo.com.uy\/site\/abril-mes-positivo-para-la-lecheria-en-uruguay\/","url_meta":{"origin":9665,"position":1},"title":"Abril: mes positivo para la lecher\u00eda en Uruguay","author":"La Hora del Campo","date":"28 mayo, 2020","format":false,"excerpt":"De acuerdo a los datos aportados por el Instituto Nacional de la Leche (INALE), durante el mes de abril de 2020 el sector lechero produjo m\u00e1s leche, recibi\u00f3 m\u00e1s dinero por litro y una leve mejora en el poder de compra del productor. Remisi\u00f3n a planta Durante el cuarto mes\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/lecheria.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/lecheria.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/lecheria.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/lecheria.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3327,"url":"https:\/\/lahoradelcampo.com.uy\/site\/poder-de-compra-de-la-leche-se-mantiene-5-sobre-2016\/","url_meta":{"origin":9665,"position":2},"title":"Poder de compra de la leche se mantiene 5% sobre 2016","author":"La Hora del Campo","date":"29 octubre, 2017","format":false,"excerpt":"En setiembre descendi\u00f3 el poder de compra comparado con el mes anterior dado por la ca\u00edda en el precio de la leche y un leve aumento en el \u00edndice de costo. Si se compara con diciembre aument\u00f3 el poder de compra de la leche un 5%, debido al incremento del\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Lecheria-2.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Lecheria-2.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Lecheria-2.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Lecheria-2.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":55913,"url":"https:\/\/lahoradelcampo.com.uy\/site\/el-precio-de-la-leche-en-tambo-subio-4-en-dolares\/","url_meta":{"origin":9665,"position":3},"title":"El precio de la leche en tambo, subi\u00f3 4% en d\u00f3lares","author":"La Hora del Campo","date":"18 abril, 2025","format":false,"excerpt":"Los precios medios de la leche registraron importantes variaciones durante febrero de 2025, marcando un escenario de contrastes entre el mercado externo e interno. Mientras que los valores en d\u00f3lares recibidos por la exportaci\u00f3n aumentaron 13% frente a febrero del a\u00f1o pasado, el precio en el mercado interno cay\u00f3 un\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/04\/INALE-Preciosleche.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/04\/INALE-Preciosleche.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/04\/INALE-Preciosleche.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/04\/INALE-Preciosleche.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":30136,"url":"https:\/\/lahoradelcampo.com.uy\/site\/precio-en-dolares-recibido-por-la-industria-lactea-cayo-2\/","url_meta":{"origin":9665,"position":4},"title":"Precio en d\u00f3lares recibido por la industria l\u00e1ctea cay\u00f3 2%","author":"La Hora del Campo","date":"15 mayo, 2021","format":false,"excerpt":"Seg\u00fan los datos presentados por el Instituto Nacional de la Leche (INALE) en su informe mensual de precios recibidos en la cadena l\u00e1ctea, se observa un descenso para el mes de marzo del 2% en el valor recibido por la industria l\u00e1ctea, respecto a igual mes de 2020. Esta baja\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/lecheria-brasil.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/lecheria-brasil.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/lecheria-brasil.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/lecheria-brasil.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":10471,"url":"https:\/\/lahoradelcampo.com.uy\/site\/subio-el-precio-al-tambero-pero-su-poder-de-compra-empeoro\/","url_meta":{"origin":9665,"position":5},"title":"Subi\u00f3 el precio al tambero pero su poder de compra empeor\u00f3","author":"La Hora del Campo","date":"6 mayo, 2019","format":false,"excerpt":"Litro de leche remitido a planta aument\u00f3 un 3,7% entre febrero y marzo. Poder de compra cay\u00f3 un 10%.","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Lecheria.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Lecheria.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Lecheria.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Lecheria.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/9665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=9665"}],"version-history":[{"count":1,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/9665\/revisions"}],"predecessor-version":[{"id":9669,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/9665\/revisions\/9669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/9667"}],"wp:attachment":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=9665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=9665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=9665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}