{"id":57617,"date":"2026-07-14T19:52:27","date_gmt":"2026-07-14T22:52:27","guid":{"rendered":"https:\/\/lahoradelcampo.com.uy\/site\/?p=57617"},"modified":"2026-07-14T19:52:28","modified_gmt":"2026-07-14T22:52:28","slug":"parodi-hay-que-permitirse-ver-garrapata-en-el-ganado","status":"publish","type":"post","link":"https:\/\/lahoradelcampo.com.uy\/site\/parodi-hay-que-permitirse-ver-garrapata-en-el-ganado\/","title":{"rendered":"Parodi: Hay que permitirse ver garrapata en el ganado"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/06\/garrapataweb.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"405\" data-attachment-id=\"21360\" data-permalink=\"https:\/\/lahoradelcampo.com.uy\/site\/laboratorio-de-udelar-se-instalara-en-artigas-para-el-estudio-de-la-garrapata\/garrapataweb\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/06\/garrapataweb.jpg?fit=880%2C440&amp;ssl=1\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"garrapataweb\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/06\/garrapataweb.jpg?fit=810%2C405&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/06\/garrapataweb.jpg?resize=810%2C405\" alt=\"\" class=\"wp-image-21360\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/06\/garrapataweb.jpg?w=880&amp;ssl=1 880w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/06\/garrapataweb.jpg?resize=300%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/06\/garrapataweb.jpg?resize=768%2C384&amp;ssl=1 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/06\/garrapataweb.jpg?resize=820%2C410&amp;ssl=1 820w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El Dr. Pablo Parodi, t\u00e9cnico del INIA, plantea la necesidad de modificar de forma estructural la conducta frente a la presencia de la garrapata en el campo. Las evaluaciones tradicionales de laboratorio destinadas a diagnosticar la multirresistencia, procesadas mediante bioensayos in vitro que demandan un per\u00edodo estimado de dos meses y medio para la entrega de resultados, coexisten actualmente con metodolog\u00edas de evaluaci\u00f3n directa en cada predio. El monitoreo a campo permite a los establecimientos rurales determinar la eficacia real de los principios activos de forma \u00e1gil y oportuna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La metodolog\u00eda de seguimiento directo en el predio se estructura a partir de la conformaci\u00f3n de lotes de prueba para evaluar de forma comparativa el desempe\u00f1o de diferentes grupos qu\u00edmicos. El protocolo sugerido por el t\u00e9cnico de INIA, consiste en la selecci\u00f3n aleatoria de 20 animales por cada principio activo que el productor pretenda testear, como podr\u00eda ser el caso, por ejemplo, de confrontar la eficacia de un fipronil frente a una ivermectina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La t\u00e9cnica requiere el conteo al d\u00eda cero, que debe ser la base para evaluar la respuesta de los productos, momento exacto en el que se procede a la aplicaci\u00f3n del tratamiento farmacol\u00f3gico correspondiente a cada lote. Posteriormente, el personal debe retornar a los corrales al d\u00eda diez para efectuar una segunda cuantificaci\u00f3n de los par\u00e1sitos viables sobre el lomo del ganado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La comparaci\u00f3n de ambos registros arroja el porcentaje exacto de reducci\u00f3n poblacional de la plaga, aportando un dato certero sobre la sensibilidad o resistencia de los \u00e1caros en esa fracci\u00f3n espec\u00edfica del establecimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La implementaci\u00f3n de esta tecnolog\u00eda en las rutinas de trabajo del medio rural no requiere de instrumental sofisticado, pero s\u00ed demanda el entrenamiento espec\u00edfico del personal para asegurar la fidelidad de la informaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, el Dr. Parodi detalla las caracter\u00edsticas del procedimiento y la facilidad de su adopci\u00f3n por parte de los operarios: \u201cEs una tecnolog\u00eda para la que tenemos necesariamente que entrenar a un funcionario rural que sepa cuantificar, a trav\u00e9s de la t\u00e9cnica de palpaci\u00f3n. B\u00e1sicamente es palpar el animal e ir contando aquellas garrapatas que tengan m\u00e1s de 4 o 5 mil\u00edmetros, ya son garrapatas visibles, f\u00e1cilmente contables. Los funcionarios que se entrenan en esto son muy \u00e1giles, lo puede hacer un funcionario, lo puede hacer el propietario o un t\u00e9cnico actuante. Y b\u00e1sicamente esa es la tecnolog\u00eda: contamos, tratamos y vamos a contar nuevamente\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En algunos casos, los t\u00e9cnicos consideran que existe un exceso de ansiedad a nivel de los productores. La visualizaci\u00f3n de un n\u00famero marginal de garrapatas sobre el ganado suele desencadenar la aplicaci\u00f3n inmediata de tratamientos qu\u00edmicos, una pr\u00e1ctica que acelera de forma dr\u00e1stica los procesos de selecci\u00f3n gen\u00e9tica y consolidaci\u00f3n de poblaciones multirresistentes. El t\u00e9cnico de INIA dijo que debe generarse un cambio conceptual a nivel productivo, invitando a los ganaderos a entender que la simple presencia del par\u00e1sito sobre el animal no guarda una relaci\u00f3n lineal directa con un detrimento en los indicadores f\u00edsicos y productivos de los ganados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentido afirm\u00f3 que las investigaciones en Uruguay han logrado validar umbrales de presencia del par\u00e1sito en cada generaci\u00f3n. Los registros demuestran que durante el desarrollo de la primera y la segunda generaci\u00f3n del \u00e1caro, la coexistencia con una carga biol\u00f3gica de entre cinco y ocho garrapatas por animal representa un escenario perfectamente inocuo que no altera la ganancia de peso ni la condici\u00f3n corporal. Asimismo, los m\u00e1rgenes de tolerancia se expanden en la tercera generaci\u00f3n, etapa donde los rodeos comerciales pueden soportar una presencia de entre 20 y 25 garrapatas por cabeza sin registrar p\u00e9rdidas de kilos en las pasturas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTener garrapatas no es igual a menor producci\u00f3n. Hay umbrales, que en Uruguay se han establecido, de visualizaci\u00f3n de garrapatas por la primera generaci\u00f3n, segunda generaci\u00f3n y dem\u00e1s. Entonces eso debe ser el primer cambio de paradigma del productor es permitirse ver garrapata\u201d dijo Dr. Pablo Parodi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El profesional explic\u00f3 que \u201cpermitirse ver garrapatas\u201d en el ganado, reducir las aplicaciones de qu\u00edmicos, va de la mano de la inmunizaci\u00f3n del rodeo vacuno con la hemovacuna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salto 14 de julio de 2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Dr. Pablo Parodi, t\u00e9cnico del INIA, plantea la necesidad de modificar de forma estructural la conducta frente a la presencia de la garrapata en el campo. Las evaluaciones tradicionales [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":21360,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,5],"tags":[],"class_list":["post-57617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-ganaderia"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/06\/garrapataweb.jpg?fit=880%2C440&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-eZj","jetpack-related-posts":[{"id":54633,"url":"https:\/\/lahoradelcampo.com.uy\/site\/garrapata-y-abortos-temas-centrales-en-jornada-de-sanidad-animal\/","url_meta":{"origin":57617,"position":0},"title":"Garrapata y abortos: temas centrales en jornada de sanidad animal","author":"La Hora del Campo","date":"23 septiembre, 2024","format":false,"excerpt":"El Centro M\u00e9dico Veterinario de Tacuaremb\u00f3, junto a la Plataforma de Salud Animal de INIA, invitan a una jornada sobre las p\u00e9rdidas reproductivas en rodeos de cr\u00eda y el control de garrapatas multiresistentes, que se realizar\u00e1 en las instalaciones de la estaci\u00f3n experimental de Tacuaremb\u00f3, el jueves 10 de octubre,\u2026","rel":"","context":"En \u00abGanader\u00eda\u00bb","block_context":{"text":"Ganader\u00eda","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/ganaderia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/06\/garrapataweb.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/06\/garrapataweb.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/06\/garrapataweb.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/06\/garrapataweb.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":56615,"url":"https:\/\/lahoradelcampo.com.uy\/site\/uruguay-lanza-un-plan-integral-para-combatir-la-garrapata-y-proteger-la-ganaderia\/","url_meta":{"origin":57617,"position":1},"title":"Uruguay lanza un plan integral para combatir la garrapata y proteger la ganader\u00eda","author":"La Hora del Campo","date":"20 agosto, 2025","format":false,"excerpt":"El Ministerio de Ganader\u00eda, Agricultura y Pesca (MGAP) junto al Instituto Nacional de Investigaci\u00f3n Agropecuaria (INIA) realizar\u00e1n el pr\u00f3ximo jueves 21 de agosto, a partir de las 16:00 horas en el CENUR Litoral Norte de Salto, la jornada \"Hacia una estrategia efectiva para el control de la garrapata en Uruguay\",\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/08\/garrapatas.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/08\/garrapatas.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/08\/garrapatas.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/08\/garrapatas.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":37675,"url":"https:\/\/lahoradelcampo.com.uy\/site\/comienza-la-2a-generacion-de-la-garrapata-y-hay-que-seguir-el-plan-sanitario\/","url_meta":{"origin":57617,"position":2},"title":"Comienza la 2\u00aa generaci\u00f3n de la garrapata y hay que seguir el plan sanitario","author":"La Hora del Campo","date":"17 diciembre, 2021","format":false,"excerpt":"Entramos en diciembre en la segunda generaci\u00f3n de la garrapata, que se extiende aproximadamente hasta fines de febrero, por lo que es importante continuar con el plan sanitario planificado con el m\u00e9dico veterinario, realizando la rotaci\u00f3n de los principios activos. El Dr. Horacio Mederos, de Biog\u00e9nesis Bag\u00f3, brind\u00f3 recomendaciones para\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/12\/Biogenesis-garrapata.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/12\/Biogenesis-garrapata.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/12\/Biogenesis-garrapata.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/12\/Biogenesis-garrapata.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":33048,"url":"https:\/\/lahoradelcampo.com.uy\/site\/dgsg-exhorta-a-iniciar-tratamiento-contra-la-garrapata-en-agosto\/","url_meta":{"origin":57617,"position":3},"title":"DGSG exhorta a iniciar tratamiento contra la garrapata en agosto","author":"La Hora del Campo","date":"13 agosto, 2021","format":false,"excerpt":"En la jornada de ayer, la Direcci\u00f3n General de Servicios Ganaderos del Ministerio de Ganader\u00eda, Agricultura y Pesca (MGAP) exhort\u00f3 a los productores, mediante un comunicado, a iniciar los tratamientos para el combate contra la garrapata en el mes de agosto. En este sentido recomienda asesorarse y planificar con el\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/08\/Garrapata.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/08\/Garrapata.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/08\/Garrapata.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/08\/Garrapata.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":55008,"url":"https:\/\/lahoradelcampo.com.uy\/site\/mgap-y-brou-acordaron-asistencia-financiera-para-el-control-de-la-garrapata-bovina\/","url_meta":{"origin":57617,"position":4},"title":"MGAP y BROU acordaron asistencia financiera para el control de la garrapata bovina","author":"La Hora del Campo","date":"30 octubre, 2024","format":false,"excerpt":"Este lunes 28 de octubre, el Banco Rep\u00fablica comunic\u00f3 al Ministerio de Ganader\u00eda, Agricultura y Pesca (MGAP) las condicionantes para brindar asistencia financiera para el control de la garrapata bovina. Esta asistencia forma parte de la resoluci\u00f3n del foro regional sobre la parasitosis realizada en el departamento de Rivera. Los\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/10\/garrapata.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/10\/garrapata.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/10\/garrapata.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/10\/garrapata.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":56316,"url":"https:\/\/lahoradelcampo.com.uy\/site\/despacho-de-tropa-si-no-conoces-el-predio-es-un-riesgo-muy-grande\/","url_meta":{"origin":57617,"position":5},"title":"Despacho de tropa: \u00abSi no conoc\u00e9s el predio, es un riesgo muy grande\u00bb","author":"La Hora del Campo","date":"15 julio, 2025","format":false,"excerpt":"El presidente del Centro M\u00e9dico Veterinario de Salto, Dr. Jaime Sanch\u00eds, se\u00f1al\u00f3 que \"el problema de la garrapata viene desde hace a\u00f1os y en el norte estamos bastante m\u00e1s complicados que en el este del pa\u00eds\" y agreg\u00f3 que \"de los test de sensibilidad que realizamos en la mayor\u00eda de\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/07\/Dr-Jaime-Sanchis.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/07\/Dr-Jaime-Sanchis.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/07\/Dr-Jaime-Sanchis.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/07\/Dr-Jaime-Sanchis.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/57617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=57617"}],"version-history":[{"count":1,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/57617\/revisions"}],"predecessor-version":[{"id":57618,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/57617\/revisions\/57618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/21360"}],"wp:attachment":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=57617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=57617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=57617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}