{"id":56564,"date":"2025-08-13T06:52:22","date_gmt":"2025-08-13T09:52:22","guid":{"rendered":"https:\/\/lahoradelcampo.com.uy\/site\/?p=56564"},"modified":"2025-08-13T06:52:24","modified_gmt":"2025-08-13T09:52:24","slug":"el-valor-del-cordero-en-gancho-de-carniceria-subio-19","status":"publish","type":"post","link":"https:\/\/lahoradelcampo.com.uy\/site\/el-valor-del-cordero-en-gancho-de-carniceria-subio-19\/","title":{"rendered":"El valor del cordero en gancho de carnicer\u00eda subi\u00f3 19%"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/08\/cordero-en-gancho.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"405\" data-attachment-id=\"56565\" data-permalink=\"https:\/\/lahoradelcampo.com.uy\/site\/el-valor-del-cordero-en-gancho-de-carniceria-subio-19\/cordero-en-gancho\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/08\/cordero-en-gancho.jpg?fit=880%2C440&amp;ssl=1\" data-orig-size=\"880,440\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"cordero en gancho\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/08\/cordero-en-gancho.jpg?fit=810%2C405&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/08\/cordero-en-gancho.jpg?resize=810%2C405&#038;ssl=1\" alt=\"\" class=\"wp-image-56565\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/08\/cordero-en-gancho.jpg?w=880&amp;ssl=1 880w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/08\/cordero-en-gancho.jpg?resize=300%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/08\/cordero-en-gancho.jpg?resize=768%2C384&amp;ssl=1 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/08\/cordero-en-gancho.jpg?resize=820%2C410&amp;ssl=1 820w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/figure>\n\n\n\n<p>El mercado interno para la carne ovina est\u00e1 muy limitado a un consumo de 2,6 kilos per c\u00e1pita, de acuerdo con el dato del Instituto Nacional de Carnes (INAC) para 2024, comercializ\u00e1ndose sus mayores vol\u00famenes en noviembre y diciembre, de cara a las tradicionales fiestas de fin de a\u00f1o. Esto lleva al persistente reclamo del sector productivo de incentivar el consumo a nivel interno.<\/p>\n\n\n\n<p>INAC semanalmente brinda el valor del kilogramo de carcasa de cordero, en gancho de carnicer\u00eda, destinado al mercado interno, el cual, en la semana al 2 de agosto, se ubic\u00f3 en US$ 7,02 por kilogramo con impuestos incluidos. Este valor fue superado en agosto y setiembre de 2022, cuando la demanda china por carne ovina determin\u00f3 una suba exponencial en los precios.<\/p>\n\n\n\n<p>En el largo plazo, en julio de 2025 el valor promedio de la tonelada comercializada al mercado interno fue de US$ 6.925, con un aumento anual de 19%. El valor medio de la carne de cordero destinada al mercado interno se ha mantenido durante todo \u00faltimo a\u00f1o por encima del promedio de la tonelada del novillo, aunque el premio naj\u00f3 a casi la mitad desde marzo.<\/p>\n\n\n\n<p><strong>Exportaci\u00f3n<\/strong><\/p>\n\n\n\n<p>Los datos de Aduanas no informan el dato del valor medio de exportaci\u00f3n de la tonelada de carne de cordero. Si bien se debe detallar la exportaci\u00f3n de las carcasas de cordero, tanto congeladas como enfriadas, en el caso de los cortes los Documentos \u00danicos de Aduana (Dua) no discriminan si pertenecen a carne de cordero o si son carne de animales adultos. Por lo tanto, no se puede llegar a un valor promedio de la tonelada de carne de cordero exportada.<\/p>\n\n\n\n<p>Salto, 13 de agosto de 2025<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mercado interno para la carne ovina est\u00e1 muy limitado a un consumo de 2,6 kilos per c\u00e1pita, de acuerdo con el dato del Instituto Nacional de Carnes (INAC) para [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":56565,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,13],"tags":[],"class_list":["post-56564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-ovinos"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/08\/cordero-en-gancho.jpg?fit=880%2C440&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-eIk","jetpack-related-posts":[{"id":43245,"url":"https:\/\/lahoradelcampo.com.uy\/site\/cae-el-precio-de-la-carne-en-gancho-de-carniceria\/","url_meta":{"origin":56564,"position":0},"title":"Cae el precio de la carne  en gancho de carnicer\u00eda","author":"La Hora del Campo","date":"28 junio, 2022","format":false,"excerpt":"En la \u00faltima semana de informaci\u00f3n de INAC, el valor de la carne en gancho de carnicer\u00eda registr\u00f3 un descenso del 0,16% en los novillos y del 1,24% en el caso de las vacas. En el registro de INAC, para la semana cerrada el 18 de junio, los valores del\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/12\/Carnevacuna.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/12\/Carnevacuna.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/12\/Carnevacuna.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/12\/Carnevacuna.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":17600,"url":"https:\/\/lahoradelcampo.com.uy\/site\/el-precio-del-cordero-pesado-cayo-un-12\/","url_meta":{"origin":56564,"position":1},"title":"El precio del cordero pesado cay\u00f3 un 12%","author":"La Hora del Campo","date":"22 febrero, 2020","format":false,"excerpt":"El valor del cordero pesado pag\u00f3 al productor en la \u00faltima semana, cerrada el 15 de febrero, determin\u00f3 una ca\u00edda del 12% respecto a la primera semana del a\u00f1o de acuerdo a los datos propuestos por el Instituto Nacional de Carnes (INAC). El valor del cordero pesado en cuarta balanza\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/05\/corderos.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/05\/corderos.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/05\/corderos.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/05\/corderos.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":41045,"url":"https:\/\/lahoradelcampo.com.uy\/site\/precio-del-cordero-al-productor-sube-un-33-en-2022\/","url_meta":{"origin":56564,"position":2},"title":"Precio del cordero al productor sube un 33% en 2022","author":"La Hora del Campo","date":"22 abril, 2022","format":false,"excerpt":"Durante las primeras 15 semanas del 2022, el valor promedio del cordero pesado en cuarta balanza ha registrado una suba del 33,2% respecto a igual per\u00edodo de 2021. Teniendo en cuenta lo sucedido entre 2012 y 2021, se pueden registrar dos escenarios posibles de valores para las \u00faltimas 15 semanas\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/04\/Corderos-carne-ovina.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/04\/Corderos-carne-ovina.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/04\/Corderos-carne-ovina.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/04\/Corderos-carne-ovina.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":52899,"url":"https:\/\/lahoradelcampo.com.uy\/site\/se-exporta-mas-carne-ovina-pero-un-24-mas-barata-que-en-2022\/","url_meta":{"origin":56564,"position":3},"title":"Se exporta m\u00e1s carne ovina, pero un 24% m\u00e1s barata que en 2022","author":"La Hora del Campo","date":"26 octubre, 2023","format":false,"excerpt":"De acuerdo a los datos publicados por el Instituto Nacional de Carnes (INAC), se llevan exportadas hasta el pasado 21 de octubre, un total de 18.229 toneladas de carne ovina, a un valor promedio de US$ 3.896 peso canal. Al observar esta cifras en comparaci\u00f3n con igual per\u00edodo del a\u00f1o\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/10\/ovinos-inacprecios.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/10\/ovinos-inacprecios.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/10\/ovinos-inacprecios.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/10\/ovinos-inacprecios.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":29282,"url":"https:\/\/lahoradelcampo.com.uy\/site\/precio-del-cordero-al-productor-cayo-un-167-en-el-primer-trimestre\/","url_meta":{"origin":56564,"position":4},"title":"Precio del cordero al productor cay\u00f3 un 16,7% en el primer trimestre","author":"La Hora del Campo","date":"16 abril, 2021","format":false,"excerpt":"De acuerdo a los datos aportados por el Instituto Nacional de Carnes (INAC) entre enero y marzo, las exportaciones de carne ovina han venido en aumento respecto a igual per\u00edodo del a\u00f1o pasado. En dicho per\u00edodo se exportaron 7.292 toneladas peso canal de este tipo de carnes, que representaron un\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/05\/corderos.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/05\/corderos.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/05\/corderos.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/05\/corderos.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":27790,"url":"https:\/\/lahoradelcampo.com.uy\/site\/con-mayor-exportacion-de-carne-ovina-el-precio-al-productor-cayo-un-21\/","url_meta":{"origin":56564,"position":5},"title":"Con mayor exportaci\u00f3n de carne ovina, el precio al productor cay\u00f3 un 21%","author":"La Hora del Campo","date":"18 febrero, 2021","format":false,"excerpt":"De acuerdo a los datos aportados por el Instituto Nacional de Carnes (INAC) entre el 3 de enero y el 6 de febrero, las exportaciones de carne ovina han venido en aumento respecto a igual per\u00edodo del a\u00f1o pasado. En dicho per\u00edodo se exportaron 2.402 toneladas peso canal de este\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/ovinos.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/ovinos.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/ovinos.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/ovinos.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/56564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=56564"}],"version-history":[{"count":1,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/56564\/revisions"}],"predecessor-version":[{"id":56566,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/56564\/revisions\/56566"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/56565"}],"wp:attachment":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=56564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=56564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=56564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}