{"id":54650,"date":"2024-09-24T07:26:46","date_gmt":"2024-09-24T10:26:46","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=54650"},"modified":"2024-09-25T12:16:01","modified_gmt":"2024-09-25T15:16:01","slug":"indicadores-del-equino-caen-en-los-primeros-ochos-meses-del-2024","status":"publish","type":"post","link":"https:\/\/lahoradelcampo.com.uy\/site\/indicadores-del-equino-caen-en-los-primeros-ochos-meses-del-2024\/","title":{"rendered":"Indicadores del equino caen en los primeros ochos meses del 2024"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/faena-equina.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"598\" data-attachment-id=\"54651\" data-permalink=\"https:\/\/lahoradelcampo.com.uy\/site\/indicadores-del-equino-caen-en-los-primeros-ochos-meses-del-2024\/faena-equina-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/faena-equina.jpg?fit=1488%2C1099&amp;ssl=1\" data-orig-size=\"1488,1099\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"faena equina\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/faena-equina.jpg?fit=810%2C598&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/faena-equina-1024x756.jpg?resize=810%2C598\" alt=\"\" class=\"wp-image-54651\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/faena-equina.jpg?resize=1024%2C756&amp;ssl=1 1024w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/faena-equina.jpg?resize=300%2C222&amp;ssl=1 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/faena-equina.jpg?resize=768%2C567&amp;ssl=1 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/faena-equina.jpg?resize=80%2C60&amp;ssl=1 80w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/faena-equina.jpg?w=1488&amp;ssl=1 1488w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/figure>\n\n\n\n<p>El sector equino en Uruguay registra un descenso en pr\u00e1cticamente todos los indicadores, salvo el en valor promedio del equino en pie, durante los ocho meses del a\u00f1o, seg\u00fan los datos actualizados por el Instituto Nacional de Carnes (INAC). La faena de equinos ha tenido una ca\u00edda 26,2% en comparaci\u00f3n con el mismo per\u00edodo del a\u00f1o anterior, lo cual se ha visto reflejado en una baja del 16,8% en el volumen de carne equina exportada.<\/p>\n\n\n\n<p>El precio de la tonelada de carne equina tambi\u00e9n ha tenido una ca\u00edda, pero en este caso es del 2,1% entre a\u00f1os, lo cual tambi\u00e9n incide en el menor nivel de ingresos que registra el pa\u00eds por las exportaciones de este tipo de carnes. Por su parte, los precios de los equinos en pie para faena a nivel interno han subido un 8,7%.<\/p>\n\n\n\n<p><strong>Faena<\/strong><\/p>\n\n\n\n<p>La faena equina, ha mostrado un descenso en este 2024, al compararse con el a\u00f1o pasado durante el mismo per\u00edodo. Durante los primeros ocho meses del a\u00f1o, se faenaron 27.768 cabezas, lo que representa una baja del 26,2% respecto a las 37.613 cabezas faenadas en 2023.<\/p>\n\n\n\n<p>La planta de faena Frigor\u00edfico Clay S.A., ubicada en la zona del Sauce en Canelones, es la principal planta de faena a nivel nacional. En este periodo, la planta faen\u00f3 un total de 19.641 cabezas, lo que representa el 71% del total. Adem\u00e1s, la planta registr\u00f3 una ca\u00edda del 11,7% en su actividad de faena.<\/p>\n\n\n\n<p>En segundo lugar, se encuentra la planta de Sarel S.A., tambi\u00e9n en Canelones, con un total de 5.802 equinos faenados. La planta registr\u00f3 un descenso del 37,9% entre a\u00f1os. Por \u00faltimo, la planta de Treinta y Tres, Agroindustrial del Este, se posiciona en tercer lugar con 2.325 cabezas faenadas y una baja del 61,5% en los ocho meses de 2024. Estas plantas representan el 21% y 8% respectivamente.<\/p>\n\n\n\n<p><strong>Precios<\/strong><\/p>\n\n\n\n<p>Seg\u00fan los datos del INAC, el precio del equino en pie para faena registra una suba del 8,7% en el promedio de los ocho meses del a\u00f1o en comparaci\u00f3n con el mismo per\u00edodo del a\u00f1o anterior. El promedio es de $ 46,2 por kilogramo en pie, mientras que en igual per\u00edodo del 2023 era de $ 42,5.<\/p>\n\n\n\n<p>En enero, el precio a nivel del mercado interno estaba fijado en $ 44 el kilogramo en pie, desde all\u00ed fue subiendo mes a mes hasta junio donde cotiz\u00f3 a $ 48,10, luego cay\u00f3 levemente en julio y agosto cerr\u00f3 en $ 50,10 por kilogramo en pie.<\/p>\n\n\n\n<p><strong>Exportaciones<\/strong><\/p>\n\n\n\n<p>Las exportaciones de carne equina han ca\u00eddo en el volumen comercializado al exterior. Entre enero y agosto se exportaron 4.899 toneladas peso embarque, de carne equina, lo que representa una baja del 16,8%, frente a las 5.890 toneladas del a\u00f1o pasado en igual per\u00edodo.<\/p>\n\n\n\n<p>Por su parte, los ingresos generados por la venta al exterior de este tipo de carnes suma 21.210 miles de d\u00f3lares, lo que representa una baja del 19,1% entre a\u00f1os.<\/p>\n\n\n\n<p>El valor promedio de la tonelada exportada se posicion\u00f3 en US$ 4.371 por tonelada, un 2,1% inferior a los US$ 4.466 de igual per\u00edodo del 2023.<\/p>\n\n\n\n<p>Los principales destinos, analizados en generaci\u00f3n de divisas, han sido Francia (27,2%), Jap\u00f3n (25%) y B\u00e9lgica (15,7%). China mercado al que se accedi\u00f3 este a\u00f1o, representa el 11,9% del total exportado.<\/p>\n\n\n\n<p>Salto, 24 de setiembre de 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sector equino en Uruguay registra un descenso en pr\u00e1cticamente todos los indicadores, salvo el en valor promedio del equino en pie, durante los ocho meses del a\u00f1o, seg\u00fan los [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":54652,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,23],"tags":[],"class_list":["post-54650","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-equinos"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/carne-equina-tonelada.jpg?fit=880%2C440&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-eds","jetpack-related-posts":[{"id":51257,"url":"https:\/\/lahoradelcampo.com.uy\/site\/exportaciones-de-carne-equina-crecieron-175-en-volumen\/","url_meta":{"origin":54650,"position":0},"title":"Exportaciones de carne equina crecieron 17,5% en volumen","author":"La Hora del Campo","date":"15 junio, 2023","format":false,"excerpt":"El sector equino en Uruguay registra un importante crecimiento en los primeros cinco meses del a\u00f1o. Seg\u00fan los datos actualizados por el Instituto Nacional de Carnes (INAC), la faena de equinos ha tenido un incremento del 7,05% en comparaci\u00f3n con el mismo per\u00edodo del a\u00f1o anterior, lo cual se ha\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/06\/equinos1.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/06\/equinos1.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/06\/equinos1.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/06\/equinos1.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":50104,"url":"https:\/\/lahoradelcampo.com.uy\/site\/exportaciones-de-carne-equina-aumentan-un-17-en-el-primer-trimestre-de-2023\/","url_meta":{"origin":54650,"position":1},"title":"Exportaciones de carne equina aumentan un 17% en el primer trimestre","author":"La Hora del Campo","date":"20 abril, 2023","format":false,"excerpt":"El sector equino en Uruguay registra un importante crecimiento en el primer trimestre del a\u00f1o. Seg\u00fan los datos actualizados por el Instituto Nacional de Carnes (INAC), la faena de equinos ha tenido un incremento del 7,5% en comparaci\u00f3n con el mismo per\u00edodo del a\u00f1o anterior, lo cual se ha visto\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/01\/Equinos-general.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/01\/Equinos-general.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/01\/Equinos-general.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/01\/Equinos-general.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":56118,"url":"https:\/\/lahoradelcampo.com.uy\/site\/precio-del-equino-para-faenase-mantiene-firme\/","url_meta":{"origin":54650,"position":2},"title":"Precio del equino para faena se mantiene firme","author":"La Hora del Campo","date":"25 mayo, 2025","format":false,"excerpt":"El sector c\u00e1rnico equino crece en sus vol\u00famenes de exportaci\u00f3n y en la facturaci\u00f3n final, lo que se ha traducido en un mayor nivel de faena y precios firmes en el mercado interno y manteni\u00e9ndose en niveles hist\u00f3ricos, seg\u00fan datos del Instituto Nacional de Carnes (INAC) del primer cuatrimestre del\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/05\/equino-mayo25.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/05\/equino-mayo25.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/05\/equino-mayo25.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/05\/equino-mayo25.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":51920,"url":"https:\/\/lahoradelcampo.com.uy\/site\/exportaciones-volumen-de-carne-equina-cayo-17-en-el-ano-ganadero-22-23\/","url_meta":{"origin":54650,"position":3},"title":"Exportaciones: Volumen de carne equina cay\u00f3 1,7% en el a\u00f1o ganadero 22-23","author":"La Hora del Campo","date":"20 julio, 2023","format":false,"excerpt":"El sector equino en Uruguay redujo 1,7% el volumen de exportaci\u00f3n de carne durante el \u00faltimo a\u00f1o agr\u00edcola ganadero (jul-22\/jun-23), a pesar de ello, las 8.037 toneladas, representan el segundo volumen m\u00e1s importante desde el 2011-12. Seg\u00fan los datos actualizados por el Instituto Nacional de Carnes (INAC), el ingreso de\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/07\/Carneequina.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/07\/Carneequina.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/07\/Carneequina.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/07\/Carneequina.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":43151,"url":"https:\/\/lahoradelcampo.com.uy\/site\/tonelada-de-carne-equina-sube-un-19-en-2022\/","url_meta":{"origin":54650,"position":4},"title":"Tonelada de carne equina sube un 19% en 2022","author":"La Hora del Campo","date":"24 junio, 2022","format":false,"excerpt":"En los primeros cinco meses del 2022, la faena equina registr\u00f3 un descenso del 11% seg\u00fan los datos actualizados por el Instituto Nacional de Carnes (INAC), lo cual ha marcado tambi\u00e9n una ca\u00edda del 7% en el volumen exportado, sin embargo la suba de un 19% en el valor de\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/01\/Equinos-general.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/01\/Equinos-general.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/01\/Equinos-general.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/01\/Equinos-general.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":39957,"url":"https:\/\/lahoradelcampo.com.uy\/site\/precio-del-equino-en-pie-a-faena-cayo-un-35-en-febrero\/","url_meta":{"origin":54650,"position":5},"title":"Precio del equino en pie a faena cay\u00f3 un 3,5% en febrero","author":"La Hora del Campo","date":"17 marzo, 2022","format":false,"excerpt":"De acuerdo a los datos publicados por el Instituto Nacional de Carnes (INAC) este mi\u00e9rcoles 16 de marzo, el valor del equino de m\u00e1s de 380 kilogramos con destino a faena registr\u00f3 un descenso del 3,5% respecto al mes de enero. De acuerdo a los datos publicados por la instituci\u00f3n,\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/01\/Equinos-general.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/01\/Equinos-general.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/01\/Equinos-general.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/01\/Equinos-general.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/54650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=54650"}],"version-history":[{"count":1,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/54650\/revisions"}],"predecessor-version":[{"id":54653,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/54650\/revisions\/54653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/54652"}],"wp:attachment":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=54650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=54650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=54650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}