{"id":54570,"date":"2024-09-13T20:00:00","date_gmt":"2024-09-13T23:00:00","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=54570"},"modified":"2024-09-14T14:46:40","modified_gmt":"2024-09-14T17:46:40","slug":"los-mejores-poll-merino-australiano-po-son-de-la-magdalena","status":"publish","type":"post","link":"https:\/\/lahoradelcampo.com.uy\/site\/los-mejores-poll-merino-australiano-po-son-de-la-magdalena\/","title":{"rendered":"Los mejores Poll Merino Australiano PO son de \u00abLa Magdalena\u00bb"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/Prado24-GCPMAPO.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"405\" data-attachment-id=\"54571\" data-permalink=\"https:\/\/lahoradelcampo.com.uy\/site\/los-mejores-poll-merino-australiano-po-son-de-la-magdalena\/prado24-gcpmapo\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/Prado24-GCPMAPO.jpg?fit=880%2C440&amp;ssl=1\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Prado24-GCPMAPO\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/Prado24-GCPMAPO.jpg?fit=810%2C405&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/Prado24-GCPMAPO.jpg?resize=810%2C405\" alt=\"\" class=\"wp-image-54571\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/Prado24-GCPMAPO.jpg?w=880&amp;ssl=1 880w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/Prado24-GCPMAPO.jpg?resize=300%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/Prado24-GCPMAPO.jpg?resize=768%2C384&amp;ssl=1 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/Prado24-GCPMAPO.jpg?resize=820%2C410&amp;ssl=1 820w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/figure>\n\n\n\n<p>Este viernes, las razas ovinas, en su gran mayor\u00eda productoras de lana, colmaron las pistas de la rural del Prado, donde se observaron ejemplares que marcan la punta de la pir\u00e1mide gen\u00e9tica en cada raza. En el caso de la raza Merino Australiano, los jurados definidos para esta oportunidad fueron el productor, Eduardo Crescionini Grasso y el t\u00e9cnico del Secretariado Uruguayo de la Lana, Jos\u00e9 Francisco Ramos, con la joven Victoria Bazzano como secretaria.<\/p>\n\n\n\n<p>A pesar de que la cantidad de caba\u00f1as y ejemplares que participan en la muestra, es inferior a la que se observa todos los a\u00f1os en la pista de la Expo Salto, los animales presentados por las caba\u00f1as participantes, auguran una exposici\u00f3n salte\u00f1a de muy alto nivel, lo que claramente le dio un gran trabajo al jurado para armar las distintas filas.<\/p>\n\n\n\n<p>En el Puro de Origen, los mejores ejemplares Poll Merino fueron presentados por \u00abLa Magdalena\u00bb de Los Tordos. La caba\u00f1a salte\u00f1a present\u00f3 en la exposici\u00f3n el Gran Campe\u00f3n y Reservado Gran Campe\u00f3n, mientras que en hembras se llevaron la Gran Campeona y Campe\u00f3n Supremo PO, junto con el reservado Gran Campeona.<\/p>\n\n\n\n<p>En el astado, los mejores Puro de Origen, la caba\u00f1a \u00abSanta Catalina\u00bb de Douglas Cortela se llev\u00f3 los t\u00edtulos de Gran Campe\u00f3n y Mejor Vell\u00f3n, mientras que \u00abLa Magdalena\u00bb de Los Tordos obtuvo el reservado Gran Campe\u00f3n y el Tercer Mejor Macho. En hembras, la Gran Campeona fue de Douglas Cortela, con Los Tordos obteniendo la reservada Gran Campeona y el tercer lugar.<\/p>\n\n\n\n<p>En el caso de los ejemplares de Pedigree, en el Poll Merino, el Gran Campe\u00f3n fue de \u00abEl Araz\u00e1\u00bb de Suc, de Arturo Aguerre, el reservado de \u00abSanta Catalina\u00bb de Douglas Cortela, y el Tercer Mejor Macho de \u00abEl Araz\u00e1\u00bb. En hembras, la Gran Campeona fue nuevamente de \u00abLa Magdalena\u00bb de Los Tordos.<\/p>\n\n\n\n<p>En el astado de pedigree, la caba\u00f1a \u00abEl Araz\u00e1\u00bb de Suc. de Arturo Aguerre present\u00f3 al Mejor Ejemplar de la categor\u00eda, llev\u00e1ndose el t\u00edtulo de Campe\u00f3n Supremo y Gran Campe\u00f3n. El reservado Gran Campe\u00f3n fue tambi\u00e9n de Suc. Arturo Aguerre, mientras que el Tercer Mejor Macho fue presentado por Douglas Cortela. En hembras, la Gran Campeona fue de Douglas Cortela, la reservada Gran Campeona y la Tercera Mejor Hembra tambi\u00e9n fueron presentadas por Los Tordos.<\/p>\n\n\n\n<p>Al cierre de las calificaciones, Eduardo Crescionini destac\u00f3 que el Gran Campe\u00f3n astado de Pedigree, de \u00abEl Araza\u00bb diciendo que es \u00abun carnero que lo tiene todo: un excelente peso de vell\u00f3n, camina en la pista con una postura destacada, pesa 128 kilos y cuenta con muy buenos datos, lo que facilit\u00f3 la decisi\u00f3n, adem\u00e1s de tener un gran vell\u00f3n y un largo de mecha excepcional\u00bb.<\/p>\n\n\n\n<p>Salto, 13 de setiembre de 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este viernes, las razas ovinas, en su gran mayor\u00eda productoras de lana, colmaron las pistas de la rural del Prado, donde se observaron ejemplares que marcan la punta de la [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":54571,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,13],"tags":[],"class_list":["post-54570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-ovinos"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/Prado24-GCPMAPO.jpg?fit=880%2C440&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-eca","jetpack-related-posts":[{"id":33683,"url":"https:\/\/lahoradelcampo.com.uy\/site\/productor-de-tambores-calificara-la-raza-ovina-nacional-en-el-prado\/","url_meta":{"origin":54570,"position":0},"title":"Productor de Tambores calificar\u00e1 la raza ovina nacional en el Prado","author":"La Hora del Campo","date":"3 septiembre, 2021","format":false,"excerpt":"En ediciones anteriores le hemos venido adelantando los diferentes especialistas que tendr\u00e1n a su cargo las calificaciones de los mejores ejemplares en el marco de la Expo Prado 2021. En este sentido el productor de R\u00edo Grande del Sur, Brasil, Jos\u00e9 Thiago Machado de Mattos, ser\u00e1 encargado de calificar la\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/09\/merilinprado.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/09\/merilinprado.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/09\/merilinprado.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/09\/merilinprado.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":46011,"url":"https:\/\/lahoradelcampo.com.uy\/site\/la-magdalena-presento-el-campeon-supremo-del-merino-australiano\/","url_meta":{"origin":54570,"position":1},"title":"La Magdalena present\u00f3 el Campe\u00f3n Supremo del Merino Australiano","author":"La Hora del Campo","date":"1 octubre, 2022","format":false,"excerpt":"La pista del Merino Australiano mostr\u00f3 el potencial de la raza, con carneros que pesaron 130 kilos y con 15,2 micras de di\u00e1metro. Se presentaron 40 ejemplares que fueron calificados por Tom Ashby, criador australiano que ya estado tres veces en Salto, seleccionando ejemplares. Veredictos En el astado, la disputa\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/10\/Expo-salto-Lamagdalena.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/10\/Expo-salto-Lamagdalena.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/10\/Expo-salto-Lamagdalena.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/10\/Expo-salto-Lamagdalena.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1077,"url":"https:\/\/lahoradelcampo.com.uy\/site\/gran-campeon-merino-australiano-po-es-de-los-tordos\/","url_meta":{"origin":54570,"position":2},"title":"Gran Campe\u00f3n Merino Australiano PO es de Los Tordos","author":"La Hora del Campo","date":"13 septiembre, 2017","format":false,"excerpt":"El Ing. Fernando Dutra fue el encargado de seleccionar los mejores ejemplares de la raza Merino Australiano, en sus variedades mocho y astado. En las pistas la caba\u00f1a salte\u00f1a, La Magdalena de Los Tordos S en C, obtuvo el Gran Campe\u00f3n PO astado y a la postres el premio al\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Merino-Australiano-Los-Tordos.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Merino-Australiano-Los-Tordos.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Merino-Australiano-Los-Tordos.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Merino-Australiano-Los-Tordos.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":32542,"url":"https:\/\/lahoradelcampo.com.uy\/site\/juan-manuel-gonzalez-sera-el-jurado-del-merino-en-la-prado-2021\/","url_meta":{"origin":54570,"position":3},"title":"Juan Manuel Gonz\u00e1lez ser\u00e1 el jurado del Merino en la Prado 2021","author":"La Hora del Campo","date":"29 julio, 2021","format":false,"excerpt":"D\u00edas atr\u00e1s le dimos a conocer que el Dr. Pedro Scremini, t\u00e9cnico del Secretariado Uruguayo de la Lana, ser\u00e1 el jurado de la raza Hampshire Down. Posteriormente se fueron definiendo jurados de otras razas, entre ellas la Texel, Corriedale y Merino Australiano. En el caso de la raza Merino Australiano,\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/01\/Merino.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/01\/Merino.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/01\/Merino.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/01\/Merino.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2183,"url":"https:\/\/lahoradelcampo.com.uy\/site\/salto-sera-sede-del-merino-australiano-a-nivel-mundial\/","url_meta":{"origin":54570,"position":4},"title":"Salto ser\u00e1 sede del Merino Australiano a nivel mundial","author":"La Hora del Campo","date":"4 octubre, 2017","format":false,"excerpt":"Del 7 al 15 de abril se desarrollar\u00e1 en nuestro pa\u00eds la 10\u00aa Conferencia Mundial Merino Australiano, est\u00e1 es la segunda oportunidad donde este congreso llega a nuestro pa\u00eds, la primera fue en el a\u00f1o 1994, donde fueron recibidas las delegaciones participantes de la cuarta conferencia mundial. Los escenarios son\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Merino-Australiano.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Merino-Australiano.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Merino-Australiano.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Merino-Australiano.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":45613,"url":"https:\/\/lahoradelcampo.com.uy\/site\/tonna-y-la-magdalena-expusieron-el-supremo-merino-australiano\/","url_meta":{"origin":54570,"position":5},"title":"Tonna y La Magdalena expusieron el Supremo Merino Australiano","author":"La Hora del Campo","date":"19 septiembre, 2022","format":false,"excerpt":"La pista del Merino Australiano acot\u00f3 la jura prevista para todo el d\u00eda, solamente a la ma\u00f1ana del d\u00eda viernes debido a que en la tarde se realiz\u00f3 la presentaci\u00f3n de \u201cLana Celeste a Qatar\u201d, con la presencia del Presidente de la Rep\u00fablica, Dr. Luis Lacalle Pou. El jurado, Juan\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/09\/Prado-supremomerino.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/09\/Prado-supremomerino.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/09\/Prado-supremomerino.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/09\/Prado-supremomerino.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/54570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=54570"}],"version-history":[{"count":1,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/54570\/revisions"}],"predecessor-version":[{"id":54572,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/54570\/revisions\/54572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/54571"}],"wp:attachment":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=54570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=54570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=54570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}