{"id":54285,"date":"2024-08-26T07:20:54","date_gmt":"2024-08-26T10:20:54","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=54285"},"modified":"2024-08-26T07:20:56","modified_gmt":"2024-08-26T10:20:56","slug":"indarte-cia-ofrece-criollos-de-largo-aliento-y-pedrigrees-consistentes-en-salto","status":"publish","type":"post","link":"https:\/\/lahoradelcampo.com.uy\/site\/indarte-cia-ofrece-criollos-de-largo-aliento-y-pedrigrees-consistentes-en-salto\/","title":{"rendered":"Indarte &amp; C\u00eda ofrece criollos de largo aliento y pedrigrees consistentes en Salto"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/08\/juanpablogutierrez.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"405\" data-attachment-id=\"54286\" data-permalink=\"https:\/\/lahoradelcampo.com.uy\/site\/indarte-cia-ofrece-criollos-de-largo-aliento-y-pedrigrees-consistentes-en-salto\/juanpablogutierrez\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/08\/juanpablogutierrez.jpg?fit=880%2C440&amp;ssl=1\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"juanpablogutierrez\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/08\/juanpablogutierrez.jpg?fit=810%2C405&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/08\/juanpablogutierrez.jpg?resize=810%2C405\" alt=\"\" class=\"wp-image-54286\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/08\/juanpablogutierrez.jpg?w=880&amp;ssl=1 880w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/08\/juanpablogutierrez.jpg?resize=300%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/08\/juanpablogutierrez.jpg?resize=768%2C384&amp;ssl=1 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/08\/juanpablogutierrez.jpg?resize=820%2C410&amp;ssl=1 820w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/figure>\n\n\n\n<p>El pr\u00f3ximo s\u00e1bado 31 de agosto, a las 16 horas, se realiza en el predio de la Asociaci\u00f3n Agropecuaria de Salto, la 5ta Edici\u00f3n del remate \u00abCriollos para ganar\u00bb, de las caba\u00f1as \u00abLa Porf\u00eda\u00bb de Luis Astore, \u00abEl Rumbo\u00bb de Gustavo De Souza, \u00abSan Telmo\u00bb de H. y D. de Brum, \u00abTres Cerros\u00bb de. A y E. Stolovas y \u00abEl Virar\u00f3\u00bb de H. y A. Mart\u00ednez. Con una oferta de 30 criollos de pedigree, en su mayor\u00eda de potros y potras de resistencia.<\/p>\n\n\n\n<p>Juan Pablo Guti\u00e9rrez, de la firma Indarte &amp; C\u00eda, record\u00f3 que este remate, dentro de la l\u00ednea de resistencia de los caballos criollos, se ha destacado por la calidad de la gen\u00e9tica ofertada por las distintas caba\u00f1as y los logros alcanzados por los compradores en los enduros del a\u00f1o siguiente a las compras, as\u00ed como tambi\u00e9n en otras pruebas de la raza.<\/p>\n\n\n\n<p>\u00abComo todos saben, este remate forma parte de una serie de ventas en distintos lados del pa\u00eds y todos los potrillos y potrancas que van al remate ya est\u00e1n anotados para correr un enduro que se hace en el mayo siguiente a la temporada de los remates y con premios muy interesantes\u00bb dijo el consignatario.<br>En esta oportunidad el enduro de mayo propone US$ 25.000 en premios.<\/p>\n\n\n\n<p>\u00abTenemos el orgullo de poder rematar las caba\u00f1as: La porf\u00eda, El rumbo, El Virar\u00f3, San Telmo y Tres cerros\u00bb dijo Guti\u00e9rrez, quien remarc\u00f3 que \u00ablo que m\u00e1s se destaca en la oferta son los pedigree de los caballos, son caba\u00f1as muy consistentes en los pedigrees para marchas y enduros, para trabajos de largo aliento\u00bb.<br>Si bien, la oferta tradicional es de potras y potros, el integrante de la firma Indarte se\u00f1al\u00f3 que, a pedido de varios criadores, la diferencia de este a\u00f1o es la presencia de un padrillo de caba\u00f1a \u00abLa Porf\u00eda\u00bb, \u00abcon una muy buena sangre, es un producto diferente por su gen\u00e9tica\u00bb indic\u00f3. Adem\u00e1s, se sumar\u00e1n \u00abdos o tres machos castrados muy lindos\u00bb que se ofertar\u00e1n este a\u00f1o.<\/p>\n\n\n\n<p>Las condiciones de venta ser\u00e1n 18 cuotas en d\u00f3lares con cualquier tarjeta, 12 cuotas en d\u00f3lares con administraci\u00f3n propia, previa consulta, 6% de descuento por pago contado, o 180 d\u00edas libres. Se debe consultar previamente por los fletes.<\/p>\n\n\n\n<p>Las preofertas ya est\u00e1n habilitadas para este remate, Gutierrez indic\u00f3 que los criadores ya han comenzado ha realizar sus piques en la web y se llevan m\u00e1s de 15 ejemplares preofertados.<\/p>\n\n\n\n<p>En este sentido record\u00f3 que este a\u00f1o, \u00ablos dos participantes que tengan m\u00e1s preofertas, llevan un bono de 250 d\u00f3lares para la compra\u00bb, mientras que paralelamente \u00abtodas las ofertas tienen un cup\u00f3n que les permite participar previo al remate en un sorteo de 500 d\u00f3lares de bono para la compra\u00bb en el remate.<\/p>\n\n\n\n<p>Salto, 26 de agosto de 2024 <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo s\u00e1bado 31 de agosto, a las 16 horas, se realiza en el predio de la Asociaci\u00f3n Agropecuaria de Salto, la 5ta Edici\u00f3n del remate \u00abCriollos para ganar\u00bb, de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":54286,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,23],"tags":[],"class_list":["post-54285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-equinos"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/08\/juanpablogutierrez.jpg?fit=880%2C440&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-e7z","jetpack-related-posts":[{"id":56675,"url":"https:\/\/lahoradelcampo.com.uy\/site\/criollos-para-ganar-con-ventas-totales\/","url_meta":{"origin":54285,"position":0},"title":"\u00abCriollos para ganar\u00bb con ventas totales","author":"La Hora del Campo","date":"1 septiembre, 2025","format":false,"excerpt":"Con agilidad y colocaci\u00f3n total, se realiz\u00f3 el s\u00e1bado en el local de la Asociaci\u00f3n Agropecuaria de Salto, la sexta edici\u00f3n de \"Criollos para Ganar\", subasta a cargo de Indarte y C\u00eda. y Gast\u00f3n Ara\u00fajo. En pista salieron 31 Criollos de pedigr\u00ed -potras y potros de resistencia- de las caba\u00f1as\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/09\/criollosparaganar1.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/09\/criollosparaganar1.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/09\/criollosparaganar1.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2025\/09\/criollosparaganar1.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":54364,"url":"https:\/\/lahoradelcampo.com.uy\/site\/100-de-venta-en-el-remate-criollos-para-ganar-en-salto\/","url_meta":{"origin":54285,"position":1},"title":"100% de venta en el remate \u00abCriollos para ganar\u00bb en Salto","author":"La Hora del Campo","date":"2 septiembre, 2024","format":false,"excerpt":"El remate cumpli\u00f3 con los tres pilares principales de una subasta, se vendi\u00f3 el 100% de la oferta, la demanda pujo por todos los lotes y los valores cumplieron con las expectativas de los vendedores y los compradores, adem\u00e1s la gen\u00e9tica se dispers\u00f3 a varios puntos del pa\u00eds. Las ventas\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/Criollosparaganar.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/Criollosparaganar.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/Criollosparaganar.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/09\/Criollosparaganar.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2149,"url":"https:\/\/lahoradelcampo.com.uy\/site\/hoy-comienzan-las-actividades-de-la-expo-salto\/","url_meta":{"origin":54285,"position":2},"title":"Hoy comienzan las actividades de la Expo Salto","author":"La Hora del Campo","date":"4 octubre, 2017","format":false,"excerpt":"Las actividades de la Expo Salto 2017 han comenzado desde el a\u00f1o pasado, al finalizar la edici\u00f3n 2016, cuando el equipo organizador comienza a delinear lo que ser\u00e1 fiesta de a\u00f1o siguiente, sin embargo para el p\u00fablico en general las actividades comienzan a partir de la jornada de hoy. A\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Expo-Salto-1.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Expo-Salto-1.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Expo-Salto-1.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Expo-Salto-1.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":40927,"url":"https:\/\/lahoradelcampo.com.uy\/site\/criollos-realizan-en-cerro-largo-la-final-nacional-de-paleteadas\/","url_meta":{"origin":54285,"position":3},"title":"Criollos realizan en Cerro Largo la final nacional de Paleteadas","author":"La Hora del Campo","date":"20 abril, 2022","format":false,"excerpt":"Entre el viernes 22 y el domingo 24 de abril se llevar\u00e1 a cabo en la ciudad de Melo, Cerro Largo, la final nacional de paleteadas organizada por la Sociedad de Criadores de Caballos Criollos del Uruguay (Scccu) y la Agremiaci\u00f3n de Criadores de Caballos Criollos de Cerro Largo. Estar\u00e1n\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/08\/criolloswebpaleteadas.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/08\/criolloswebpaleteadas.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/08\/criolloswebpaleteadas.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/08\/criolloswebpaleteadas.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":50008,"url":"https:\/\/lahoradelcampo.com.uy\/site\/24-de-abril-cierran-las-pre-inscripciones-para-la-marcha-de-criollos\/","url_meta":{"origin":54285,"position":4},"title":"24 de abril cierran las pre-inscripciones para la Marcha de Criollos","author":"La Hora del Campo","date":"16 abril, 2023","format":false,"excerpt":"La Sociedad de Criadores de Caballos Criollos del Uruguay (SCCCU) se prepara para celebrar la 52\u00b0 edici\u00f3n de la Marcha Funcional \"Carlos M\u00e1spoli\" y, junto a la Federaci\u00f3n Internacional de Criadores de Caballos Criollos (FICCC), la 8\u00b0 edici\u00f3n de la Marcha FICCC. Esta competici\u00f3n de resistencia y rusticidad se llevar\u00e1\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/08\/Marchacriollos.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/08\/Marchacriollos.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/08\/Marchacriollos.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/08\/Marchacriollos.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":54679,"url":"https:\/\/lahoradelcampo.com.uy\/site\/zambrano-e-indarte-cia-realizan-hoy-el-remate-genetica-efectiva\/","url_meta":{"origin":54285,"position":5},"title":"Zambrano e Indarte &amp; C\u00eda realizan hoy el remate \u201cGen\u00e9tica efectiva\u201d","author":"La Hora del Campo","date":"26 septiembre, 2024","format":false,"excerpt":"Hoy jueves 26 de septiembre, en la estancia \"La Totora\", ubicada en el kil\u00f3metro 303 de la ruta 3, cerca de la ciudad de Young, departamento de R\u00edo Negro, se llevar\u00e1 a cabo el segundo remate anual \"Gen\u00e9tica Efectiva\". Este evento, organizado por las firmas Indarte y C\u00eda. y Zambrano\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/07\/Gonzaloindarte.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/07\/Gonzaloindarte.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/07\/Gonzaloindarte.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/07\/Gonzaloindarte.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/54285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=54285"}],"version-history":[{"count":1,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/54285\/revisions"}],"predecessor-version":[{"id":54287,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/54285\/revisions\/54287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/54286"}],"wp:attachment":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=54285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=54285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=54285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}