{"id":54254,"date":"2024-08-20T07:24:18","date_gmt":"2024-08-20T10:24:18","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=54254"},"modified":"2024-08-20T07:24:19","modified_gmt":"2024-08-20T10:24:19","slug":"se-exportaron-7-000-vaquillonas-angus-a-turquia","status":"publish","type":"post","link":"https:\/\/lahoradelcampo.com.uy\/site\/se-exportaron-7-000-vaquillonas-angus-a-turquia\/","title":{"rendered":"Se exportaron 7.000 vaquillonas Angus a Turqu\u00eda"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/08\/JuanPabloPerezFrontini.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"405\" data-attachment-id=\"54255\" data-permalink=\"https:\/\/lahoradelcampo.com.uy\/site\/se-exportaron-7-000-vaquillonas-angus-a-turquia\/juanpabloperezfrontini\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/08\/JuanPabloPerezFrontini.jpg?fit=880%2C440&amp;ssl=1\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"JuanPabloPerezFrontini\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/08\/JuanPabloPerezFrontini.jpg?fit=810%2C405&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/08\/JuanPabloPerezFrontini.jpg?resize=810%2C405\" alt=\"\" class=\"wp-image-54255\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/08\/JuanPabloPerezFrontini.jpg?w=880&amp;ssl=1 880w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/08\/JuanPabloPerezFrontini.jpg?resize=300%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/08\/JuanPabloPerezFrontini.jpg?resize=768%2C384&amp;ssl=1 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/08\/JuanPabloPerezFrontini.jpg?resize=820%2C410&amp;ssl=1 820w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Uruguay ha enviado 7.000 vaquillonas Aberdeen Angus a Turqu\u00eda, en una operaci\u00f3n que marca un hito en la exportaci\u00f3n de gen\u00e9tica bovina de alta calidad de la raza. El presidente de la Sociedad de Criadores de Angus, Juan Pablo P\u00e9rez Frontini, explic\u00f3 que de estas vaquillonas, aproximadamente 3.600 ser\u00e1n pre\u00f1adas y cerca de 4.000 abiertas, todas ellas certificadas bajo un riguroso programa fenot\u00edpico para garantizar el cumplimiento de los est\u00e1ndares internacionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este proceso de certificaci\u00f3n se realiza durante la cuarentena de los animales, asegurando que cada uno cumpla con los requisitos exigidos y reciba un certificado \u00fanico que asegura su trazabilidad y calidad.<br>P\u00e9rez Frontini destac\u00f3 la importancia de este env\u00edo, no solo por el volumen de animales exportados, sino tambi\u00e9n por el potencial que representa para el mercado uruguayo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El programa de certificaci\u00f3n, llevado a cabo por la Sociedad de Criadores de Angus, evita el uso de marcado a fuego en los animales, una medida especialmente relevante para los que est\u00e1n pre\u00f1ados y en condiciones delicadas para el transporte. Este tipo de operaciones no solo aporta valor al mercado, sino que tambi\u00e9n ofrece una opci\u00f3n diferenciada para los productores que se dedican a la cr\u00eda de animales de alta calidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de la Sociedad de Criadores de Angus tambi\u00e9n subray\u00f3 las expectativas de que esta exportaci\u00f3n se convierta en una corriente comercial estable, fortaleciendo la posici\u00f3n de Uruguay en el mercado internacional de gen\u00e9tica bovina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque no hay planes concretos para nuevos negocios en el corto plazo, P\u00e9rez Frontini se\u00f1al\u00f3 que ya est\u00e1n comenzando a certificar otros animales que probablemente se exporten en los pr\u00f3ximos meses. Turqu\u00eda, seg\u00fan indic\u00f3, sigue siendo un mercado clave para Uruguay, y se espera que la exportaci\u00f3n de vaquillonas Angus contin\u00fae, consolidando la reputaci\u00f3n del pa\u00eds como un proveedor de gen\u00e9tica de calidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Salto, 20 de agosto de 2024<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uruguay ha enviado 7.000 vaquillonas Aberdeen Angus a Turqu\u00eda, en una operaci\u00f3n que marca un hito en la exportaci\u00f3n de gen\u00e9tica bovina de alta calidad de la raza. El presidente [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":54255,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,5],"tags":[],"class_list":["post-54254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-ganaderia"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/08\/JuanPabloPerezFrontini.jpg?fit=880%2C440&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-e74","jetpack-related-posts":[{"id":35555,"url":"https:\/\/lahoradelcampo.com.uy\/site\/la-magdalena-coloco-148-toros-a-us-3-452-de-promedio-en-valentin\/","url_meta":{"origin":54254,"position":0},"title":"\u00abLa Magdalena\u00bb coloc\u00f3 149 toros a US$ 3.452 de promedio en Valent\u00edn","author":"La Hora del Campo","date":"18 octubre, 2021","format":false,"excerpt":"El viernes 15 de octubre fue una tarde de ventas \u00e1giles y buenos negocios en el local de la Asociaci\u00f3n Fomento Rural de Valent\u00edn, en el marco del 19\u00b0 Remate anual de la caba\u00f1a \"La Magdalena\" de Los Tordos S en C. Las ventas estuvieron a cargo de los escritorios\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/10\/zafra-magdalena.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/10\/zafra-magdalena.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/10\/zafra-magdalena.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/10\/zafra-magdalena.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":24520,"url":"https:\/\/lahoradelcampo.com.uy\/site\/continua-la-concrecion-de-buenos-negocios-en-la-zafra-de-reproductores\/","url_meta":{"origin":54254,"position":1},"title":"Contin\u00faa la concreci\u00f3n de buenos negocios en la zafra de reproductores","author":"La Hora del Campo","date":"10 octubre, 2020","format":false,"excerpt":"Actualizamos la informaci\u00f3n con los remates que se realizaron en las \u00faltimas jornadas de ventas. El Hereford de Isla Larga El Hereford de Raquel Arrarte en la propia caba\u00f1a coloc\u00f3 45 toros a US$ 3.073 de promedio, con seis toros colocados fuera de pista. El m\u00e1ximo fue de US$ 4.320\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/10\/Torosarchivo.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/10\/Torosarchivo.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/10\/Torosarchivo.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/10\/Torosarchivo.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":28708,"url":"https:\/\/lahoradelcampo.com.uy\/site\/us-10-008-de-promedio-para-los-vientres-del-gala-angus\/","url_meta":{"origin":54254,"position":2},"title":"US$ 10.008 de promedio para los vientres del Gala Angus","author":"La Hora del Campo","date":"22 marzo, 2021","format":false,"excerpt":"Luego de la venta del Especial Angus de Plaza Rural, la firma Zambrano & C\u00eda comercializ\u00f3 el pasado viernes los vientres especiales que se ofrecen hace 16 a\u00f1os en el tradicional Gala Angus, que este a\u00f1o se realiz\u00f3 de forma virtual. El mayor valor de la noche fue para una\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/03\/Galaangus.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/03\/Galaangus.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/03\/Galaangus.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/03\/Galaangus.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":44375,"url":"https:\/\/lahoradelcampo.com.uy\/site\/fuerte-caida-de-la-exportacion-en-pie-en-el-primer-semestre\/","url_meta":{"origin":54254,"position":3},"title":"Fuerte ca\u00edda de la exportaci\u00f3n en pie en el primer semestre","author":"La Hora del Campo","date":"1 agosto, 2022","format":false,"excerpt":"El cambio de los destinos y las categor\u00edas que se exportaron en pie durante el primer semestre de este a\u00f1o 2022, marcan un fuerte descenso en el volumen de cabezas comercializadas. Seg\u00fan los datos publicados por el Instituto Nacional de Carnes (INAC), en los primeros seis meses del 2022, la\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/01\/Exportacionenpie.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/01\/Exportacionenpie.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/01\/Exportacionenpie.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/01\/Exportacionenpie.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2831,"url":"https:\/\/lahoradelcampo.com.uy\/site\/san-rafael-alcanzo-us-2-894-por-los-angus\/","url_meta":{"origin":54254,"position":4},"title":"San Rafael alcanz\u00f3 U$S 2.894 por los Angus","author":"La Hora del Campo","date":"17 octubre, 2017","format":false,"excerpt":"Caba\u00f1a San Rafael y Vasco Pampeano comercializaron en la jornada de ayer sus reproductores Angus y Polled Hereford, con colocaci\u00f3n parcial de la oferta de toros Hereford de dos a\u00f1os. Las ventas comenzaron con los vientres, coloc\u00e1ndose 5 vacas SA pre\u00f1adas a U$S 936 y 3 vaquillonas SA servidas a\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/San-Rafael.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/San-Rafael.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/San-Rafael.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/San-Rafael.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2681,"url":"https:\/\/lahoradelcampo.com.uy\/site\/la-magdalena-vendio-137-toros-a-un-promedio-de-us-3-228\/","url_meta":{"origin":54254,"position":5},"title":"La Magdalena vendi\u00f3 137 toros a un promedio de U$S 3.228","author":"La Hora del Campo","date":"15 octubre, 2017","format":false,"excerpt":"El viernes por la tarde, la caba\u00f1a \"La Magadalena\" de Los Tordos S. en C., realiz\u00f3 su d\u00e9cimo quinto remate anual en el local Valent\u00edn de Salto, en una tarde gris pero \u00e1gil y r\u00e1pida en la concreci\u00f3n de los negocios en la pista, coloc\u00e1ndose el 100% de la oferta\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/La-Magdalena.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/La-Magdalena.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/La-Magdalena.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/La-Magdalena.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/54254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=54254"}],"version-history":[{"count":1,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/54254\/revisions"}],"predecessor-version":[{"id":54256,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/54254\/revisions\/54256"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/54255"}],"wp:attachment":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=54254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=54254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=54254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}