{"id":51059,"date":"2023-06-05T13:35:01","date_gmt":"2023-06-05T16:35:01","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=51059"},"modified":"2023-06-05T13:35:09","modified_gmt":"2023-06-05T16:35:09","slug":"informe-de-jose-maria-rodriguez-del-5-de-junio-de-2023","status":"publish","type":"post","link":"https:\/\/lahoradelcampo.com.uy\/site\/informe-de-jose-maria-rodriguez-del-5-de-junio-de-2023\/","title":{"rendered":"Informe de Jos\u00e9 Mar\u00eda Rodr\u00edguez del 5 de junio de 2023"},"content":{"rendered":"\n<p>El Informe del tiempo m\u00e1s completo para el norte del pa\u00eds, elaborado por el meteor\u00f3logo Jos\u00e9 Mar\u00eda Rodr\u00edguez para La Hora del Campo. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"405\" data-attachment-id=\"19548\" data-permalink=\"https:\/\/lahoradelcampo.com.uy\/site\/josema-nuevo\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&amp;ssl=1\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Josema nuevo\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=810%2C405&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?resize=810%2C405\" alt=\"\" class=\"wp-image-19548\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?w=880&amp;ssl=1 880w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?resize=300%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?resize=768%2C384&amp;ssl=1 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?resize=820%2C410&amp;ssl=1 820w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/figure>\n\n\n<div\r\n    id=\"h5ap-player-1\"\r\n    data-id=\"h5ap-player-1\"\r\n    data-attributes=\"{&quot;uniqueId&quot;:&quot;player51051&quot;,&quot;clientId&quot;:&quot;&quot;,&quot;align&quot;:&quot;&quot;,&quot;alignment&quot;:&quot;left&quot;,&quot;color&quot;:&quot;#fff&quot;,&quot;textColor&quot;:&quot;#fff&quot;,&quot;primaryColor&quot;:&quot;#195FF5&quot;,&quot;hoverColor&quot;:&quot;#00B3FF&quot;,&quot;controlColor&quot;:&quot;#4a5464&quot;,&quot;bgColor&quot;:&quot;#f2f2f2&quot;,&quot;skin&quot;:&quot;Default&quot;,&quot;repeat&quot;:false,&quot;autoplay&quot;:false,&quot;isSticky&quot;:false,&quot;muted&quot;:false,&quot;loader&quot;:false,&quot;saveState&quot;:false,&quot;disablePause&quot;:false,&quot;seekTime&quot;:10,&quot;startTime&quot;:0,&quot;preload&quot;:&quot;metadata&quot;,&quot;download&quot;:false,&quot;width&quot;:&quot;100%&quot;,&quot;radius&quot;:&quot;5px&quot;,&quot;controls&quot;:{&quot;play&quot;:true},&quot;options&quot;:{&quot;volume&quot;:null},&quot;CSS&quot;:&quot;&quot;,&quot;i18n&quot;:{&quot;restart&quot;:&quot;Restart&quot;,&quot;rewind&quot;:&quot;Rewind {seektime}s&quot;,&quot;play&quot;:&quot;Play&quot;,&quot;pause&quot;:&quot;Pause&quot;,&quot;fastForward:&quot;:&quot;Forward {seektime}s&quot;,&quot;seek&quot;:&quot;Seek&quot;,&quot;seekLabel&quot;:&quot;{currentTime} of {duration}&quot;,&quot;played&quot;:&quot;Played&quot;,&quot;buffered&quot;:&quot;Buffered&quot;,&quot;currentTime:&quot;:&quot;Current time&quot;,&quot;duration&quot;:&quot;Duration&quot;,&quot;volume&quot;:&quot;Volume&quot;,&quot;mute&quot;:&quot;Mute&quot;,&quot;unmute&quot;:&quot;Unmute&quot;,&quot;enableCaptions&quot;:&quot;Enable captions&quot;,&quot;disableCaptions&quot;:&quot;Disable captions&quot;,&quot;download&quot;:&quot;Download&quot;,&quot;enterFullscreen&quot;:&quot;Enter fullscreen&quot;,&quot;exitFullscreen&quot;:&quot;Exit fullscreen&quot;,&quot;frameTitle&quot;:&quot;Player for {title}&quot;,&quot;captions&quot;:&quot;Captions&quot;,&quot;settings&quot;:&quot;Settings&quot;,&quot;pip&quot;:&quot;PIP&quot;,&quot;menuBack&quot;:&quot;Go back to previous menu&quot;,&quot;speed&quot;:&quot;Speed&quot;,&quot;normal&quot;:&quot;Normal&quot;,&quot;quality&quot;:&quot;Quality&quot;,&quot;loop&quot;:&quot;Loop&quot;,&quot;start&quot;:&quot;Start&quot;,&quot;end&quot;:&quot;End&quot;,&quot;all&quot;:&quot;All&quot;,&quot;reset&quot;:&quot;Reset&quot;,&quot;disabled&quot;:&quot;Disabled&quot;,&quot;enabled&quot;:&quot;Enabled&quot;,&quot;advertisement&quot;:&quot;Ad&quot;,&quot;qualityBadge&quot;:{&quot;2160&quot;:&quot;4K&quot;,&quot;1440&quot;:&quot;HD&quot;,&quot;1080&quot;:&quot;HD&quot;,&quot;720&quot;:&quot;HD&quot;,&quot;576&quot;:&quot;SD&quot;,&quot;480&quot;:&quot;SD&quot;}},&quot;source&quot;:&quot;&quot;,&quot;poster&quot;:&quot;&quot;,&quot;title&quot;:&quot;audio title&quot;,&quot;artist&quot;:&quot;&quot;,&quot;speed&quot;:{&quot;selected&quot;:1,&quot;speed&quot;:[&quot;0.5&quot;,&quot; 0.75&quot;,&quot; 1&quot;,&quot; 1.25&quot;,&quot; 1.5&quot;,&quot; 1.75&quot;,&quot; 2&quot;,&quot; 4&quot;,&quot; 8&quot;]},&quot;multiple_audio&quot;:false,&quot;defaultValue&quot;:{&quot;Default&quot;:{&quot;primaryColor&quot;:&quot;#4A5464&quot;,&quot;controlColor&quot;:&quot;#4A5464&quot;,&quot;bgColor&quot;:&quot;#F5F5F5&quot;},&quot;Fusion&quot;:{&quot;primaryColor&quot;:&quot;#fff&quot;,&quot;bgColor&quot;:&quot;#161616&quot;,&quot;controlColor&quot;:&quot;#fff&quot;},&quot;Stamp&quot;:{&quot;controlColor&quot;:&quot;#fff&quot;,&quot;bgColor&quot;:&quot;#161616&quot;},&quot;Wave&quot;:{&quot;primaryColor&quot;:&quot;#fff&quot;,&quot;controlColor&quot;:&quot;#fff&quot;,&quot;bgColor&quot;:&quot;#161616&quot;,&quot;textColor&quot;:&quot;#fff&quot;},&quot;Card-1&quot;:{&quot;primaryColor&quot;:&quot;#fff&quot;,&quot;controlColor&quot;:&quot;#161616&quot;,&quot;bgColor&quot;:&quot;#161616&quot;,&quot;textColor&quot;:&quot;#fff&quot;},&quot;Card-2&quot;:{&quot;primaryColor&quot;:&quot;#00FBF3&quot;,&quot;controlColor&quot;:&quot;#fff&quot;,&quot;bgColor&quot;:&quot;#161616&quot;,&quot;textColor&quot;:&quot;#fff&quot;},&quot;Simple-1&quot;:{&quot;primaryColor&quot;:&quot;#00dcff&quot;,&quot;controlColor&quot;:&quot;#fff&quot;,&quot;bgColor&quot;:&quot;#161616&quot;,&quot;textColor&quot;:&quot;#00dcff&quot;},&quot;Simple-2&quot;:{&quot;primaryColor&quot;:&quot;#06F7FF00&quot;,&quot;controlColor&quot;:&quot;#fff&quot;,&quot;bgColor&quot;:&quot;#161616&quot;},&quot;Player9&quot;:{&quot;primaryColor&quot;:&quot;#195FF6&quot;,&quot;controlColor&quot;:&quot;#fff&quot;,&quot;bgColor&quot;:&quot;#161616&quot;,&quot;textColor&quot;:&quot;#EDEFF2&quot;},&quot;Player10&quot;:{&quot;primaryColor&quot;:&quot;#195FF6&quot;,&quot;controlColor&quot;:&quot;#fff&quot;,&quot;bgColor&quot;:&quot;#161616&quot;,&quot;textColor&quot;:&quot;#EDEFF2&quot;},&quot;Player11&quot;:{&quot;primaryColor&quot;:&quot;#195FF6&quot;,&quot;controlColor&quot;:&quot;#fff&quot;,&quot;bgColor&quot;:&quot;#161616&quot;,&quot;textColor&quot;:&quot;#fff&quot;}}}\"\r\n    class=\"wp-block-h5ap-tailwind wp-block-h5ap-audioplayer\">\r\n    <\/div>\n\n\n\n<p>Salto, 5 de junio de 2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Informe del tiempo m\u00e1s completo para el norte del pa\u00eds, elaborado por el meteor\u00f3logo Jos\u00e9 Mar\u00eda Rodr\u00edguez para La Hora del Campo. Salto, 5 de junio de 2023<\/p>\n","protected":false},"author":5,"featured_media":19548,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,1],"tags":[],"class_list":["post-51059","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-varias"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-dhx","jetpack-related-posts":[{"id":42571,"url":"https:\/\/lahoradelcampo.com.uy\/site\/informe-de-jose-maria-rodriguez-para-el-8-de-junio-de-2022\/","url_meta":{"origin":51059,"position":0},"title":"Informe de Jos\u00e9 Mar\u00eda Rodr\u00edguez para el 8 de junio de 2022","author":"La Hora del Campo","date":"8 junio, 2022","format":false,"excerpt":"El informe del tiempo m\u00e1s completo para el norte del pa\u00eds. Salto, 8 de junio de 2022","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":42721,"url":"https:\/\/lahoradelcampo.com.uy\/site\/informe-de-jose-maria-rodriguez-para-el-13-de-junio-de-2022\/","url_meta":{"origin":51059,"position":1},"title":"Informe de Jos\u00e9 Mar\u00eda Rodr\u00edguez para el 13 de junio de 2022","author":"La Hora del Campo","date":"13 junio, 2022","format":false,"excerpt":"El Informe del tiempo m\u00e1s completo para el norte del pa\u00eds. Salto, 13 de junio de 2022","rel":"","context":"En \u00abVarias\u00bb","block_context":{"text":"Varias","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/varias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":42947,"url":"https:\/\/lahoradelcampo.com.uy\/site\/informe-de-jose-maria-rodriguez-para-el-17-de-junio-de-2022\/","url_meta":{"origin":51059,"position":2},"title":"Informe de Jos\u00e9 Mar\u00eda Rodr\u00edguez para el 17 de junio de 2022","author":"La Hora del Campo","date":"17 junio, 2022","format":false,"excerpt":"El informe del tiempo m\u00e1s completo para el norte del pa\u00eds. Salto, 17 de junio de 2022","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":43175,"url":"https:\/\/lahoradelcampo.com.uy\/site\/informe-de-jose-maria-rodriguez-para-el-24-de-junio-de-2022\/","url_meta":{"origin":51059,"position":3},"title":"Informe de Jos\u00e9 Mar\u00eda Rodr\u00edguez para el 24 de junio de 2022","author":"La Hora del Campo","date":"24 junio, 2022","format":false,"excerpt":"El informe del tiempo m\u00e1s completo para el norte del pa\u00eds. Salto, 24 de junio de 2022","rel":"","context":"En \u00abVarias\u00bb","block_context":{"text":"Varias","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/varias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":42345,"url":"https:\/\/lahoradelcampo.com.uy\/site\/informe-de-jose-maria-rodriguez-del-1-de-junio-de-2022\/","url_meta":{"origin":51059,"position":4},"title":"Informe de Jos\u00e9 Mar\u00eda Rodr\u00edguez del 1 de junio de 2022","author":"La Hora del Campo","date":"1 junio, 2022","format":false,"excerpt":"El informe del tiempo m\u00e1s completo para el norte del pa\u00b4\u00eds. Salto, 1 de junio de 2022","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":42429,"url":"https:\/\/lahoradelcampo.com.uy\/site\/informe-de-jose-maria-rodriguez-del-3-de-junio-de-2022\/","url_meta":{"origin":51059,"position":5},"title":"Informe de Jos\u00e9 Mar\u00eda Rodr\u00edguez del 3 de junio de 2022","author":"La Hora del Campo","date":"3 junio, 2022","format":false,"excerpt":"El Informe del tiempo m\u00e1s completo para el norte del pa\u00eds. Salto, 3 de junio de 2022","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/51059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=51059"}],"version-history":[{"count":1,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/51059\/revisions"}],"predecessor-version":[{"id":51061,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/51059\/revisions\/51061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/19548"}],"wp:attachment":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=51059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=51059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=51059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}