{"id":33891,"date":"2021-09-08T07:18:21","date_gmt":"2021-09-08T10:18:21","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=33891"},"modified":"2021-09-08T07:18:26","modified_gmt":"2021-09-08T10:18:26","slug":"uruguay-comenzara-a-negociar-un-tlc-con-china","status":"publish","type":"post","link":"https:\/\/lahoradelcampo.com.uy\/site\/uruguay-comenzara-a-negociar-un-tlc-con-china\/","title":{"rendered":"Uruguay comenzar\u00e1 a negociar un TLC con China"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"405\" data-attachment-id=\"33893\" data-permalink=\"https:\/\/lahoradelcampo.com.uy\/site\/uruguay-comenzara-a-negociar-un-tlc-con-china\/lacallepou\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/09\/lacallepou.jpg?fit=880%2C440&amp;ssl=1\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"lacallepou\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/09\/lacallepou.jpg?fit=810%2C405&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/09\/lacallepou.jpg?resize=810%2C405\" alt=\"\" class=\"wp-image-33893\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/09\/lacallepou.jpg?w=880&amp;ssl=1 880w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/09\/lacallepou.jpg?resize=300%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/09\/lacallepou.jpg?resize=768%2C384&amp;ssl=1 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/09\/lacallepou.jpg?resize=820%2C410&amp;ssl=1 820w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<p>Nadie desconoce la incidencia de China en el comercio mundial y menos a\u00fan en la econom\u00eda uruguaya, debido a su demanda principalmente por prote\u00edna animal, pero tambi\u00e9n de otros productos. <\/p>\n\n\n\n<p>Al mismo tiempo la relaci\u00f3n interna dentro del bloque del Mercosur, se ha friccionado en los \u00faltimos meses debido a la intenci\u00f3n de Uruguay de negociar con sus principales mercados para bajar los aranceles que paga para exportar sus principales productos.  <\/p>\n\n\n\n<p>En este sentido se inform\u00f3 por Telenoche 4, en la jornada de ayer, que el Presidente de la Rep\u00fablica, Dr. Luis Lacalle Pou, se reuni\u00f3 a los l\u00edderes de todos los partidos pol\u00edticos y les comunic\u00f3 la decisi\u00f3n de comenzar a negociar un Tratado de Libre Comercio (TLC) con su principal socio comercial y por fuera del bloque regional. <br><\/p>\n\n\n\n<p>China es nuestro principal socio comercial  y con el cual Uruguay   mantiene una balanza comercial favorable, en torno a los 200 millones de d\u00f3lares anuales. De acuerdo a Uruguay XXI, el gigante asi\u00e1tico tambi\u00e9n lider\u00f3 el monto por pago de aranceles el a\u00f1o pasado, en una cifra que ascendi\u00f3 a los 184,4 millones de d\u00f3lares.<br><\/p>\n\n\n\n<p>Esa cifra reporta el 54% del total abonado por Uruguay por concepto de aranceles durante ese a\u00f1o y en el caso de China actualmente el 79% de los productos uruguayos enfrentan restricciones arancelarias de alg\u00fan tipo.<br><\/p>\n\n\n\n<p>China es, adem\u00e1s, el principal mercado de los tres principales bienes de exportaci\u00f3n uruguayos: la carne bovina, la celulosa y la soja. Estos tres productos representan el 82% del total exportado.<br><\/p>\n\n\n\n<p>A nivel arancelario, por ejemplo, la carne bovina para un 12% de arancel mientras que los l\u00e1cteos oscilan en niveles que van del 12% al 6% dependiendo del producto. Otros productos tienen incluso aranceles m\u00e1s altos como los vinos (14%).<\/p>\n\n\n\n<p>Salto, 8 de setiembre de 2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nadie desconoce la incidencia de China en el comercio mundial y menos a\u00fan en la econom\u00eda uruguaya, debido a su demanda principalmente por prote\u00edna animal, pero tambi\u00e9n de otros productos. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":33893,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,5],"tags":[],"class_list":["post-33891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-ganaderia"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/09\/lacallepou.jpg?fit=880%2C440&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-8OD","jetpack-related-posts":[{"id":16300,"url":"https:\/\/lahoradelcampo.com.uy\/site\/china-mantiene-su-posicion-de-firmar-un-tlc-con-uruguay\/","url_meta":{"origin":33891,"position":0},"title":"China mantiene su posici\u00f3n de firmar un TLC con Uruguay","author":"La Hora del Campo","date":"7 diciembre, 2019","format":false,"excerpt":"Luego de la \u00faltima visita del Ministro de Ganader\u00eda, Agricultura y Pesca, Enzo Benech, a China, el embajador chino en Uruguay, Wang Gang, confirm\u00f3 que su pa\u00eds mantiene el inter\u00e9s de negociar un tratado de libre comercio (TLC). El diplom\u00e1tico respondi\u00f3 as\u00ed a la consulta realizada por los empresarios uruguayos\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/12\/China-embajador.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/12\/China-embajador.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/12\/China-embajador.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/12\/China-embajador.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":53203,"url":"https:\/\/lahoradelcampo.com.uy\/site\/uruguay-y-china-fortalecen-sus-lazos-comerciales-y-aceleran-el-proceso-de-un-tlc\/","url_meta":{"origin":33891,"position":1},"title":"Uruguay y China fortalecen sus lazos comerciales y aceleran el proceso de un TLC","author":"La Hora del Campo","date":"24 noviembre, 2023","format":false,"excerpt":"En el marco de la visita oficial del presidente de Uruguay, Luis Lacalle Pou, a Beijing, se ha alcanzado un hito significativo en las relaciones bilaterales entre Uruguay y China. El presidente Lacalle Pou y su hom\u00f3logo chino, Xi Jinping, acordaron acelerar la construcci\u00f3n de una Asociaci\u00f3n de Libre Comercio\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/11\/Uruguay-China.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/11\/Uruguay-China.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/11\/Uruguay-China.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/11\/Uruguay-China.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":34377,"url":"https:\/\/lahoradelcampo.com.uy\/site\/tlc-con-china-puede-ser-el-cambio-mas-importante-de-los-ultimos-70-anos\/","url_meta":{"origin":33891,"position":2},"title":"TLC con China, \u00abpuede ser el cambio m\u00e1s importante de los \u00faltimos 70 a\u00f1os\u00bb","author":"La Hora del Campo","date":"20 septiembre, 2021","format":false,"excerpt":"El Ministro de Ganader\u00eda, Agricultura y Pesca, Ing. Agr. Fernando Mattos, record\u00f3 al inicio de su discurso que a pesar de la pandemia, el sector agropecuario ha crecido fuertemente en sus exportaciones, tanto del sector c\u00e1rnico como de la lecher\u00eda, entre otros rubros de la producci\u00f3n agropecuaria nacional. En materia\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/09\/Prado-discursomattos.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/09\/Prado-discursomattos.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/09\/Prado-discursomattos.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/09\/Prado-discursomattos.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":36529,"url":"https:\/\/lahoradelcampo.com.uy\/site\/importadores-de-carne-de-eeuu-apoyan-un-tlc-con-uruguay\/","url_meta":{"origin":33891,"position":3},"title":"Importadores de carne de EEUU apoyan un TLC con Uruguay","author":"La Hora del Campo","date":"15 noviembre, 2021","format":false,"excerpt":"El Consejo de Importadores de Carne de Estados Unidos (MICA, por su sigla en ingl\u00e9s) anunci\u00f3 que los miembros de su organizaci\u00f3n est\u00e1n de acuerdo en que se concrete un Tratado de Libre Comercio entre Estados Unidos y Uruguay, a efectos de mejorar el acceso de carne uruguaya a su\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/11\/INAC-MICA1.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/11\/INAC-MICA1.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/11\/INAC-MICA1.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/11\/INAC-MICA1.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":34021,"url":"https:\/\/lahoradelcampo.com.uy\/site\/la-carne-bovina-uno-de-los-grandes-ganadores-en-un-acuerdo-uruguay-china\/","url_meta":{"origin":33891,"position":4},"title":"La carne bovina, uno de los grandes ganadores en un acuerdo Uruguay-China","author":"La Hora del Campo","date":"13 septiembre, 2021","format":false,"excerpt":"Hace pocos d\u00edas el Presidente de la Rep\u00fablica, Dr. Luis Lacalle Pou, anunci\u00f3 el inicio de un camino hacia un posible Tratado de Libre Comercio (TLC) con China, actualmente su principal socio comercial y donde nuestro pa\u00eds deja en las aduanas del gigante asi\u00e1tico un importe muy alto en d\u00f3lares\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/09\/CED-CHINA.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/09\/CED-CHINA.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/09\/CED-CHINA.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/09\/CED-CHINA.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":43825,"url":"https:\/\/lahoradelcampo.com.uy\/site\/tlc-el-sector-carnico-dejaria-de-pagar-us-150-millones-en-aranceles\/","url_meta":{"origin":33891,"position":5},"title":"TLC: el sector c\u00e1rnico dejar\u00eda de pagar US$ 150 millones en aranceles","author":"La Hora del Campo","date":"15 julio, 2022","format":false,"excerpt":"La noticia brindada por el Presidente de la Rep\u00fablica, Dr. Luis Lacalle Pou y reafirmada por las autoridades chinas, sobre el cierre del an\u00e1lisis de factibilidad de un posible Tratado de Libre Comercio (TLC) podr\u00eda brindarle a nuestro pa\u00eds la oportunidad de reducir en 150 millones de d\u00f3lares sus pagos\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/07\/INAC-Carneuruguay.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/07\/INAC-Carneuruguay.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/07\/INAC-Carneuruguay.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/07\/INAC-Carneuruguay.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/33891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=33891"}],"version-history":[{"count":1,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/33891\/revisions"}],"predecessor-version":[{"id":33895,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/33891\/revisions\/33895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/33893"}],"wp:attachment":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=33891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=33891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=33891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}