{"id":3145,"date":"2017-10-25T16:17:53","date_gmt":"2017-10-25T19:17:53","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=3145"},"modified":"2017-10-25T16:17:53","modified_gmt":"2017-10-25T19:17:53","slug":"la-formacion-del-precio-tiene-que-empezar-con-el-costo-en-el-campo","status":"publish","type":"post","link":"https:\/\/lahoradelcampo.com.uy\/site\/la-formacion-del-precio-tiene-que-empezar-con-el-costo-en-el-campo\/","title":{"rendered":"La formaci\u00f3n del precio tiene que empezar con el costo en el campo"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Macron.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3147\" data-permalink=\"https:\/\/lahoradelcampo.com.uy\/site\/la-formacion-del-precio-tiene-que-empezar-con-el-costo-en-el-campo\/macron\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Macron.jpg?fit=880%2C440&amp;ssl=1\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Vicente-Manuel-Tort&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;Presidencia de la Republica - Sec.Com.Inst.&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Macron\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Macron.jpg?fit=810%2C405&amp;ssl=1\" class=\"aligncenter wp-image-3147 size-full\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Macron.jpg?resize=810%2C405\" alt=\"\" width=\"810\" height=\"405\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Macron.jpg?w=880&amp;ssl=1 880w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Macron.jpg?resize=300%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Macron.jpg?resize=768%2C384&amp;ssl=1 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Macron.jpg?resize=820%2C410&amp;ssl=1 820w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/a><\/p>\n<p>El presidente de la Rep\u00fablica francesa, Emmanuel Macron, ha anunciado una ley para reequilibrar los contratos entre los agricultores, fabricantes y distribuidores y para remunerar mejor a los agricultores. Para ello, quiere que la\u00a0nueva ley revierta el sistema de formaci\u00f3n de precios de los alimentos y que comience a partir de los costos de producci\u00f3n.<\/p>\n<p>Proponen que los precios pagados a los agricultores se fijen a partir de su costo. A partir de este precio se sumar\u00edan los m\u00e1rgenes de los procesadores y distribuidores dando el precio al consumo. Actualmente, el sistema funciona exactamente al rev\u00e9s.<\/p>\n<p>La Federaci\u00f3n francesa de empresas y empresarios considera que la ley va en buena direcci\u00f3n pero que solo\u00a0podr\u00eda funcionar si los procesadores tuvieran la seguridad de que iban a poder aplicar los m\u00e1rgenes a la distribuci\u00f3n. Adem\u00e1s, con el fin de poder tener en cuenta las variaciones de los costos de producci\u00f3n de los agricultores, la Federaci\u00f3n cree que deber\u00eda haber un\u00a0\u00edndice oficial de dichos costos.<\/p>\n<p>La nueva ley de Macron tambi\u00e9n quiere que los productores tengan un mayor poder de negociaci\u00f3n, por lo que se prev\u00e9 el apoyo a la\u00a0constituci\u00f3n de fuertes organizaciones de productores. Para ello\u00a0el Estado tendr\u00e1 que clarificar el derecho de competencia.<\/p>\n<p>Fuente: Agrodigital<br \/>\nFoto: CNN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Rep\u00fablica francesa, Emmanuel Macron, ha anunciado una ley para reequilibrar los contratos entre los agricultores, fabricantes y distribuidores y para remunerar mejor a los agricultores. Para [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":3147,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[859,865,863,861,441],"class_list":["post-3145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","tag-alimentos","tag-campo","tag-francia","tag-macron","tag-precio"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Macron.jpg?fit=880%2C440&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-OJ","jetpack-related-posts":[{"id":6741,"url":"https:\/\/lahoradelcampo.com.uy\/site\/precio-local-de-trigo-alcanzo-su-maximo-en-tres-anos\/","url_meta":{"origin":3145,"position":0},"title":"Precio local de trigo alcanz\u00f3  su m\u00e1ximo en tres a\u00f1os","author":"La Hora del Campo","date":"1 mayo, 2018","format":false,"excerpt":"El precio local de trigo subi\u00f3 por cuarta semana consecutiva. La referencia de la C\u00e1mara Mercantil para trigo disponible puesto en molino fue US$ 220 por tonelada, cinco centavos m\u00e1s que la semana pasada. Fue el mejor valor desde la semana del 3 de marzo de 2015, cuando se comercializ\u00f3\u2026","rel":"","context":"En \u00abAgricultura\u00bb","block_context":{"text":"Agricultura","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/agricultura\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Trigosiembra.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Trigosiembra.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Trigosiembra.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Trigosiembra.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":5979,"url":"https:\/\/lahoradelcampo.com.uy\/site\/poder-ejecutivo-promulgo-las-leyes-del-fondo-lechero-y-la-devolucion-del-iva-al-gasoil\/","url_meta":{"origin":3145,"position":1},"title":"Poder Ejecutivo promulg\u00f3 las leyes del fondo lechero y la devoluci\u00f3n del iva al gasoil","author":"La Hora del Campo","date":"21 febrero, 2018","format":false,"excerpt":"El Poder Ejecutivo promulg\u00f3 el 20 de febrero la Ley de creaci\u00f3n del Fondo de Garant\u00eda para Deudas de los Productores Lecheros, as\u00ed como tambi\u00e9n la que establece la devoluci\u00f3n del Iva en adquisisiones de gasoil de productores lecheros, arroceros y fruticultores, donde se incluyen adem\u00e1s a los floricultores pero\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/lecheria.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/lecheria.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/lecheria.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/lecheria.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":41891,"url":"https:\/\/lahoradelcampo.com.uy\/site\/bajo-el-precio-y-aumento-el-consumo-de-asado-de-10-a-13-costillas-segun-inac\/","url_meta":{"origin":3145,"position":2},"title":"Bajo el precio y aumento el consumo de asado de 10 a 13 costillas seg\u00fan INAC","author":"La Hora del Campo","date":"17 mayo, 2022","format":false,"excerpt":"La aplicaci\u00f3n de la exoneraci\u00f3n del IVA (Ley 20.024, fecha 23\/03\/2022) del corte asado 10 o 13 costillas congelado o enfriado, gener\u00f3 a nivel minorista un doble efecto: Aumento en los vol\u00famenes: En las 5 semanas posteriores a la vigencia de la ley, se comercializaron al abasto 1.297 toneladas de\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/05\/INAC-asado.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/05\/INAC-asado.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/05\/INAC-asado.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/05\/INAC-asado.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":3013,"url":"https:\/\/lahoradelcampo.com.uy\/site\/mgap-procura-crear-fondo-de-garantia-para-lecheros\/","url_meta":{"origin":3145,"position":3},"title":"MGAP procura crear fondo de garant\u00eda para lecheros","author":"La Hora del Campo","date":"20 octubre, 2017","format":false,"excerpt":"El ministro Tabar\u00e9 Aguerre inform\u00f3 que el Poder Ejecutivo enviar\u00e1 al Parlamento un proyecto de ley para crear un fondo de garant\u00eda que atienda el endeudamiento de los productores lecheros. Para su financiamiento se aumentar\u00e1 el precio de la leche en dos pesos por litro. Por otra parte, el ministro\u2026","rel":"","context":"En \u00abLecher\u00eda\u00bb","block_context":{"text":"Lecher\u00eda","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/lecheria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Lecheria-1.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Lecheria-1.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Lecheria-1.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Lecheria-1.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":40171,"url":"https:\/\/lahoradelcampo.com.uy\/site\/la-asociacion-de-productores-avicolas-congela-el-precio-de-los-huevos\/","url_meta":{"origin":3145,"position":4},"title":"Productores Av\u00edcolas congelan el precio de los huevos","author":"La Hora del Campo","date":"23 marzo, 2022","format":false,"excerpt":"El compromiso es de los productores, pero no de quienes lo venden al p\u00fablico, por lo cual es importante que el consumidor se informe para no hacer un sobrepago. Este lunes 21 de marzo, la Asociaci\u00f3n de Productores Av\u00edcolas de Uruguay acord\u00f3 no subir el precio de los huevos por\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/03\/UAM-Huevos.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/03\/UAM-Huevos.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/03\/UAM-Huevos.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/03\/UAM-Huevos.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":11613,"url":"https:\/\/lahoradelcampo.com.uy\/site\/vazquez-respondio-por-escrito-a-los-pedidos-de-los-productores-arroceros\/","url_meta":{"origin":3145,"position":5},"title":"V\u00e1zquez respondi\u00f3 por escrito a los pedidos de los productores arroceros","author":"La Hora del Campo","date":"7 junio, 2019","format":false,"excerpt":"La carta firmada por el presidente Tabar\u00e9 V\u00e1zquez informa que el Gobierno decidi\u00f3 que el descuento del 15 % en la tarifa de energ\u00eda el\u00e9ctrica para la industria se prorrogue hasta fin de a\u00f1o. Record\u00f3 que los productores que invirtieron en sistemas de riego cuentan con un descuento de igual\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/06\/arroceros-3.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/06\/arroceros-3.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/06\/arroceros-3.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/06\/arroceros-3.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/3145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=3145"}],"version-history":[{"count":1,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/3145\/revisions"}],"predecessor-version":[{"id":3149,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/3145\/revisions\/3149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/3147"}],"wp:attachment":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=3145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=3145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=3145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}