{"id":31400,"date":"2021-06-21T19:00:03","date_gmt":"2021-06-21T22:00:03","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=31400"},"modified":"2021-06-23T10:07:12","modified_gmt":"2021-06-23T13:07:12","slug":"informe-de-jose-maria-rodriguez-del-21-de-junio-de-2021","status":"publish","type":"post","link":"https:\/\/lahoradelcampo.com.uy\/site\/informe-de-jose-maria-rodriguez-del-21-de-junio-de-2021\/","title":{"rendered":"Informe de Jos\u00e9 Mar\u00eda Rodr\u00edguez del 21 de junio de 2021"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"405\" data-attachment-id=\"19548\" data-permalink=\"https:\/\/lahoradelcampo.com.uy\/site\/josema-nuevo\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&amp;ssl=1\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Josema nuevo\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=810%2C405&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?resize=810%2C405\" alt=\"\" class=\"wp-image-19548\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?w=880&amp;ssl=1 880w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?resize=300%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?resize=768%2C384&amp;ssl=1 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?resize=820%2C410&amp;ssl=1 820w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n<div\r\n    id=\"h5ap-player-1\"\r\n    data-id=\"h5ap-player-1\"\r\n    data-attributes=\"{&quot;uniqueId&quot;:&quot;player31392&quot;,&quot;clientId&quot;:&quot;&quot;,&quot;align&quot;:&quot;&quot;,&quot;alignment&quot;:&quot;left&quot;,&quot;color&quot;:&quot;#fff&quot;,&quot;textColor&quot;:&quot;#fff&quot;,&quot;primaryColor&quot;:&quot;#195FF5&quot;,&quot;hoverColor&quot;:&quot;#00B3FF&quot;,&quot;controlColor&quot;:&quot;#4a5464&quot;,&quot;bgColor&quot;:&quot;#f2f2f2&quot;,&quot;skin&quot;:&quot;Default&quot;,&quot;repeat&quot;:false,&quot;autoplay&quot;:false,&quot;isSticky&quot;:false,&quot;muted&quot;:false,&quot;loader&quot;:false,&quot;saveState&quot;:false,&quot;disablePause&quot;:false,&quot;seekTime&quot;:10,&quot;startTime&quot;:0,&quot;preload&quot;:&quot;metadata&quot;,&quot;download&quot;:false,&quot;width&quot;:&quot;100%&quot;,&quot;radius&quot;:&quot;5px&quot;,&quot;controls&quot;:{&quot;play&quot;:true},&quot;options&quot;:{&quot;volume&quot;:null},&quot;CSS&quot;:&quot;&quot;,&quot;i18n&quot;:{&quot;restart&quot;:&quot;Restart&quot;,&quot;rewind&quot;:&quot;Rewind {seektime}s&quot;,&quot;play&quot;:&quot;Play&quot;,&quot;pause&quot;:&quot;Pause&quot;,&quot;fastForward:&quot;:&quot;Forward {seektime}s&quot;,&quot;seek&quot;:&quot;Seek&quot;,&quot;seekLabel&quot;:&quot;{currentTime} of {duration}&quot;,&quot;played&quot;:&quot;Played&quot;,&quot;buffered&quot;:&quot;Buffered&quot;,&quot;currentTime:&quot;:&quot;Current time&quot;,&quot;duration&quot;:&quot;Duration&quot;,&quot;volume&quot;:&quot;Volume&quot;,&quot;mute&quot;:&quot;Mute&quot;,&quot;unmute&quot;:&quot;Unmute&quot;,&quot;enableCaptions&quot;:&quot;Enable captions&quot;,&quot;disableCaptions&quot;:&quot;Disable captions&quot;,&quot;download&quot;:&quot;Download&quot;,&quot;enterFullscreen&quot;:&quot;Enter fullscreen&quot;,&quot;exitFullscreen&quot;:&quot;Exit fullscreen&quot;,&quot;frameTitle&quot;:&quot;Player for {title}&quot;,&quot;captions&quot;:&quot;Captions&quot;,&quot;settings&quot;:&quot;Settings&quot;,&quot;pip&quot;:&quot;PIP&quot;,&quot;menuBack&quot;:&quot;Go back to previous menu&quot;,&quot;speed&quot;:&quot;Speed&quot;,&quot;normal&quot;:&quot;Normal&quot;,&quot;quality&quot;:&quot;Quality&quot;,&quot;loop&quot;:&quot;Loop&quot;,&quot;start&quot;:&quot;Start&quot;,&quot;end&quot;:&quot;End&quot;,&quot;all&quot;:&quot;All&quot;,&quot;reset&quot;:&quot;Reset&quot;,&quot;disabled&quot;:&quot;Disabled&quot;,&quot;enabled&quot;:&quot;Enabled&quot;,&quot;advertisement&quot;:&quot;Ad&quot;,&quot;qualityBadge&quot;:{&quot;2160&quot;:&quot;4K&quot;,&quot;1440&quot;:&quot;HD&quot;,&quot;1080&quot;:&quot;HD&quot;,&quot;720&quot;:&quot;HD&quot;,&quot;576&quot;:&quot;SD&quot;,&quot;480&quot;:&quot;SD&quot;}},&quot;source&quot;:&quot;&quot;,&quot;poster&quot;:&quot;&quot;,&quot;title&quot;:&quot;audio title&quot;,&quot;artist&quot;:&quot;&quot;,&quot;speed&quot;:{&quot;selected&quot;:1,&quot;speed&quot;:[&quot;0.5&quot;,&quot; 0.75&quot;,&quot; 1&quot;,&quot; 1.25&quot;,&quot; 1.5&quot;,&quot; 1.75&quot;,&quot; 2&quot;,&quot; 4&quot;,&quot; 8&quot;]},&quot;multiple_audio&quot;:false,&quot;defaultValue&quot;:{&quot;Default&quot;:{&quot;primaryColor&quot;:&quot;#4A5464&quot;,&quot;controlColor&quot;:&quot;#4A5464&quot;,&quot;bgColor&quot;:&quot;#F5F5F5&quot;},&quot;Fusion&quot;:{&quot;primaryColor&quot;:&quot;#fff&quot;,&quot;bgColor&quot;:&quot;#161616&quot;,&quot;controlColor&quot;:&quot;#fff&quot;},&quot;Stamp&quot;:{&quot;controlColor&quot;:&quot;#fff&quot;,&quot;bgColor&quot;:&quot;#161616&quot;},&quot;Wave&quot;:{&quot;primaryColor&quot;:&quot;#fff&quot;,&quot;controlColor&quot;:&quot;#fff&quot;,&quot;bgColor&quot;:&quot;#161616&quot;,&quot;textColor&quot;:&quot;#fff&quot;},&quot;Card-1&quot;:{&quot;primaryColor&quot;:&quot;#fff&quot;,&quot;controlColor&quot;:&quot;#161616&quot;,&quot;bgColor&quot;:&quot;#161616&quot;,&quot;textColor&quot;:&quot;#fff&quot;},&quot;Card-2&quot;:{&quot;primaryColor&quot;:&quot;#00FBF3&quot;,&quot;controlColor&quot;:&quot;#fff&quot;,&quot;bgColor&quot;:&quot;#161616&quot;,&quot;textColor&quot;:&quot;#fff&quot;},&quot;Simple-1&quot;:{&quot;primaryColor&quot;:&quot;#00dcff&quot;,&quot;controlColor&quot;:&quot;#fff&quot;,&quot;bgColor&quot;:&quot;#161616&quot;,&quot;textColor&quot;:&quot;#00dcff&quot;},&quot;Simple-2&quot;:{&quot;primaryColor&quot;:&quot;#06F7FF00&quot;,&quot;controlColor&quot;:&quot;#fff&quot;,&quot;bgColor&quot;:&quot;#161616&quot;},&quot;Player9&quot;:{&quot;primaryColor&quot;:&quot;#195FF6&quot;,&quot;controlColor&quot;:&quot;#fff&quot;,&quot;bgColor&quot;:&quot;#161616&quot;,&quot;textColor&quot;:&quot;#EDEFF2&quot;},&quot;Player10&quot;:{&quot;primaryColor&quot;:&quot;#195FF6&quot;,&quot;controlColor&quot;:&quot;#fff&quot;,&quot;bgColor&quot;:&quot;#161616&quot;,&quot;textColor&quot;:&quot;#EDEFF2&quot;},&quot;Player11&quot;:{&quot;primaryColor&quot;:&quot;#195FF6&quot;,&quot;controlColor&quot;:&quot;#fff&quot;,&quot;bgColor&quot;:&quot;#161616&quot;,&quot;textColor&quot;:&quot;#fff&quot;}}}\"\r\n    class=\"wp-block-h5ap-tailwind wp-block-h5ap-audioplayer\">\r\n    <\/div>\n\n\n\n<p style=\"text-align:right\"><strong>Salto, Lunes 21 de junio de 2021<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Salto, Lunes 21 de junio de 2021<\/p>\n","protected":false},"author":5,"featured_media":19548,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-varias"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-8as","jetpack-related-posts":[{"id":31060,"url":"https:\/\/lahoradelcampo.com.uy\/site\/informe-climatico-de-jose-maria-rodriguez-del-7-de-junio-de-2021\/","url_meta":{"origin":31400,"position":0},"title":"Informe clim\u00e1tico de Jos\u00e9 Mar\u00eda Rodr\u00edguez del 7 de junio de 2021","author":"La Hora del Campo","date":"7 junio, 2021","format":false,"excerpt":"Salto, lunes 7 de junio de 2021","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":31258,"url":"https:\/\/lahoradelcampo.com.uy\/site\/informe-de-jose-maria-rodriguez-del-14-de-junio-de-2021\/","url_meta":{"origin":31400,"position":1},"title":"Informe de Jos\u00e9 Mar\u00eda Rodr\u00edguez del 14 de junio de 2021","author":"La Hora del Campo","date":"14 junio, 2021","format":false,"excerpt":"Salto, lunes 14 de junio de 2021","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":31362,"url":"https:\/\/lahoradelcampo.com.uy\/site\/informe-de-jose-maria-rodriguez-del-18-de-junio-de-2021\/","url_meta":{"origin":31400,"position":2},"title":"Informe de Jos\u00e9 Mar\u00eda Rodr\u00edguez del 18 de junio de 2021","author":"La Hora del Campo","date":"18 junio, 2021","format":false,"excerpt":"Salto, 18 de junio de 2021","rel":"","context":"En \u00abVarias\u00bb","block_context":{"text":"Varias","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/varias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":31342,"url":"https:\/\/lahoradelcampo.com.uy\/site\/informe-de-jose-maria-rodriguez-para-el-16-de-junio-de-2021\/","url_meta":{"origin":31400,"position":3},"title":"Informe de Jos\u00e9 Mar\u00eda Rodr\u00edguez para el 16 de junio de 2021","author":"La Hora del Campo","date":"16 junio, 2021","format":false,"excerpt":"Salto, mi\u00e9rcoles 16 de junio de 2021","rel":"","context":"En \u00abVarias\u00bb","block_context":{"text":"Varias","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/varias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":31706,"url":"https:\/\/lahoradelcampo.com.uy\/site\/informe-de-jose-maria-rodriguez-del-30-de-junio-de-2021\/","url_meta":{"origin":31400,"position":4},"title":"Informe de Jos\u00e9 Mar\u00eda Rodr\u00edguez del 30 de junio de 2021","author":"La Hora del Campo","date":"30 junio, 2021","format":false,"excerpt":"Salto, 30 de junio de 2021","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":31560,"url":"https:\/\/lahoradelcampo.com.uy\/site\/informe-de-jose-maria-rodriguez-del-28-de-junio-de-2021\/","url_meta":{"origin":31400,"position":5},"title":"Informe de Jos\u00e9 Mar\u00eda Rodr\u00edguez del 28 de junio de 2021","author":"La Hora del Campo","date":"28 junio, 2021","format":false,"excerpt":"Salto, 28 de junio de 2021","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/Josema-nuevo.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/31400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=31400"}],"version-history":[{"count":1,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/31400\/revisions"}],"predecessor-version":[{"id":31402,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/31400\/revisions\/31402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/19548"}],"wp:attachment":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=31400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=31400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=31400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}