{"id":19564,"date":"2020-05-11T07:30:12","date_gmt":"2020-05-11T10:30:12","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=19564"},"modified":"2020-05-11T01:46:53","modified_gmt":"2020-05-11T04:46:53","slug":"central-lanera-aun-no-definio-fecha-para-la-liquidacion-final","status":"publish","type":"post","link":"https:\/\/lahoradelcampo.com.uy\/site\/central-lanera-aun-no-definio-fecha-para-la-liquidacion-final\/","title":{"rendered":"Central Lanera a\u00fan no defini\u00f3 fecha para la liquidaci\u00f3n final"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"405\" data-attachment-id=\"3517\" data-permalink=\"https:\/\/lahoradelcampo.com.uy\/site\/ime-en-australia-alcanzan-los-us-1252-en-una-semana-positiva\/lanas-7\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/11\/Lanas.jpg?fit=880%2C440&amp;ssl=1\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Vicente-Manuel-Tort&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;Presidencia de la Republica - Sec.Com.Inst.&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Lanas\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/11\/Lanas.jpg?fit=810%2C405&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/11\/Lanas.jpg?resize=810%2C405\" alt=\"\" class=\"wp-image-3517\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/11\/Lanas.jpg?w=880&amp;ssl=1 880w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/11\/Lanas.jpg?resize=300%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/11\/Lanas.jpg?resize=768%2C384&amp;ssl=1 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/11\/Lanas.jpg?resize=820%2C410&amp;ssl=1 820w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<p>Diego Saavedra, director general de Central Lanera Uruguaya, indic\u00f3 que el directorio de la cooperativa ha decidido mantener la planta de Lanera Piedra Alta, sin actividad hasta visualizar un cambio en el mercado (por lo menos estar\u00e1 cerrada durante mayo). El funcionario dijo que la cooperativa contin\u00faa con su operativa normal en el resto de los sectores. <br><\/p>\n\n\n\n<p>Consultado sobre la liquidaci\u00f3n final de la zafra lanera 2019\/2020, que en abril confirm\u00f3 a Faxlana que hab\u00eda sido postergada en el tiempo, Saavedra dijo que a\u00fan no se ha definido la fecha y record\u00f3 que la quietud del mercado ha determinado un bajo nivel de comercializaci\u00f3n de la lana remitida por los productores, por lo tanto hasta no alcanzar un nivel de volumen de venta que permita definir un valor s\u00f3lido y que refleje la realidad del mercado y la zafra. <br><\/p>\n\n\n\n<p>Recordemos que en este momento, hace m\u00e1s de un mes, que no existen valores de referencia en el mercado local. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diego Saavedra, director general de Central Lanera Uruguaya, indic\u00f3 que el directorio de la cooperativa ha decidido mantener la planta de Lanera Piedra Alta, sin actividad hasta visualizar un cambio [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":3517,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,5],"tags":[],"class_list":["post-19564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-ganaderia"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/11\/Lanas.jpg?fit=880%2C440&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-55y","jetpack-related-posts":[{"id":42027,"url":"https:\/\/lahoradelcampo.com.uy\/site\/clu-analiza-realizar-una-liquidacion-parcial-de-la-zafra-lanera\/","url_meta":{"origin":19564,"position":0},"title":"CLU analiza realizar una liquidaci\u00f3n parcial de la zafra lanera","author":"La Hora del Campo","date":"19 mayo, 2022","format":false,"excerpt":"La situaci\u00f3n del mercado lanero ha mantenido su tendencia pr\u00e1cticamente toda la zafra, m\u00e1s all\u00e1 de un centavo m\u00e1s o un centavo menos. La demanda est\u00e1 focalizada en lanas merinas, principalmente de alta calidad y con certificaciones de sustentabilidad, en tanto que las lanas medias y gruesas han venido m\u00e1s\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/05\/CLU-diegosaavedra.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/05\/CLU-diegosaavedra.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/05\/CLU-diegosaavedra.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/05\/CLU-diegosaavedra.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":18814,"url":"https:\/\/lahoradelcampo.com.uy\/site\/clu-postergo-el-cierre-de-la-zafra-lanera-2019-2020\/","url_meta":{"origin":19564,"position":1},"title":"CLU posterg\u00f3 el cierre de  la zafra lanera 2019\/2020","author":"La Hora del Campo","date":"13 abril, 2020","format":false,"excerpt":"El gerente de Central Lanera Uruguaya (CLU), Diego Saavedra, dialog\u00f3 con La Hora del Campo sobre la situaci\u00f3n que atraviesa la industria lanera uruguaya en la actualidad y confirm\u00f3 que la empresa de los productores ha definido postergar el cierre de zafra de la cooperativa debido al bajo nivel de\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/04\/Saavedra.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/04\/Saavedra.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/04\/Saavedra.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/04\/Saavedra.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":52934,"url":"https:\/\/lahoradelcampo.com.uy\/site\/central-lanera-uruguaya-comienza-en-30-dias-a-pagar-a-los-productores\/","url_meta":{"origin":19564,"position":2},"title":"Central Lanera Uruguaya comienza en 30 d\u00edas a pagar a los productores","author":"La Hora del Campo","date":"30 octubre, 2023","format":false,"excerpt":"El concurso voluntario al cual se present\u00f3 Central Lanera Uruguaya (CLU) contin\u00faa con avanzando, hacia lo que ser\u00e1 la venta de la planta industrial en Florida y de ser necesario, otros activos para hacer frente a los adeudos que mantiene la empresa, principalmente con las entidades financieras. Entre los acreedores\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/10\/Diego-Saavedra.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/10\/Diego-Saavedra.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/10\/Diego-Saavedra.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/10\/Diego-Saavedra.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":32912,"url":"https:\/\/lahoradelcampo.com.uy\/site\/central-lanera-uruguaya-comenzo-a-certificar-lanas-rws\/","url_meta":{"origin":19564,"position":3},"title":"Central Lanera Uruguaya comenz\u00f3 a certificar lanas RWS","author":"La Hora del Campo","date":"10 agosto, 2021","format":false,"excerpt":"Central Lanera Uruguaya a comenzado el proceso de certificar la lana de sus productores bajo el Est\u00e1ndar de Lana Responsable (RWS por sus siglas en ingl\u00e9s) debido a la demanda desde el exterior, principalmente de Europa y Jap\u00f3n, por este tipo de certificaciones, as\u00ed lo confirm\u00f3 el gerente de la\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Lana-s.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Lana-s.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Lana-s.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Lana-s.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":41145,"url":"https:\/\/lahoradelcampo.com.uy\/site\/en-el-tramo-final-de-la-zafra-lanera-hay-mucho-mas-mesura-en-los-negocios\/","url_meta":{"origin":19564,"position":4},"title":"En el tramo final de la zafra lanera \u00abhay mucho m\u00e1s mesura\u00bb en los negocios","author":"La Hora del Campo","date":"26 abril, 2022","format":false,"excerpt":"La zafra lanera tiene por delante la presente semana de abril y luego dos meses para cerrar un a\u00f1o de subas y bajas en los valores, con mayor agilidad en unos micronajes que en otros y con varios eventos que han afectado la comercializaci\u00f3n en este per\u00edodo. Diego Saavedra, el\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/04\/CLU-Saavedra.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/04\/CLU-Saavedra.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/04\/CLU-Saavedra.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/04\/CLU-Saavedra.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":45375,"url":"https:\/\/lahoradelcampo.com.uy\/site\/clu-comenzo-a-liquidar-las-lanas-medias-y-gruesas-de-la-ultima-zafra\/","url_meta":{"origin":19564,"position":5},"title":"CLU comenz\u00f3 a liquidar las lanas medias y gruesas de la \u00faltima zafra","author":"La Hora del Campo","date":"8 septiembre, 2022","format":false,"excerpt":"Central Lanera Uruguaya (CLU) realiz\u00f3 una liquidaci\u00f3n parcial en mayo de las lanas remitidas a la cooperativa durante la \u00faltima zafra, en tanto que esta semana comenz\u00f3 a realizar el pago del resto de los micronajes que a esa fecha se encontraban con un alto porcentaje a\u00fan sin colocaci\u00f3n. Recordemos\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/05\/CLU-diegosaavedra.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/05\/CLU-diegosaavedra.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/05\/CLU-diegosaavedra.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/05\/CLU-diegosaavedra.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/19564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=19564"}],"version-history":[{"count":1,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/19564\/revisions"}],"predecessor-version":[{"id":19566,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/19564\/revisions\/19566"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/3517"}],"wp:attachment":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=19564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=19564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=19564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}