{"id":19160,"date":"2020-04-24T06:15:55","date_gmt":"2020-04-24T09:15:55","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=19160"},"modified":"2020-04-24T08:18:19","modified_gmt":"2020-04-24T11:18:19","slug":"mercado-lanero-australiano-perdio-26-centavos-en-el-ime","status":"publish","type":"post","link":"https:\/\/lahoradelcampo.com.uy\/site\/mercado-lanero-australiano-perdio-26-centavos-en-el-ime\/","title":{"rendered":"Mercado lanero australiano perdi\u00f3  26 centavos en el IME"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"405\" data-attachment-id=\"1339\" data-permalink=\"https:\/\/lahoradelcampo.com.uy\/site\/lote-de-181-micras-cotizo-a-us-1080\/lanas-a\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Lanas-a.jpg?fit=880%2C440&amp;ssl=1\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Vicente-Manuel-Tort&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;Presidencia de la Republica - Sec.Com.Inst.&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Lanas a\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Lanas-a.jpg?fit=810%2C405&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Lanas-a.jpg?resize=810%2C405\" alt=\"\" class=\"wp-image-1339\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Lanas-a.jpg?w=880&amp;ssl=1 880w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Lanas-a.jpg?resize=300%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Lanas-a.jpg?resize=768%2C384&amp;ssl=1 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Lanas-a.jpg?resize=820%2C410&amp;ssl=1 820w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<p>La pasada semana el mercado se vi\u00f3 influenciado por el tipo de cambio, que permiti\u00f3 una recuperaci\u00f3n importante del Indicador de Mercados del Este (IME), sin embargo en un mundo tan inestable desde el punto de vista econ\u00f3mico, estaba dentro de las posibilidades el descenso acontecido esta semana, donde las monedas volvieron a jugar su papel pero en esta oportunidad a la inversa. <\/p>\n\n\n\n<p>El mercado lanero australiano cerr\u00f3 perdiendo 26 centavos por kilogramo base limpia en la moneda estadounidense, mientras que en d\u00f3lares australianos el mercado cerr\u00f3 20 centavos por debajo del mi\u00e9rcoles de la pasada semana. En este sentido el Indicador de Mercados del Este (IME) cerr\u00f3 en US$ 8,02, mientras que en la moneda local cotiz\u00f3 a A$ 12,72. <\/p>\n\n\n\n<p>La calidad de la oferta fue la principal variable bajista que encontr\u00f3 el mercado esta semana, sin embargo el bajo nivel de la oferta permiti\u00f3 darle sost\u00e9n al mercado. La oferta semanal la oferta alcanz\u00f3 los 24.947 fardos, de los cuales se vendi\u00f3 en los dos d\u00edas de actividad un 84,7% del total. <\/p>\n\n\n\n<p>Las ventas del mercado lanero australiano se retomar\u00e1n el pr\u00f3ximo mi\u00e9rcoles 29 de abril y continuar\u00e1n el d\u00eda jueves 30. La oferta estar\u00e1 compuesta por 25.554 fardos inscritos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pasada semana el mercado se vi\u00f3 influenciado por el tipo de cambio, que permiti\u00f3 una recuperaci\u00f3n importante del Indicador de Mercados del Este (IME), sin embargo en un mundo [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1339,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,5],"tags":[],"class_list":["post-19160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-ganaderia"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Lanas-a.jpg?fit=880%2C440&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-4Z2","jetpack-related-posts":[{"id":12635,"url":"https:\/\/lahoradelcampo.com.uy\/site\/el-ime-entro-al-receso-en-us-1222-subiendo-10-centavos-en-la-semana\/","url_meta":{"origin":19160,"position":0},"title":"El IME entr\u00f3 al receso en US$ 12,22, subiendo 10 centavos en la semana","author":"La Hora del Campo","date":"12 julio, 2019","format":false,"excerpt":"El mercado lanero australiano cerr\u00f3 las ventas de esta semana con un nuevo incremento en los valores de referencia del Indicador de Mercados del Este (IME). Una demanda firme en la b\u00fasqueda de adquirir el volumen necesario para afrontar las tres semanas de receso que comienzan en Australia permitieron un\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/07\/Lana-australia1.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/07\/Lana-australia1.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/07\/Lana-australia1.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/07\/Lana-australia1.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":24480,"url":"https:\/\/lahoradelcampo.com.uy\/site\/ime-recupero-18-centavos-esta-semana-y-cerro-a-us-727\/","url_meta":{"origin":19160,"position":1},"title":"IME recuper\u00f3 18 centavos esta semana y cerr\u00f3 a US$ 7,27","author":"La Hora del Campo","date":"9 octubre, 2020","format":false,"excerpt":"El mercado lanero australiano volvi\u00f3 a mostrarse firme en sus valores esta semana, m\u00e1s all\u00e1 de leves vaivenes en la moneda local en algunos micronajes al cierre de la semana, principalmente por la calidad de la lana ofertada, el feriado en China y el aumento de la oferta. Al trasladarse\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Lanas-Australia.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Lanas-Australia.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Lanas-Australia.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Lanas-Australia.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":37183,"url":"https:\/\/lahoradelcampo.com.uy\/site\/el-ime-cerro-la-semana-con-una-baja-de-dos-centavos\/","url_meta":{"origin":19160,"position":2},"title":"El IME cerr\u00f3 la semana con una baja de dos centavos","author":"La Hora del Campo","date":"3 diciembre, 2021","format":false,"excerpt":"En el medio de los vaivenes econ\u00f3micos generados por la nueva variante del Covid-19 \"Omicron\", el mercado lanero australiano se mostr\u00f3 firme y al alza esta semana en la moneda australiana, sin embargo el Indicador de Mercados del Este (IME) termina retrocediendo dos centavos al finalizar la segunda jornada de\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/06\/lanaaustralia1.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/06\/lanaaustralia1.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/06\/lanaaustralia1.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/06\/lanaaustralia1.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":9587,"url":"https:\/\/lahoradelcampo.com.uy\/site\/ime-gano-1-centavo-y-cerro-a-us-1383\/","url_meta":{"origin":19160,"position":3},"title":"IME gan\u00f3 1 centavo y cerr\u00f3 a US$ 13,83","author":"La Hora del Campo","date":"5 abril, 2019","format":false,"excerpt":"Semana estable en el mercado lanero australiano analizado en d\u00f3lares estadounidenses, favorecido por el tipo de cambio, a pesar que la baja calidad de la oferta contin\u00faa presionando los valores en la moneda local. Pr\u00e1cticamente se puede se\u00f1alar dos mercados muy claros y contrastantes, uno conformado por lanas de buena\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Lanas-Australia.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Lanas-Australia.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Lanas-Australia.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Lanas-Australia.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":9923,"url":"https:\/\/lahoradelcampo.com.uy\/site\/ime-subio-11-centavos-en-la-semana-previa-al-receso-de-pascuas\/","url_meta":{"origin":19160,"position":4},"title":"IME subi\u00f3 11 centavos en la semana previa al receso de Pascuas","author":"La Hora del Campo","date":"19 abril, 2019","format":false,"excerpt":"Con el receso de las Pascuas en la puerta, la demanda apunt\u00f3 a hacerse del volumen necesario para mantener la operativa a nivel de la industria, sin embargo contin\u00fao firme en su posicionamiento, pagando m\u00e1s por lo que vale m\u00e1s y castigando aquellos lotes con claros efectos de la sequ\u00eda\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Lanas.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Lanas.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Lanas.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Lanas.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":37427,"url":"https:\/\/lahoradelcampo.com.uy\/site\/la-demanda-esta-firme-y-el-ime-gana-seis-centavos-en-la-semana\/","url_meta":{"origin":19160,"position":5},"title":"La demanda est\u00e1 firme y el IME gana seis centavos en la semana","author":"La Hora del Campo","date":"10 diciembre, 2021","format":false,"excerpt":"El mercado lanero australiano cerr\u00f3 con alzas en ambas monedas, aunque mostr\u00f3 una mayor fortaleza en la moneda local que en d\u00f3lares estadounidenses, pero lo m\u00e1s importante es la fuerte demanda que se present\u00f3 por parte de los compradores chinos. Las lanas finas y superfinas, contin\u00faan con la demanda desde\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/03\/Lanaa.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/03\/Lanaa.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/03\/Lanaa.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/03\/Lanaa.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/19160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=19160"}],"version-history":[{"count":1,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/19160\/revisions"}],"predecessor-version":[{"id":19166,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/19160\/revisions\/19166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/1339"}],"wp:attachment":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=19160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=19160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=19160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}