{"id":16134,"date":"2019-11-29T09:11:14","date_gmt":"2019-11-29T12:11:14","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=16134"},"modified":"2019-11-30T16:13:38","modified_gmt":"2019-11-30T19:13:38","slug":"miguel-sanguinetti-la-lana-esta-trancada-en-su-comercializacion","status":"publish","type":"post","link":"https:\/\/lahoradelcampo.com.uy\/site\/miguel-sanguinetti-la-lana-esta-trancada-en-su-comercializacion\/","title":{"rendered":"Miguel Sanguinetti: La lana esta trancada en su comercializaci\u00f3n"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"405\" data-attachment-id=\"16130\" data-permalink=\"https:\/\/lahoradelcampo.com.uy\/site\/el-sul-presento-los-resultados-y-propuestas-para-mejorar-el-rubro-ovino\/sanguinetti\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/11\/Sanguinetti.jpg?fit=880%2C440&amp;ssl=1\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Sanguinetti\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/11\/Sanguinetti.jpg?fit=810%2C405&amp;ssl=1\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/11\/Sanguinetti.jpg?resize=810%2C405\" alt=\"\" class=\"wp-image-16130\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/11\/Sanguinetti.jpg?w=880&amp;ssl=1 880w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/11\/Sanguinetti.jpg?resize=300%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/11\/Sanguinetti.jpg?resize=768%2C384&amp;ssl=1 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/11\/Sanguinetti.jpg?resize=820%2C410&amp;ssl=1 820w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<p>Sobre la situaci\u00f3n del rubro, el presidente del SUL reconoci\u00f3 que en los \u00faltimos tres a cuatro meses \u201cvenimos con una trancadera en la comercializaci\u00f3n de la lana, con precios que se han tenido que ir reacomodando. El productor que ha podido no ha vendido, aunque lamentablemente algunos por problemas particulares ha tenido que vender a precios m\u00e1s bajo, cosas que no nos gustan porque queremos que el productor haga su mejor negocio\u201d.<br><\/p>\n\n\n\n<p>Pero acot\u00f3 que \u201cpor suerte el ganado vacuno est\u00e1 valiendo, y eso hace que el productor de ovinos que tiene los dos rubros se defienda de otra manera\u201d.<br><\/p>\n\n\n\n<p>Sobre la situaci\u00f3n econ\u00f3mica de la instituci\u00f3n, relacionada directamente con la lana, la fuente de ingreso tambi\u00e9n para el SUL, dijo que \u201clo venimos monitoreando todas las semanas, y por suerte en el \u00faltimo per\u00edodo hab\u00eda quedado una fuerte reserva en la instituci\u00f3n, lo que nos ha ayudado much\u00edsimo\u201d.<br><\/p>\n\n\n\n<p>\u201cHemos manejado las ventas de las producciones de los dos campos en forma adelantada\u201d, citando el ejemplo de la venta \u201cde unas vaquillonas que estaban en el engorde y con muy buenos precios. Tambi\u00e9n hay lanares vendidos a frigor\u00edfico, logrando equilibrar los n\u00fameros recibiendo de la lana pr\u00e1cticamente en un 100 por ciento\u201d.<br><\/p>\n\n\n\n<p>Tambi\u00e9n se refiri\u00f3 a que Uruguay hoy importa de Brasil y Argentina lana para trabajarlas en la industria uruguaya, \u201cy que muchas veces sale con el sello de lana uruguaya. Consideramos que si la lana sale al exterior con el sello de lana uruguaya, la instituci\u00f3n tuvo mucho que ver en la valorizaci\u00f3n de esa lana\u201d.<br><\/p>\n\n\n\n<p>La idea de Sanguinetti \u201ces comenzar a trabajar regionalmente para el lado de Rio Grande, Curuz\u00fa Cuati\u00e1 o alg\u00fan otro punto de Argentina, tratando de llevar nuestra t\u00e9cnica a productores de la regi\u00f3n y as\u00ed rescatar recursos. Incluso, estamos pensando que t\u00e9cnicos que recientemente se han jubilado del SUL, podr\u00edan hacer trabajos en el exterior y traer lanas que lleguen en buena calidad, lo que favorecer\u00e1 a la industria local y el pa\u00eds, y que de eso el SUL tambi\u00e9n reciba algo\u201d.<br><\/p>\n\n\n<p><!--EndFragment--><br>\n<br>\n<\/p>","protected":false},"excerpt":{"rendered":"<p>Sobre la situaci\u00f3n del rubro, el presidente del SUL reconoci\u00f3 que en los \u00faltimos tres a cuatro meses \u201cvenimos con una trancadera en la comercializaci\u00f3n de la lana, con precios [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":16130,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,5],"tags":[],"class_list":["post-16134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-ganaderia"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/11\/Sanguinetti.jpg?fit=880%2C440&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-4ce","jetpack-related-posts":[{"id":3843,"url":"https:\/\/lahoradelcampo.com.uy\/site\/operativa-lanera-retraida-con-importantes-pretensiones-de-los-vendedores\/","url_meta":{"origin":16134,"position":0},"title":"Operativa lanera retra\u00edda con importantes pretensiones de los vendedores","author":"La Hora del Campo","date":"10 noviembre, 2017","format":false,"excerpt":"Operadores en la zona han se\u00f1alado en los \u00faltimos d\u00edas que debido a los altos valores que se registraron en la pasada semana a nivel de lotes de lana merino australiano superfinas y con la importante suba que ha tenido el mercado internacional en Australia estas dos \u00faltimas semanas, el\u2026","rel":"","context":"En \u00abGanader\u00eda\u00bb","block_context":{"text":"Ganader\u00eda","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/ganaderia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/11\/lana-u.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/11\/lana-u.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/11\/lana-u.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/11\/lana-u.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":26008,"url":"https:\/\/lahoradelcampo.com.uy\/site\/la-caida-de-los-precios-de-la-lana-lleva-a-los-productores-chicos-a-dejar-el-rubro\/","url_meta":{"origin":16134,"position":1},"title":"La ca\u00edda de los precios de la lana, lleva a los productores chicos a dejar el rubro","author":"La Hora del Campo","date":"10 diciembre, 2020","format":false,"excerpt":"La zona de Mataojo se encuentra al este del departamento de Salto, sobre el arroyo del mismo nombre, campos de basalto superficial del norte del pa\u00eds que hist\u00f3ricamente se han compartido entre ovinos y vacunos, principalmente por la especie ovina. Sin embargo se observa que esta especie va disminuyendo cada\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/04\/Ovinos.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/04\/Ovinos.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/04\/Ovinos.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/04\/Ovinos.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":10993,"url":"https:\/\/lahoradelcampo.com.uy\/site\/los-valores-de-las-lanas-llegaron-a-su-techo-esta-zafra\/","url_meta":{"origin":16134,"position":2},"title":"Los valores de las lanas llegaron a su techo esta zafra","author":"La Hora del Campo","date":"22 mayo, 2019","format":false,"excerpt":"Facundo Ruvira - Director de Top Fray Marcos La zafra lanera 2018\/19 est\u00e1 llegando lentamente a su final, faltando seis semanas de venta tanto a nivel nacional como internacional. El Director de Top Fray Marcos, Facundo Ruvira, en di\u00e1logo con La Hora del Campo dijo que \u201cfue una zafra muy\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/05\/Ruvira.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/05\/Ruvira.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/05\/Ruvira.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/05\/Ruvira.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":19764,"url":"https:\/\/lahoradelcampo.com.uy\/site\/la-exportacion-de-lana-en-sucio-tambien-esta-paralizada\/","url_meta":{"origin":16134,"position":3},"title":"La exportaci\u00f3n de lana en sucio  tambi\u00e9n est\u00e1 paralizada","author":"La Hora del Campo","date":"14 mayo, 2020","format":false,"excerpt":"En las \u00faltimas semanas hablamos de la par\u00e1lisis en la industria lanera con plantas que a\u00fan contin\u00faan sin operativa. En las \u00faltimas horas estuvimos en di\u00e1logo con Djalma Puppo, exportador de lana en sucio, un sector que tambi\u00e9n est\u00e1 paralizado completamente en la actualidad, sin demanda desde el exterior y\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/lana-1.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/lana-1.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/lana-1.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/lana-1.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":24048,"url":"https:\/\/lahoradelcampo.com.uy\/site\/sul-recurre-a-linea-de-credito-ante-caida-de-las-exportaciones-de-lana\/","url_meta":{"origin":16134,"position":4},"title":"SUL recurre a l\u00ednea de cr\u00e9dito ante ca\u00edda de las exportaciones de lana","author":"La Hora del Campo","date":"28 septiembre, 2020","format":false,"excerpt":"Las ventas de lana al exterior han disminuido fuertemente en este \u00faltimo a\u00f1o, teniendo en cuenta el impacto que ha generado la pandemia en el mundo de la moda y principalmente en el mercado lanero. Al igual que las industrias laneras, que atraviesan momentos cr\u00edticos por sus bajas ventas al\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/09\/Volonte.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/09\/Volonte.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/09\/Volonte.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/09\/Volonte.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":7353,"url":"https:\/\/lahoradelcampo.com.uy\/site\/excelente-optimismo-para-la-zafra-lanera-con-un-buen-momento-de-precios-a-nivel-internacional\/","url_meta":{"origin":16134,"position":5},"title":"\u00abExcelente optimismo para la zafra lanera, con un buen momento de precios a nivel internacional\u00bb","author":"La Hora del Campo","date":"25 mayo, 2018","format":false,"excerpt":"En momentos donde termina la zafra lanera 2017-18, pr\u00e1cticamente sin disponibilidad de lana, y comienzan a prepararse las primeras esquilas pre parto y crece la consulta por negocios en el lomo y los tanteos de precios en el mercado, La Hora del Campo dialog\u00f3 con el rematador Carlos Andr\u00e9s Moriondo,\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Moriondo.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Moriondo.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Moriondo.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Moriondo.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/16134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=16134"}],"version-history":[{"count":1,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/16134\/revisions"}],"predecessor-version":[{"id":16136,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/16134\/revisions\/16136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/16130"}],"wp:attachment":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=16134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=16134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=16134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}