{"id":1607,"date":"2017-09-21T18:23:11","date_gmt":"2017-09-21T21:23:11","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=1607"},"modified":"2017-09-21T18:23:11","modified_gmt":"2017-09-21T21:23:11","slug":"solo-si-falta-arroz-se-obtiene-un-buen-precio","status":"publish","type":"post","link":"https:\/\/lahoradelcampo.com.uy\/site\/solo-si-falta-arroz-se-obtiene-un-buen-precio\/","title":{"rendered":"Solo si falta arroz, se obtiene un buen precio"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Roberto-Amaral.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1609\" data-permalink=\"https:\/\/lahoradelcampo.com.uy\/site\/solo-si-falta-arroz-se-obtiene-un-buen-precio\/roberto-amaral\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Roberto-Amaral.jpg?fit=880%2C440&amp;ssl=1\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Vicente-Manuel-Tort&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;Presidencia de la Republica - Sec.Com.Inst.&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Roberto Amaral\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Roberto-Amaral.jpg?fit=810%2C405&amp;ssl=1\" class=\"alignright wp-image-1609 size-medium\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Roberto-Amaral.jpg?resize=300%2C150\" alt=\"\" width=\"300\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Roberto-Amaral.jpg?resize=300%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Roberto-Amaral.jpg?resize=768%2C384&amp;ssl=1 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Roberto-Amaral.jpg?resize=820%2C410&amp;ssl=1 820w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Roberto-Amaral.jpg?w=880&amp;ssl=1 880w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>La problem\u00e1tica del sector arrocero, que est\u00e1 llevando a una reducci\u00f3n de \u00e1rea en nuestro pa\u00eds, tambi\u00e9n se extiende a los dem\u00e1s pa\u00edses de la regi\u00f3n y los productores en Brasil est\u00e1n fuertemente preocupados en presionar al gobierno para limitar el ingreso del arroz de la regi\u00f3n y mejorar los valores del cereal, ante un margen muy acotado debido a los altos costos productivos.<\/p>\n<p>Roberto Amaral es productor arrocero en el estado de R\u00edo Grande del Sur, Brasil, y en el marco de la Expo Prado dijo a La Hora del Campo, que \u201clos costos est\u00e1n muy altos como en Uruguay, tenemos 2.000 d\u00f3lares por hect\u00e1rea\u201d, seg\u00fan el productor adem\u00e1s de los altos costos se debe tener en cuenta la problem\u00e1tica \u201cpol\u00edtica\u201d del vecino pa\u00eds, con una \u201ceconom\u00eda que est\u00e1 muy desarticulada\u201d.<\/p>\n<p>Amaral sostuvo que \u201cporteras adentro\u201d el productor brasile\u00f1o se encuentra trabajando con \u201cproductividades muy altas, quienes est\u00e1n trabajando con tecnolog\u00eda de punta est\u00e1n cosechando entre 9 y 10 mil kilos por hect\u00e1rea\u201d por lo que consider\u00f3 que \u201ca nivel de chacra es muy dif\u00edcil aumentar la productividad para disminuir los costos\u201d.<\/p>\n<p>El productor tambi\u00e9n reclamo por la falta de financiamiento a nivel de Brasil para el sector arrocero y la problem\u00e1tica que conlleva el ingreso de arroz desde Uruguay, Argentina y \u201cel volumen significativo que entra desde Paraguay, eso est\u00e1 desequilibrando mucho el mercado\u201d.<\/p>\n<p>Roberto Amaral dijo que la regi\u00f3n de R\u00edo Grande del Sur, el principal estado productor del cereal en Brasil, se encuentra con muchas dificultades para iniciar y concretar la siembra en una fecha \u00f3ptima para el cultivo. \u201cHa llovido en los \u00faltimos 20 d\u00edas m\u00e1s de 200 mil\u00edmetros, entonces es una regi\u00f3n que est\u00e1 bastante perjudicada, ya se va a tener un atraso en la fecha \u00f3ptima de siembra. Nosotros tenemos hasta el fin de octubre para sembrar y del mes de setiembre ya no se habla m\u00e1s entonces vamos a ver si octubre mejora para poder plantar\u201d.<\/p>\n<p>En este sentido explic\u00f3 que las gremiales arroceras del estado se encuentran realizando una campa\u00f1a importante, para que los productores adopten una disminuci\u00f3n del \u00e1rea, \u201cvamos a ver si los productores acompa\u00f1an ese llamado de las gremiales porque solo se tiene precio bueno cuando se tiene falta de producto\u201d dijo Amaral, qui\u00e9n manifest\u00f3 que \u201cno habiendo falta de producto la tendencia, como es una comida popular de Brasil, es de estar el precio cada vez m\u00e1s bajo\u201d.<\/p>\n<p>El productor reconoci\u00f3 que el arroz \u201ces un producto para el pobre en Brasil\u201d, remarc\u00f3 que existen \u201calgunos l\u00edmites de rentabilidad para que el productor pueda mantener la actividad, sino habr\u00e1 que sustituir por soja, ganader\u00eda, o alguna otra producci\u00f3n porque si el arroz queda como est\u00e1 no hay mucho como sobrevivir\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La problem\u00e1tica del sector arrocero, que est\u00e1 llevando a una reducci\u00f3n de \u00e1rea en nuestro pa\u00eds, tambi\u00e9n se extiende a los dem\u00e1s pa\u00edses de la regi\u00f3n y los productores en [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1609,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,7],"tags":[399,127,401],"class_list":["post-1607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-agricultura","tag-arroz","tag-brasil","tag-rio-grande-del-sur"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Roberto-Amaral.jpg?fit=880%2C440&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-pV","jetpack-related-posts":[{"id":38855,"url":"https:\/\/lahoradelcampo.com.uy\/site\/se-han-perdido-1-500-hectareas-de-arroz-en-el-norte-del-pais\/","url_meta":{"origin":1607,"position":0},"title":"Se han perdido 1.500 hect\u00e1reas de arroz en el norte del pa\u00eds","author":"La Hora del Campo","date":"3 febrero, 2022","format":false,"excerpt":"La falta de precipitaciones y el alto nivel de evapotranspiraci\u00f3n en el norte del pa\u00eds ha determinado que el sector arrocero tambi\u00e9n sea afectado por menores rendimientos y muchas chacras y el abandono de algunas debido a la falta de agua en las represas. Entre los departamentos de Salto y\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/05\/arroz-2.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/05\/arroz-2.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/05\/arroz-2.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/05\/arroz-2.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":47019,"url":"https:\/\/lahoradelcampo.com.uy\/site\/costos-del-arroz-superan-los-ingresos-actuales-del-cereal\/","url_meta":{"origin":1607,"position":1},"title":"Costos del arroz superan los ingresos actuales del cereal","author":"La Hora del Campo","date":"16 noviembre, 2022","format":false,"excerpt":"El inicio de la zafra arrocera 2022-2023 augura nuevamente altos niveles de producci\u00f3n, con una siembra r\u00e9cord dentro de la ventana \u00f3ptima para el cultivo, con mayor disponibilidad de agua respecto a la zafra anterior, pero con preocupaci\u00f3n con los altos costos con los cuales se ha sembrado el cereal.\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/08\/Guillermo-Obrien.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/08\/Guillermo-Obrien.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/08\/Guillermo-Obrien.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/08\/Guillermo-Obrien.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":16332,"url":"https:\/\/lahoradelcampo.com.uy\/site\/con-una-menor-siembra-de-arroz-en-la-region-los-precios-suben-en-brasil\/","url_meta":{"origin":1607,"position":2},"title":"Con una menor siembra de arroz en la regi\u00f3n, los precios suben en Brasil","author":"La Hora del Campo","date":"9 diciembre, 2019","format":false,"excerpt":"El sector arrocero en la regi\u00f3n atraves\u00f3 un periodo de siembra dif\u00edcil este a\u00f1o con el clima y el \u00e1rea de del cultivo ha ca\u00eddo por debajo de las expectativas, lo que ha hecho que las cotizaciones del cereal en Brasil, el principal consumidor del Mercosur, comiencen a subir, llegando\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/Arroceros.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/Arroceros.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/Arroceros.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/Arroceros.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":6337,"url":"https:\/\/lahoradelcampo.com.uy\/site\/aumento-del-arroz-a-nivel-internacional-se-lo-devora-los-costos-industriales\/","url_meta":{"origin":1607,"position":3},"title":"Aumento del arroz a nivel internacional  se lo \u00abdevora\u00bb los costos industriales","author":"La Hora del Campo","date":"4 abril, 2018","format":false,"excerpt":"El sector arrocero uruguayo se encuentra en plena zafra de cosecha de arroz, principalmente aqu\u00ed en el norte del pa\u00eds donde se comienza antes la recolecci\u00f3n del grano. El productor salte\u00f1o y directivo de la Asociaci\u00f3n de Cultivadores de Arroz del Uruguay, Guillermo O'brien, se\u00f1al\u00f3 que de las 28.000 hect\u00e1reas\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/04\/Guillermo-web.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/04\/Guillermo-web.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/04\/Guillermo-web.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/04\/Guillermo-web.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":54059,"url":"https:\/\/lahoradelcampo.com.uy\/site\/el-arrocero-aumentara-el-area-pero-no-me-imagino-a-estos-niveles-de-precios-dijo-obrien\/","url_meta":{"origin":1607,"position":4},"title":"El arrocero aumentar\u00e1 el \u00e1rea, pero \u00abno me imagino a estos niveles de precios\u00bb dijo O&#8217;brien","author":"La Hora del Campo","date":"27 julio, 2024","format":false,"excerpt":"Guillermo O'Brien, vicepresidente de la Asociaci\u00f3n de Cultivadores de Arroz (ACA), destac\u00f3 que \"la capacidad de almacenamiento llena y la situaci\u00f3n actual del negocio invitan a pensar en eso\", en un incremento de \u00e1rea que podr\u00eda llegar a las 175 mil hect\u00e1reas a nivel nacional en la pr\u00f3xima zafra. El\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/07\/GuillermoObrien2.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/07\/GuillermoObrien2.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/07\/GuillermoObrien2.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/07\/GuillermoObrien2.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2953,"url":"https:\/\/lahoradelcampo.com.uy\/site\/productores-brasilenos-piden-suspender-importacion-de-arroz-de-uruguay\/","url_meta":{"origin":1607,"position":5},"title":"Productores brasile\u00f1os piden suspender importaci\u00f3n de arroz de Uruguay","author":"La Hora del Campo","date":"19 octubre, 2017","format":false,"excerpt":"Un sector que todos los a\u00f1os genera presi\u00f3n para frenar las importaciones en Brasil, es el sector arrocero, y como era de esperar se aline\u00f3 detr\u00e1s de los productores lecheros brasile\u00f1os y est\u00e1 solicitando la suspensi\u00f3n de las importaciones de arroz del Mercorsur. En esta oportunidad los productores arroceros del\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/arroz.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/arroz.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/arroz.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/arroz.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/1607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=1607"}],"version-history":[{"count":1,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/1607\/revisions"}],"predecessor-version":[{"id":1611,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/1607\/revisions\/1611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/1609"}],"wp:attachment":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=1607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=1607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=1607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}