{"id":1315,"date":"2017-09-16T12:52:26","date_gmt":"2017-09-16T15:52:26","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=1315"},"modified":"2017-09-16T22:39:03","modified_gmt":"2017-09-17T01:39:03","slug":"convivir-con-el-atraso-cambiario-esta-en-el-adn-de-los-uruguayos","status":"publish","type":"post","link":"https:\/\/lahoradelcampo.com.uy\/site\/convivir-con-el-atraso-cambiario-esta-en-el-adn-de-los-uruguayos\/","title":{"rendered":"\u00abConvivir con el atraso cambiario, est\u00e1 en el ADN de los uruguayos\u00bb"},"content":{"rendered":"<figure id=\"attachment_1317\" aria-describedby=\"caption-attachment-1317\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/pablo-zerbino.jpg\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1317\" data-permalink=\"https:\/\/lahoradelcampo.com.uy\/site\/convivir-con-el-atraso-cambiario-esta-en-el-adn-de-los-uruguayos\/pablo-zerbino\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/pablo-zerbino.jpg?fit=880%2C440&amp;ssl=1\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Vicente-Manuel-Tort&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;Presidencia de la Republica - Sec.Com.Inst.&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"pablo zerbino\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Foto: El Observador&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/pablo-zerbino.jpg?fit=810%2C405&amp;ssl=1\" class=\"size-medium wp-image-1317\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/pablo-zerbino.jpg?resize=300%2C150\" alt=\"\" width=\"300\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/pablo-zerbino.jpg?resize=300%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/pablo-zerbino.jpg?resize=768%2C384&amp;ssl=1 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/pablo-zerbino.jpg?resize=820%2C410&amp;ssl=1 820w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/pablo-zerbino.jpg?w=880&amp;ssl=1 880w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-1317\" class=\"wp-caption-text\">Foto: El Observador<\/figcaption><\/figure>\n<p>El Dr. Pablo Zerbino, presidente de la Asociaci\u00f3n Rural del Uruguay, comenz\u00f3 su discurso de clausura de la Expo Prado 2017, saludando a las mujeres rurales en el A\u00f1o Internacional de la Mujer. Posteriormente saludos a los representantes del Poder Ejecutivo presentes; el Ministro de Relaciones Exteriores, Rodolfo Nin Novoa, el Ministro de Transporte y Obras P\u00fablicas, V\u00edctor Rossi, y el Ministro Interino de Ganader\u00eda, Agricultura y Pesca, Ing. Enzo Benech; as\u00ed como tambi\u00e9n a legisladores, embajadores y representantes de la gremiales amigas e integrantes de ARU.<\/p>\n<p>En el lanzamiento de la muestra hace casi un mes atr\u00e1s, Zerbino, en este acto de cierre record\u00f3 que hace 51 a\u00f1os, qui\u00e9n estaba parado haciendo el discurso de la Asociaci\u00f3n Rural del Uruguay, fue su padre, don Jos\u00e9 Zerbino. En un repaso por la historia, se remont\u00f3 a los inicios de la gremial, donde dijo que \u00abpasaron 146 a\u00f1os de ARU colaborando con el desarrollo productivo\u00bb.<\/p>\n<p>Dentro de lo que ha sido el \u00faltimo a\u00f1o, Zerbino prefiri\u00f3 comenzar por el final dando a conocer su gran satisfacci\u00f3n por la noticia de poder exportar carne ovina con hueso a Estados Unidos, logro que fue resultado del protagonismo decisivo de la gremial y otras instituciones. Con respecto al ovino, el presidente de ARU, sostuvo que \u00abestamos lejos de solucionar el problema de jaur\u00edas de perros que atacan a animales productivos\u00bb.<\/p>\n<p>Al pasar habl\u00f3 de la inclusi\u00f3n financiera y la preocupaci\u00f3n que genera su ejecuci\u00f3n en el sector agropecuario. Posteriormente hablo de los Consejos de Salarios, donde luego de varias reuniones infructuosas, donde el sector gremial empresarial quedo en minor\u00eda y al no permitirse exponer su posici\u00f3n en el acta de dichas reuniones, decidi\u00f3 retirarse del mismo.<\/p>\n<p>\u00abUruguay no deber\u00eda dejar de vacunar\u00bb dijo Zerbino con respecto al tema de la fiebre aftosa y entre otros \u00e1mbitos de trabajo, record\u00f3 que se festejan los 50 a\u00f1os de Mevir, que a su entender es el principal y m\u00e1s exitoso plan de viviendas. En este sentido record\u00f3 el lema del Dr. Alberto Gallinal: \u00abpara ver llover de adentro sin mojarse\u00bb.<\/p>\n<p>Present\u00f3 los resultados de un trabajo realizado por Organizaci\u00f3n de las Naciones Unidas para la Alimentaci\u00f3n y la Agricultura, instituci\u00f3n conocida por FAO. En este sentido dijo que la poblaci\u00f3n urbana actualmente es del 49% y pasara al 70% en 2050 y por ello la producci\u00f3n de alimentos deber\u00e1 incrementarse un 70%. Zerbino se\u00f1al\u00f3 que el mundo distar\u00e1 mucho de solucionar el problema alimentario, en el 2050, y este objetivo no ser\u00e1 alcanzado sin pol\u00edticas que apoyen a los agricultores.<\/p>\n<blockquote><p>\u201cdeber\u00edamos aprender de Chile, que en las buenas ahorra para aguantar en las malas\u201d.<\/p><\/blockquote>\n<p>El presidente de ARU record\u00f3 que el 85% de las exportaciones de bienes son agroindustriales y debido a la dinamizaci\u00f3n que genera el sector agropecuario, \u201ccuando al campo le va bien, le va bien al pa\u00eds\u201d y dijo que \u201cdeber\u00edamos aprender de Chile, que en las buenas ahorra para aguantar en las malas\u201d.<\/p>\n<p>Pablo Zerbino destac\u00f3 la importancia de la exportaci\u00f3n en pie para sostener el precio del ternero, que el producto generado por el criador, el primer eslab\u00f3n de la cadena, lo que adem\u00e1s permiti\u00f3 un incremento de la faena en el \u00faltimo a\u00f1o. Resalt\u00f3 adem\u00e1s la gran producci\u00f3n de soja y arroz en la \u00faltima zafra, pero remarc\u00f3 que en el \u00e1mbito comercial \u201csomos los primeros de la clase al hacer los deberes pero los \u00faltimos en recibir las notas\u201d<\/p>\n<p>El presidente de la Asociaci\u00f3n Rural del Uruguay se\u00f1al\u00f3 la ca\u00edda de los n\u00fameros del sector lechero, con menos trabajadores y gran endeudamiento que equivale a todo el rodeo de vacas lecheras del pa\u00eds. \u201cLa sostenida ca\u00edda de la rentabilidad de las empresas del agro y el peso salarial lleva a recortes de mano de obra y p\u00e9rdida de productividad\u201d dijo Zerbino, el productor asegur\u00f3 que a\u00fan el sector tiene capacidad crediticia, pero se perdi\u00f3 capacidad de pagos \u201cy eso es como entrar en un corral de ramas\u201d.<\/p>\n<p>Para el productor, en materia de inserci\u00f3n internacional \u201cUruguay retrocede\u201d mientras otros pa\u00edses avanzan con estrategias internacionales. \u201cHay un claro reacomodo en el contexto internacional del que Uruguay participa poco o nada\u201d dijo Zerbino y coment\u00f3 adem\u00e1s que \u201cel gobierno usa el tipo de cambio como ancla para controlar la inflaci\u00f3n y eso aumenta los costos en d\u00f3lares del pa\u00eds\u201d.<\/p>\n<p>En este sentido resalt\u00f3 que \u201cUruguay est\u00e1 caro en d\u00f3lares\u201d y al mismo tiempo dijo que \u201caumenta la presi\u00f3n fiscal con impuestos ciegos que no tienen que ver con la reforma tributaria\u201d y que el impuesto al patrimonio \u201cno deber\u00eda existir, porque ya est\u00e1 grabado por la renta y contribuci\u00f3n inmobiliaria\u201d.<\/p>\n<blockquote><p>\u00abparece que convivir con el atraso cambiario est\u00e1 en el ADN de los uruguayos\u201d<\/p><\/blockquote>\n<p>Zerbino dijo que \u201ctropezamos una y otra vez con la misma piedra, parece que convivir con el atraso cambiario est\u00e1 en el ADN de los uruguayos\u201d, para el productor \u201ca la riqueza\u201d antes de repartirla hay que generarla con empresas privadas y \u201cla pobreza\u201d se combate con recursos genuinos que provienen de esas empresas.<\/p>\n<p>Al finalizar el productor saludo a caba\u00f1eros, expositores y jurados; agradeci\u00f3 la presencia y el apoyo de las gremiales rurales del Mercosur, a los j\u00f3venes rurales y a las dem\u00e1s gremiales empresariales. Luego de emocionarse al saludar a su familia y a las familias rurales, cerr\u00f3 su discurso diciendo \u201cViva la ARU y viva la patria\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Dr. Pablo Zerbino, presidente de la Asociaci\u00f3n Rural del Uruguay, comenz\u00f3 su discurso de clausura de la Expo Prado 2017, saludando a las mujeres rurales en el A\u00f1o Internacional [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1317,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[75,323,55,147],"class_list":["post-1315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","tag-aru","tag-economia","tag-expo-prado","tag-pablo-zerbino"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/pablo-zerbino.jpg?fit=880%2C440&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-ld","jetpack-related-posts":[{"id":753,"url":"https:\/\/lahoradelcampo.com.uy\/site\/expo-prado-aguerre-confirmo-que-no-estara-en-el-acto-de-cierre\/","url_meta":{"origin":1315,"position":0},"title":"\u00abHay un buen di\u00e1logo con el ministro Aguerre\u00bb dijo Zerbino","author":"La Hora del Campo","date":"10 septiembre, 2017","format":false,"excerpt":"El Dr. Pablo Zerbino, presidente de la Asociaci\u00f3n Rural del Uruguay, dijo que \"hay un buen di\u00e1logo con el ministro Aguerre\", luego del almuerzo de trabajo realizado en la Expo Prado 2017 entre la gremial y los integrantes del MGAP. El Ministro confirm\u00f3 a la directiva de la gremial que\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Pablo-Zerbino-Aru.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Pablo-Zerbino-Aru.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Pablo-Zerbino-Aru.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Pablo-Zerbino-Aru.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":37299,"url":"https:\/\/lahoradelcampo.com.uy\/site\/pablo-zerbino-sera-el-jurado-angus-de-la-expo-prado-2022\/","url_meta":{"origin":1315,"position":1},"title":"Pablo Zerbino ser\u00e1 el Jurado Angus de la Expo Prado 2022","author":"La Hora del Campo","date":"7 diciembre, 2021","format":false,"excerpt":"Como es tradicional, los caba\u00f1eros realizaron la elecci\u00f3n del jurado para la Expo Prado 2022 mediante la votaci\u00f3n de los candidatos presentados por la gremial y los propios caba\u00f1eros. De acuerdo a la informaci\u00f3n brindada por la Sociedad de Criadores de Aberdeen Angus del Uruguay, el pasado lunes se realiz\u00f3\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/12\/Angus-Zerbino.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/12\/Angus-Zerbino.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/12\/Angus-Zerbino.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/12\/Angus-Zerbino.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1137,"url":"https:\/\/lahoradelcampo.com.uy\/site\/el-endeudamiento-ganadero-abarca-todos-los-terneros-producidos\/","url_meta":{"origin":1315,"position":2},"title":"El endeudamiento ganadero abarca todos los terneros producidos","author":"La Hora del Campo","date":"13 septiembre, 2017","format":false,"excerpt":"El presidente de la Asociaci\u00f3n Rural del Uruguay, Dr. Pablo Zerbino, luego de la reuni\u00f3n con el Ministro de Econom\u00eda y Finanzas, Cr. Danilo Astori,\u00a0 se\u00f1al\u00f3 que los temas tratados con el representante del gobierno estuvieron centrados en las problem\u00e1ticas del sector agropecuario, desde la lecher\u00eda, agricultura, los productores arroceros\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Pablo-Zerbino-ARU.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Pablo-Zerbino-ARU.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Pablo-Zerbino-ARU.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Pablo-Zerbino-ARU.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":43473,"url":"https:\/\/lahoradelcampo.com.uy\/site\/zerbino-y-penagaricano-calificaran-las-principales-razas-britanicas-en-el-prado\/","url_meta":{"origin":1315,"position":3},"title":"Zerbino y Pe\u00f1agaricano calificaran las principales  razas brit\u00e1nicas en el Prado","author":"La Hora del Campo","date":"5 julio, 2022","format":false,"excerpt":"El pasado 30 de agosto cerr\u00f3 el plazo para las preinscripciones de animales de cara a la 117\u00aa edici\u00f3n de la Exposici\u00f3n Internacional de Ganader\u00eda y Muestra Agro Industrial y Comercial, Expo Prado 2022, que se llevar\u00e1 a cabo entre el 9 y 18 de setiembre. Para esta edici\u00f3n se\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/12\/Angus-Zerbino.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/12\/Angus-Zerbino.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/12\/Angus-Zerbino.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/12\/Angus-Zerbino.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":23670,"url":"https:\/\/lahoradelcampo.com.uy\/site\/angus-mostro-todo-el-potencial-de-los-vientres-de-la-raza-en-la-pista-del-prado\/","url_meta":{"origin":1315,"position":4},"title":"Angus mostr\u00f3 todo el potencial de los  vientres de la raza en la pista del Prado","author":"La Hora del Campo","date":"16 septiembre, 2020","format":false,"excerpt":"En una gran exhibici\u00f3n de gen\u00e9tica que demuestra el excelente momento que pasa la raza Aberdeen Angus en el pa\u00eds, el ingeniero agr\u00f3nomo Alvaro D\u00edaz Nadal tuvo un extenso trabajo con los mejores vientres expuestos por las principales caba\u00f1as del pa\u00eds. En una pista algo m\u00e1s grande que lo habitual,\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/09\/AngusGCH.jpg?fit=880%2C440&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/09\/AngusGCH.jpg?fit=880%2C440&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/09\/AngusGCH.jpg?fit=880%2C440&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/09\/AngusGCH.jpg?fit=880%2C440&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":483,"url":"https:\/\/lahoradelcampo.com.uy\/site\/el-miercoles-comienza-una-nueva-edicion-de-la-expo-prado\/","url_meta":{"origin":1315,"position":5},"title":"El mi\u00e9rcoles comienza una nueva edici\u00f3n de la Expo Prado","author":"La Hora del Campo","date":"3 septiembre, 2017","format":false,"excerpt":"El pr\u00f3ximo mi\u00e9rcoles 6 de setiembre comienza una nueva edici\u00f3n de la Expo Prado baj\u00f3 el slogan \"El campo hace ciudad, hace el pa\u00eds\" donde la Asociaci\u00f3n Rural del Uruguay realiza una nueva apuesta al encuentro campo-ciudad en la m\u00e1xima expresi\u00f3n de la gen\u00e9tica nacional. En el lanzamiento de la\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"https:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/4.jpg?fit=1040%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/4.jpg?fit=1040%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/4.jpg?fit=1040%2C400&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/4.jpg?fit=1040%2C400&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/1315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=1315"}],"version-history":[{"count":1,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/1315\/revisions"}],"predecessor-version":[{"id":1319,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/1315\/revisions\/1319"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/1317"}],"wp:attachment":[{"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=1315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=1315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=1315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}