{"id":27818,"date":"2021-02-19T09:13:20","date_gmt":"2021-02-19T12:13:20","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=27818"},"modified":"2021-02-19T09:13:28","modified_gmt":"2021-02-19T12:13:28","slug":"se-paso-la-mitad-del-mes-y-comienza-disminuir-las-ventas","status":"publish","type":"post","link":"http:\/\/lahoradelcampo.com.uy\/site\/se-paso-la-mitad-del-mes-y-comienza-disminuir-las-ventas\/","title":{"rendered":"Se paso la mitad del mes y comienza disminuir las ventas"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"405\" data-attachment-id=\"16122\" data-permalink=\"http:\/\/lahoradelcampo.com.uy\/site\/el-sul-presento-los-resultados-y-propuestas-para-mejorar-el-rubro-ovino\/granjaa\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/11\/Granjaa.jpg?fit=880%2C440\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Granjaa\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/11\/Granjaa.jpg?fit=810%2C405\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/11\/Granjaa.jpg?resize=810%2C405\" alt=\"\" class=\"wp-image-16122\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/11\/Granjaa.jpg?w=880 880w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/11\/Granjaa.jpg?resize=300%2C150 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/11\/Granjaa.jpg?resize=768%2C384 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/11\/Granjaa.jpg?resize=820%2C410 820w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"27820\" data-permalink=\"http:\/\/lahoradelcampo.com.uy\/site\/se-paso-la-mitad-del-mes-y-comienza-disminuir-las-ventas\/preciosgranja\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/02\/preciosgranja.jpg?fit=286%2C634\" data-orig-size=\"286,634\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"preciosgranja\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/02\/preciosgranja.jpg?fit=286%2C634\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/02\/preciosgranja.jpg?resize=211%2C468\" alt=\"\" class=\"wp-image-27820\" width=\"211\" height=\"468\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/02\/preciosgranja.jpg?w=286 286w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2021\/02\/preciosgranja.jpg?resize=135%2C300 135w\" sizes=\"auto, (max-width: 211px) 100vw, 211px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El pasar la mitad del mes y comenzar la \u00faltima quincena, conlleva a que la comercializaci\u00f3n en el Mercado Modelo, en la capital del pa\u00eds comience a disminuir. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El relevamiento realizado en la jornada de ayer en el mercado mayorista en la capital del pa\u00eds marc\u00f3 una actividad medianamente \u00e1gil, concentr\u00e1ndose la actividad en las primeras horas de la ma\u00f1ana. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las precipitaciones tambi\u00e9n afectaron la calidad de algunos productos que se pusieron a la venta en el mercado esta semana, principalmente en algunos grupos de hortalizas de hoja y de fruto, que se producen a nivel de campo. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este escenario se registraron aumentos en los valores de: bonitos, papas, frutilla, lim\u00f3n, cebolla de Verdeo, coliflor, espinaca, lechugas, choclo, y rabanito. En contrapartida se registraron descensos en morrones Amarillo y Rojo, tomate Perita y Cherry, pera, manzana Gala y uva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:right\"><strong>Salto, 19 de febrero de 2021<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasar la mitad del mes y comenzar la \u00faltima quincena, conlleva a que la comercializaci\u00f3n en el Mercado Modelo, en la capital del pa\u00eds comience a disminuir. El relevamiento [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":16122,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,9],"tags":[],"class_list":["post-27818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-granja"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/11\/Granjaa.jpg?fit=880%2C440","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-7eG","jetpack-related-posts":[{"id":20904,"url":"http:\/\/lahoradelcampo.com.uy\/site\/el-desempleo-crecio-un-19-en-el-sector-rural-durante-2019\/","url_meta":{"origin":27818,"position":0},"title":"El desempleo creci\u00f3 un 19%  en el sector rural durante 2019","author":"La Hora del Campo","date":"15 junio, 2020","format":false,"excerpt":"La din\u00e1mica de la pandemia del COVID-19 gener\u00f3 a nivel mundial una combinaci\u00f3n de shocks externos e internos de oferta y demanda, que los principales organismos internacionales estiman ser\u00e1 la causa de la mayor crisis econ\u00f3mica y social del mundo y de Am\u00e9rica Latina en d\u00e9cadas, con efectos muy negativos\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/trabajadores-rurales.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/trabajadores-rurales.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/trabajadores-rurales.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/trabajadores-rurales.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":18464,"url":"http:\/\/lahoradelcampo.com.uy\/site\/mercado-lanero-paralizado-y-con-plantas-sin-actividad\/","url_meta":{"origin":27818,"position":1},"title":"Mercado lanero paralizado y con plantas sin actividad","author":"La Hora del Campo","date":"27 marzo, 2020","format":false,"excerpt":"La ca\u00edda acumulada en las \u00faltimas semanas a nivel internacional, a pesar de la suba de esta semana, sumada a la problem\u00e1tica del Covid-19 en nuestro pa\u00eds, ha llevado a un mercado lanero interno pr\u00e1cticamente paralizado en su totalidad. Si bien existen algunas consultas por parte de los productores a\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Lanas-2.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Lanas-2.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Lanas-2.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/10\/Lanas-2.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":4691,"url":"http:\/\/lahoradelcampo.com.uy\/site\/cae-la-oferta-de-frutilla-en-el-mercado-modelo\/","url_meta":{"origin":27818,"position":2},"title":"Cae la oferta de frutilla en el Mercado Modelo","author":"La Hora del Campo","date":"6 diciembre, 2017","format":false,"excerpt":"La pasada semana se verificaron importantes ingresos de frutilla en el Mercado Modelo, tanto de cultivos del sur como del norte del pa\u00eds. Este escenario presion\u00f3 los precios a la baja con respecto a las semanas previas, en particular sobre la segunda mitad de la semana. Las mayores reducciones de\u2026","rel":"","context":"En \u00abGranja\u00bb","block_context":{"text":"Granja","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/granja\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/Frutilla.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/Frutilla.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/Frutilla.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/Frutilla.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":19802,"url":"http:\/\/lahoradelcampo.com.uy\/site\/mercado-lanero-uruguayo-sigue-sin-operativa-2\/","url_meta":{"origin":27818,"position":3},"title":"Mercado lanero uruguayo sigue sin operativa","author":"La Hora del Campo","date":"15 mayo, 2020","format":false,"excerpt":"Hablar del mercado lanero interno, es hablar de tener paciencia y esperar. El mercado est\u00e1 paralizado hace varias semanas y desde el exterior, con China operando en el mercado australiano y los dem\u00e1s demandantes de la fibra sin actividad debido a la pandemia Covid-19, no se tiene una demanda que\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/LANA-UY.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/LANA-UY.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/LANA-UY.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/05\/LANA-UY.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":40493,"url":"http:\/\/lahoradelcampo.com.uy\/site\/el-mercado-granjero-mantuvo-la-baja-actividad-comun-del-fin-de-mes\/","url_meta":{"origin":27818,"position":4},"title":"El mercado granjero mantuvo la baja actividad, com\u00fan del fin de mes","author":"La Hora del Campo","date":"2 abril, 2022","format":false,"excerpt":"La operativa comercial en la Unidad Agroalimentaria Metropolitana (UAM) mantuvo la baja agilidad en los negocios, propio del final del mes, pero que se ha visto m\u00e1s extendida de lo normal, en parte por el incremento de los valores en varios productos. En este contexto el retiro de mercader\u00eda se\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/10\/UAM-granja.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/10\/UAM-granja.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/10\/UAM-granja.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/10\/UAM-granja.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":47631,"url":"http:\/\/lahoradelcampo.com.uy\/site\/la-primera-mitad-de-la-zafra-lanera-22-23-cerro-con-el-ime-en-us-909\/","url_meta":{"origin":27818,"position":5},"title":"La primera mitad de la zafra lanera 22-23 cerr\u00f3 con el IME en US$ 9,09","author":"La Hora del Campo","date":"17 diciembre, 2022","format":false,"excerpt":"El pasado jueves 15 de diciembre cerr\u00f3 la primera mitad de la zafra lanera 22-23, con un Indicador de Mercados del Este (IME) en US$ 9,09 por kilogramo base limpia. Esta referencia es un 7,9% inferior al cierre de la zafra pasada, el 29 de junio, sin embargo este cierre\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/06\/lanas-australia.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/06\/lanas-australia.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/06\/lanas-australia.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/06\/lanas-australia.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/27818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=27818"}],"version-history":[{"count":1,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/27818\/revisions"}],"predecessor-version":[{"id":27822,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/27818\/revisions\/27822"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/16122"}],"wp:attachment":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=27818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=27818"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=27818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}