{"id":27438,"date":"2021-02-08T05:26:44","date_gmt":"2021-02-08T08:26:44","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=27438"},"modified":"2021-02-07T11:18:36","modified_gmt":"2021-02-07T14:18:36","slug":"inavi-lleva-adelante-el-primer-censo-nacional-de-enoturismo","status":"publish","type":"post","link":"http:\/\/lahoradelcampo.com.uy\/site\/inavi-lleva-adelante-el-primer-censo-nacional-de-enoturismo\/","title":{"rendered":"Inavi lleva adelante el primer censo nacional de enoturismo"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"405\" data-attachment-id=\"9879\" data-permalink=\"http:\/\/lahoradelcampo.com.uy\/site\/produccion-mundial-de-vino-es-casi-record\/vinos\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Vinos.jpg?fit=880%2C440\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Vinos\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Vinos.jpg?fit=810%2C405\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Vinos.jpg?resize=810%2C405\" alt=\"\" class=\"wp-image-9879\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Vinos.jpg?w=880 880w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Vinos.jpg?resize=300%2C150 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Vinos.jpg?resize=768%2C384 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Vinos.jpg?resize=820%2C410 820w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Con el objetivo de contar con informaci\u00f3n de primera mano sobre todas las propuestas de enotur\u00edsticas que existen en el pa\u00eds, INAVI est\u00e1 llevando adelante el Primer Censo Nacional de Bodegas y Vi\u00f1edos Tur\u00edsticos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa surge de un relevamiento desarrollado junto al Ministerio de Turismo y llevado a consulta a los referentes de los establecimientos vitivin\u00edcolas tur\u00edsticos durante las reuniones regionales efectuadas a partir de agosto del pasado a\u00f1o. Su importancia es crucial para la promoci\u00f3n y difusi\u00f3n del enoturismo a nivel nacional e internacional. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la primer quincena de febrero se estar\u00e1n recibiendo las respuestas para su posterior evaluaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"text-align:right\"><strong>Salto, 8 de febrero de 2021<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el objetivo de contar con informaci\u00f3n de primera mano sobre todas las propuestas de enotur\u00edsticas que existen en el pa\u00eds, INAVI est\u00e1 llevando adelante el Primer Censo Nacional de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":9879,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,9],"tags":[],"class_list":["post-27438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-granja"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Vinos.jpg?fit=880%2C440","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-78y","jetpack-related-posts":[{"id":25330,"url":"http:\/\/lahoradelcampo.com.uy\/site\/el-proximo-domingo-se-celebra-el-dia-internacional-del-enoturismo\/","url_meta":{"origin":27438,"position":0},"title":"El pr\u00f3ximo domingo se celebra el d\u00eda internacional del enoturismo","author":"La Hora del Campo","date":"6 noviembre, 2020","format":false,"excerpt":"El pr\u00f3ximo domingo 8 de noviembre se celebra el D\u00eda Internacional del Enoturismo, que como es tradicional se celebra todos los segundos domingos del d\u00e9cimo primer mes del a\u00f1o. Y esta seguramente, ser\u00e1 la celebraci\u00f3n m\u00e1s at\u00edpica en su historia, debido a las restricciones de movilidad y protocolos que se\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/11\/EnoturismoINAVI.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/11\/EnoturismoINAVI.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/11\/EnoturismoINAVI.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/11\/EnoturismoINAVI.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":53641,"url":"http:\/\/lahoradelcampo.com.uy\/site\/sector-vinicola-nacional-brillo-en-la-cumbre-mundial-de-enoturismo\/","url_meta":{"origin":27438,"position":1},"title":"Sector vin\u00edcola nacional brillo en la Cumbre Mundial de Enoturismo","author":"La Hora del Campo","date":"2 abril, 2024","format":false,"excerpt":"En un evento que reuni\u00f3 a los l\u00edderes m\u00e1s destacados de la vitivinicultura mundial, Punta del Este se convirti\u00f3 en el epicentro de la innovaci\u00f3n y la excelencia en el enoturismo. Del 19 al 21 de marzo, la Primera Cumbre Global de Enoturismo Responsable, organizada por la Organizaci\u00f3n Mundial de\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/03\/INAVI-EnoturismoPdelE.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/03\/INAVI-EnoturismoPdelE.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/03\/INAVI-EnoturismoPdelE.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/03\/INAVI-EnoturismoPdelE.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":18008,"url":"http:\/\/lahoradelcampo.com.uy\/site\/el-21-de-marzo-se-realiza-la-fiesta-nacional-de-la-vendimia-en-uruguay\/","url_meta":{"origin":27438,"position":2},"title":"El 21 de marzo se realiza la fiesta nacional de la vendimia en Uruguay","author":"La Hora del Campo","date":"13 marzo, 2020","format":false,"excerpt":"Bajo la consigna Descubr\u00ed la Vendimia, el Instituto Nacional de Vitivinicultura (INAVI) y la Intendencia Municipal de Montevideo, con el apoyo del Ministerio de Turismo y Los Caminos del Vino, presentaron las actividades de la Vendimia 2020 y anunciaron la Fiesta Nacional de la Vendimia, que se realizar\u00e1 el s\u00e1bado\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/uva.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/uva.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/uva.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/uva.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":52944,"url":"http:\/\/lahoradelcampo.com.uy\/site\/enoturismo-en-uruguay-genera-ingresos-deus-11-millones\/","url_meta":{"origin":27438,"position":3},"title":"Enoturismo en Uruguay genera ingresos deUS$ 11 millones","author":"La Hora del Campo","date":"30 octubre, 2023","format":false,"excerpt":"El Instituto Nacional de Vitivinicultura (INAVI) de Uruguay ha presentado los resultados de una encuesta sobre el impacto econ\u00f3mico del enoturismo en el pa\u00eds, llevada a cabo por la firma Opci\u00f3n Consultores. El informe destaca la creciente importancia del enoturismo en Uruguay, una tendencia que ha experimentado un crecimiento constante\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/10\/INAVI-enoturismo.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/10\/INAVI-enoturismo.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/10\/INAVI-enoturismo.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/10\/INAVI-enoturismo.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":51005,"url":"http:\/\/lahoradelcampo.com.uy\/site\/el-enoturismo-descubriendo-los-tesoros-vinicolas-del-pais\/","url_meta":{"origin":27438,"position":4},"title":"El enoturismo: Descubriendo los Tesoros Vin\u00edcolas del Pa\u00eds","author":"La Hora del Campo","date":"2 junio, 2023","format":false,"excerpt":"La Mag. Mar\u00eda Paula Vila, Jefe de Enoturismo del Instituto Nacional de Vitivinicultura (INAVI), estuvo recientemente por Salto, en el marco de la Semana de Harriague. El Mercado 18, fue el punto de encuentro para amantes del vino y curiosos que buscaron conocer m\u00e1s de la historia de Harriague, y\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/06\/INAVI_MariaPaulaVila.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/06\/INAVI_MariaPaulaVila.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/06\/INAVI_MariaPaulaVila.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/06\/INAVI_MariaPaulaVila.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":30754,"url":"http:\/\/lahoradelcampo.com.uy\/site\/nueva-directiva-de-la-asociacion-de-turismo-enologico-prepara-varias-actividades\/","url_meta":{"origin":27438,"position":5},"title":"Nueva directiva de la Asociaci\u00f3n de Turismo Enol\u00f3gico prepara varias actividades","author":"La Hora del Campo","date":"1 junio, 2021","format":false,"excerpt":"La nueva directiva de la Asociaci\u00f3n de Turismo Enol\u00f3gico del Uruguay (ATEU) est\u00e1 presidida por Virginia Moreira, directora de la Bodega Stagnari. En los \u00faltimos d\u00edas, la gremial se reuni\u00f3 con el presidente del Instituto Nacional de Vitivinicultura (INAVI) y el equipo de enoturismo del instituto. Durante el encuentro se\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/uva.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/uva.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/uva.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/uva.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/27438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=27438"}],"version-history":[{"count":1,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/27438\/revisions"}],"predecessor-version":[{"id":27440,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/27438\/revisions\/27440"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/9879"}],"wp:attachment":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=27438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=27438"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=27438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}