{"id":18130,"date":"2020-03-19T06:45:46","date_gmt":"2020-03-19T09:45:46","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=18130"},"modified":"2020-03-19T06:49:14","modified_gmt":"2020-03-19T09:49:14","slug":"carne-ovina-no-adelanta-abrir-demasiado-los-mercados-en-la-medida-que-no-los-podes-atender","status":"publish","type":"post","link":"http:\/\/lahoradelcampo.com.uy\/site\/carne-ovina-no-adelanta-abrir-demasiado-los-mercados-en-la-medida-que-no-los-podes-atender\/","title":{"rendered":"Carne ovina: \u00abNo adelanta abrir demasiado los mercados en la medida que no los podes atender\u00bb"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"405\" data-attachment-id=\"18132\" data-permalink=\"http:\/\/lahoradelcampo.com.uy\/site\/carne-ovina-no-adelanta-abrir-demasiado-los-mercados-en-la-medida-que-no-los-podes-atender\/fernando-mattos\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/Fernando-Mattos.jpg?fit=880%2C440\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Fernando Mattos\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/Fernando-Mattos.jpg?fit=810%2C405\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/Fernando-Mattos.jpg?resize=810%2C405\" alt=\"\" class=\"wp-image-18132\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/Fernando-Mattos.jpg?w=880 880w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/Fernando-Mattos.jpg?resize=300%2C150 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/Fernando-Mattos.jpg?resize=768%2C384 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/Fernando-Mattos.jpg?resize=820%2C410 820w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 va primero? \u00bfEl huevo o la gallina? O si lo preguntamos en t\u00e9rminos de reclamo de los productores por mejores valores e incentivos para la producci\u00f3n ovina, que va primero \u00bflos mercados o el aumento de la oferta?, si bien siempre se ha reclamado una mayor producci\u00f3n y desestacionalizarla, los compartimentos es un claro ejemplo que la mejora en los valores por el producto final, es decir la carne, ha generado una r\u00e1pida respuesta del sector productivo y un aumento de la producci\u00f3n. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pasado 11 de marzo, el Presidente de la Rep\u00fablica, Dr. Luis Lacalle Pou, firm\u00f3 la resoluci\u00f3n que instaur\u00f3 oficialmente como Presidente del Instituto Nacional de Carnes al Ing. Agr. Fernando Mattos. El novel jerarca dijo que \u00abno adelanta abrir demasiado los mercados en la medida que no los podes atender\u00bb y explic\u00f3 que eso podr\u00eda ser \u00abun factor contraproducente\u00bb para las aspiraciones de la producci\u00f3n ovina. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reconoci\u00f3 que el rubro \u00abes relevante\u00bb para el pa\u00eds y que \u00abhay que apoyar desde nuestra posici\u00f3n\u00bb, pero advirti\u00f3 que se debe tener en cuenta que \u00abla gran limitante que tiene el Uruguay es el bajo volumen, la baja oferta por el bajo stock\u00bb. En este sentido indic\u00f3 que se debe estimular la producci\u00f3n y dijo creer que \u00abvamos en el camino correcto\u00bb haciendo alusi\u00f3n principalmente a las medidas adoptadas en temas de seguridad. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mattos se\u00f1al\u00f3 que \u00ablas medidas que est\u00e1 tomando el Ministerio del Interior dan garant\u00edas desde el punto de vista de combatir el abigeato\u00bb, si bien reconoci\u00f3 que a\u00fan est\u00e1 \u00abpendiente\u00bb la problem\u00e1tica ocasionada por las jaur\u00edas de perros en el interior remarc\u00f3 la estrategia prevista por el MGAP para \u00abel combate al gusano barrenador, la bichera\u00bb. Desde su punto de vista son pasos que permitir\u00e1n avanzar en estimular a la producci\u00f3n ovina. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El futuro presidente del instituto de promoci\u00f3n de nuestras carnes dijo: \u00abnosotros vamos a contribuir desde el punto de vista de la promoci\u00f3n en INAC sea para el mercado interno como para la exportaci\u00f3n\u00bb. Sin embargo remarc\u00f3 que el productor debe saber que \u00abnecesitas una masa cr\u00edtica m\u00e1s importante para poder ofrecer en el mercado una continuidad de abastecimiento y no quedar restringido al volumen que puede hoy ofrecer el Uruguay\u00bb.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fernando Mattos dijo que se debe avanzar \u00abpaso a paso\u00bb y que \u00abno adelanta abrir demasiado los mercados en la medida que no los pod\u00e9s atender, porque termina siendo un factor contraproducente\u00bb. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 va primero? \u00bfEl huevo o la gallina? O si lo preguntamos en t\u00e9rminos de reclamo de los productores por mejores valores e incentivos para la producci\u00f3n ovina, que va [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":18132,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,5],"tags":[171,71],"class_list":["post-18130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-ganaderia","tag-carne-ovina","tag-inac"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/Fernando-Mattos.jpg?fit=880%2C440","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-4Iq","jetpack-related-posts":[{"id":14315,"url":"http:\/\/lahoradelcampo.com.uy\/site\/japon-analiza-ingreso-de-carne-ovina-con-hueso-desde-los-compartimentos\/","url_meta":{"origin":18130,"position":0},"title":"Jap\u00f3n analiza ingreso de carne ovina con hueso desde los compartimentos","author":"La Hora del Campo","date":"14 septiembre, 2019","format":false,"excerpt":"Uruguay avanza en la posibilidad de incrementar sus negocios con Jap\u00f3n luego de la apertura de este mercado en el mes de febrero para la carne vacuna, luego de a\u00f1os de negociaci\u00f3n. El Presidente del Instituto Nacional de Carnes, Ing. Agr. Federico Stanham, dijo que posteriormente a esta habilitaci\u00f3n para\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Stanham.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Stanham.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Stanham.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/05\/Stanham.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":53079,"url":"http:\/\/lahoradelcampo.com.uy\/site\/no-hay-una-estrategia-pais-para-el-rubro-ovino-ante-una-muy-clara-demanda-internacional\/","url_meta":{"origin":18130,"position":1},"title":"\u00abNo hay una estrategia pa\u00eds\u00bb para el rubro ovino, ante \u00abuna muy clara demanda internacional\u00bb","author":"La Hora del Campo","date":"9 noviembre, 2023","format":false,"excerpt":"La producci\u00f3n de carne ovina de alta calidad es posible y es rentable, algo m\u00e1s que comprobado en el pa\u00eds, con mayor o menor nivel de tecnolog\u00eda, con razas m\u00e1s o menos prol\u00edficas. Sin embargo la situaci\u00f3n actual del rubro ovino, principalmente en los mercados de la carne y la\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/11\/Alejandro-Michelena.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/11\/Alejandro-Michelena.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/11\/Alejandro-Michelena.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/11\/Alejandro-Michelena.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":22780,"url":"http:\/\/lahoradelcampo.com.uy\/site\/sul-inia-e-inac-trabajan-para-mejorar-la-competitividad-internacional-de-la-carne-ovina\/","url_meta":{"origin":18130,"position":2},"title":"SUL, INIA e INAC trabajan para mejorar la competitividad internacional de la carne ovina","author":"La Hora del Campo","date":"18 agosto, 2020","format":false,"excerpt":"El Secretariado Uruguayo de la Lana (SUL), conjuntamente con el Instituto Nacional de Investigaci\u00f3n Agropecuaria (INIA) y el Instituto Nacional de Carnes (INAC) llevan adelante el convenio de cooperaci\u00f3n \u201cInvestigaci\u00f3n, transferencia de tecnolog\u00eda e innovaci\u00f3n para la mejora de la competitividad internacional de la cadena c\u00e1rnica ovina del Uruguay\u201d. En\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Ovinos.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Ovinos.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Ovinos.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Ovinos.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":54981,"url":"http:\/\/lahoradelcampo.com.uy\/site\/el-sul-carece-de-un-proyecto-parala-carne-ovina-inac-apuesta-a-brasil\/","url_meta":{"origin":18130,"position":3},"title":"El SUL carece de un proyecto para la carne ovina, INAC apuesta a Brasil","author":"La Hora del Campo","date":"28 octubre, 2024","format":false,"excerpt":"El presidente del Instituto Nacional de Carnes (INAC), Conrado Ferber, dijo a CAMBIO que se reuni\u00f3 con el Secretariado Uruguayo de la Lana (SUL) al asumir el cargo y solicit\u00f3 un proyecto para el desarrollo de la carne ovina, \"lamentablemente, no lo ten\u00edan\", y casi al final de su administraci\u00f3n\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/10\/ConradoFerbera.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/10\/ConradoFerbera.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/10\/ConradoFerbera.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/10\/ConradoFerbera.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":963,"url":"http:\/\/lahoradelcampo.com.uy\/site\/la-apertura-de-e-e-u-u-nos-permitira-abrir-otros-mercados\/","url_meta":{"origin":18130,"position":4},"title":"La apertura de E.E.U.U. nos permitir\u00e1 abrir otros mercados","author":"La Hora del Campo","date":"11 septiembre, 2017","format":false,"excerpt":"El Presidente del Secretariado Uruguayo de la Lana, Ing. Agr. Alejandro Gambetta, dijo que la apertura del mercado de Estados Unidos para la carne ovina con hueso, permitir\u00e1 a Uruguay avanzar en M\u00e9xico, Canad\u00e1, Europa e Israel, para abrir estos mercados para la carne ovina uruguaya. Gambetta record\u00f3 que est\u00e1\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Alejandro-Gambetta-Pte-SUL.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Alejandro-Gambetta-Pte-SUL.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Alejandro-Gambetta-Pte-SUL.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/09\/Alejandro-Gambetta-Pte-SUL.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":54046,"url":"http:\/\/lahoradelcampo.com.uy\/site\/sul-destaco-el-crecimiento-de-las-exportaciones-de-carne-ovina-a-medio-oriente\/","url_meta":{"origin":18130,"position":5},"title":"SUL destac\u00f3 el crecimiento de las exportaciones de carne ovina a Medio Oriente","author":"La Hora del Campo","date":"26 julio, 2024","format":false,"excerpt":"En la reciente Jornada anual en el Centro de Investigaci\u00f3n y Experimentaci\u00f3n Dr. Alejandro Gallinal (CIEDAG) en Cerro Colorado, Florida, el Secretariado Uruguayo de la Lana (SUL) centr\u00f3 sus esfuerzos en la \"Producci\u00f3n de carne ovina y lanas finas en sistemas mixtos\". En este evento, la Doctora Antonella Riani, t\u00e9cnica\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/07\/SUL-Antonella.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/07\/SUL-Antonella.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/07\/SUL-Antonella.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2024\/07\/SUL-Antonella.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/18130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=18130"}],"version-history":[{"count":1,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/18130\/revisions"}],"predecessor-version":[{"id":18134,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/18130\/revisions\/18134"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/18132"}],"wp:attachment":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=18130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=18130"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=18130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}