{"id":17872,"date":"2020-03-10T06:03:39","date_gmt":"2020-03-10T09:03:39","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=17872"},"modified":"2020-03-10T17:20:20","modified_gmt":"2020-03-10T20:20:20","slug":"base-de-us-330-por-kilo-en-la-primera-etapa-del-operativo-cordero-pesado","status":"publish","type":"post","link":"http:\/\/lahoradelcampo.com.uy\/site\/base-de-us-330-por-kilo-en-la-primera-etapa-del-operativo-cordero-pesado\/","title":{"rendered":"Base de US$ 3,30 por kilo en la primera etapa del Operativo Cordero Pesado"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"405\" data-attachment-id=\"17874\" data-permalink=\"http:\/\/lahoradelcampo.com.uy\/site\/base-de-us-330-por-kilo-en-la-primera-etapa-del-operativo-cordero-pesado\/papera\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/papera.jpg?fit=880%2C440\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"papera\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/papera.jpg?fit=810%2C405\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/papera.jpg?resize=810%2C405\" alt=\"\" class=\"wp-image-17874\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/papera.jpg?w=880 880w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/papera.jpg?resize=300%2C150 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/papera.jpg?resize=768%2C384 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/papera.jpg?resize=820%2C410 820w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Central Lanera Uruguaya (CLU) ha puesto en marcha el Operativo Cordero Pesado 2020, que al igual que el a\u00f1o pasado tendr\u00e1 tres per\u00edodos de precios: dos puntuales y uno a promedio. El acuerdo fue alcanzado, con las dos plantas frigor\u00edficas con las que ha venido trabajando la cooperativa. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juan Paperan, representante en Salto de la cooperativa en Calsal, dijo que \u00abes un operativo que se mantiene en sus caracter\u00edsticas principales como el apoyo financiero para los productores que participan y comprometen sus corderos, lo que tiene que ver con sobreprecios, el seguro por mortandad pos esquila y la seguridad de carga en base a los contratos firmados entre Central Lanera y el productor, como as\u00ed tambi\u00e9n con la industria\u00bb. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los precios que han sido acordados como base, o seguro para el productor ante cualquier baja imprevista de los precios, son US$ 3,30 para el per\u00edodo enero-marzo a precio puntual de venta y en el mismo sistema para el per\u00edodo abril-julio se plante\u00f3 un precio de US$ 3,20. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso del per\u00edodo que va desde agosto a noviembre, donde los productores remiten sus corderos a precio promedio, la base estipulada en el acuerdo es de US$ 3,10. En todos los periodos los valores son acordados en una base de carcasas de 13 a 24 kilogramos en segunda balanza. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para los borregos, los precios se ubican cinco centavos menos para cada periodo. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paperan dijo que si bien los valores se encuentran por debajo de lo acordado el a\u00f1o pasado, \u00abcontin\u00faan siendo hist\u00f3ricamente muy buenos y normalmente la zafra a medida que va transcurriendo, los precios tienden a subir hacia setiembre-octubre\u00bb, por lo que reafirm\u00f3 que los precios base son \u00abmuy buenos\u00bb como respaldo para el productor a la hora de hacer las cuentas y planificar la producci\u00f3n de este a\u00f1o.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El operativo volver\u00e1 a contar con US$ 0,10 de sobreprecio para las carcasas de razas carniceras hasta el 30 de septiembre, recordemos que el a\u00f1o pasado este incentivo fue de cinco centavos. Para aquellos que cumplen con sus inscripciones en el per\u00edodo de agosto a noviembre contar\u00e1n con 5 centavos de sobreprecio y quienes adelanten su producci\u00f3n y entreguen los corderos a faena en octubre, tendr\u00e1n un 10 centavos de sobreprecio. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paperan dijo que en el caso de los compartimentos ovinos que trabajan con la cooperativa, \u00abest\u00e1n saliendo las condiciones del negocio, existe alguna modificaci\u00f3n respecto al a\u00f1o pasado, pero b\u00e1sicamente se mantiene el sobreprecio del 25% sobre el valor de INAC\u00bb. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El promotor de Central Lanera en la cooperativa salte\u00f1a resalt\u00f3 \u00abla asistencia financiera\u00bb que dispone la instituci\u00f3n para sus productores remitentes. \u00abEn estos momentos de mucha turbulencia a nivel comercial y de los exportadores, a nivel financiero, consideramos que la asistencia financiera es un pilar importante por lo que ya la estamos poniendo a disposici\u00f3n para los productores con adelantos de hasta US$ 35 por animal\u00bb. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aquellos productores que hasta el momento comercializaron sus productos a trav\u00e9s de otro sistema y quieren probar el operativo se han mostrado reticentes a consignar la lana conjuntamente con los corderos. Juan Paperan explic\u00f3 que \u00abexiste una grilla para los adelantos en funci\u00f3n de cuanto producto est\u00e1 comprometiendo al sistema de Central Lanera, por eso es hasta US$ 35\u00bb. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abClaramente aquel productor que tradicionalmente embarca toda la lana, los corderos, que ha cumplido en otros operativos tiene un adelanto superior y en la medida que, por ejemplo, manda solo los corderos tiene otro tipo de adelanto\u00bb se\u00f1al\u00f3 el promotor de CLU. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Central Lanera Uruguaya (CLU) ha puesto en marcha el Operativo Cordero Pesado 2020, que al igual que el a\u00f1o pasado tendr\u00e1 tres per\u00edodos de precios: dos puntuales y uno a [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":17874,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,5],"tags":[],"class_list":["post-17872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-ganaderia"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/papera.jpg?fit=880%2C440","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-4Eg","jetpack-related-posts":[{"id":37773,"url":"http:\/\/lahoradelcampo.com.uy\/site\/clu-liquida-a-hoy-el-operativo-cordero-pesado-con-un-maximo-de-us-465\/","url_meta":{"origin":17872,"position":0},"title":"CLU liquida el Operativo Cordero Pesado con un m\u00e1ximo de US$ 4,65","author":"La Hora del Campo","date":"22 diciembre, 2021","format":false,"excerpt":"Hoy, mi\u00e9rcoles 22 de diciembre, Central Lanera Uruguaya est\u00e1 realizando el cierre del Operativo Ovinos 2021, pagando a 450 productores de todo el pa\u00eds que embarcaron animales entre agosto y diciembre. Los productores remitentes de corderos pesados a trav\u00e9s del sistema cooperativo recibieron pagos a cuenta del precio promedio final\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Corderos-CLU.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Corderos-CLU.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Corderos-CLU.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Corderos-CLU.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":38461,"url":"http:\/\/lahoradelcampo.com.uy\/site\/clu-lanzo-el-operativo-ovinos-2022-con-base-de-us-400-hasta-marzo\/","url_meta":{"origin":17872,"position":1},"title":"CLU lanz\u00f3 el operativo ovinos 2022, con base de US$ 4,00 hasta marzo","author":"La Hora del Campo","date":"21 enero, 2022","format":false,"excerpt":"La cooperativa Central Lanera Uruguaya en este 2022 cumple 26 a\u00f1os del Operativo Ovinos. Luego del incremento en el volumen de corderos faenados el a\u00f1o pasado, se lanza una nueva campa\u00f1a con sus particulares beneficios y certezas que brinda en la faena. La actual campa\u00f1a de inscripciones comenz\u00f3 en la\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/01\/CLU-corderos.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/01\/CLU-corderos.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/01\/CLU-corderos.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/01\/CLU-corderos.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":5207,"url":"http:\/\/lahoradelcampo.com.uy\/site\/clu-realizo-ayer-el-cierre-del-operativo-ovinos-2017\/","url_meta":{"origin":17872,"position":2},"title":"CLU realiz\u00f3 ayer el cierre del Operativo Ovinos 2017","author":"La Hora del Campo","date":"28 diciembre, 2017","format":false,"excerpt":"Central Lanera Uruguaya (CLU) realiz\u00f3 ayer el cierre del Operativo Corderos Pesados 2017, fijando los precios definitivos y pagando a unos 330 productores de todo el pa\u00eds que embarcaron animales entre agosto y los primeros d\u00edas de diciembre. Los productores remitentes de corderos pesados a trav\u00e9s del sistema cooperativo recibieron\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/CLU.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/CLU.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/CLU.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2017\/12\/CLU.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":9599,"url":"http:\/\/lahoradelcampo.com.uy\/site\/central-lanera-lanzo-su-operativo-corderos-2019-un-sobreprecio-asegurado-para-corderos-de-compartimentos\/","url_meta":{"origin":17872,"position":3},"title":"Central Lanera lanz\u00f3 su operativo corderos 2019 un sobreprecio asegurado para corderos de compartimentos","author":"La Hora del Campo","date":"5 abril, 2019","format":false,"excerpt":"La cooperativa Central Lanera Uruguaya lanz\u00f3 su operativo de corderos 2019, con una mayor apertura hacia todos los productores. \u201cNo s\u00f3lo los productores ganaderos pueden aprovechar las ventajas del operativo, sino, quienes tengan pasturas de calidad y est\u00e9n evaluando alternativas de uso, tanto en puentes verdes como en campos que\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Corderos-CLU.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Corderos-CLU.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Corderos-CLU.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Corderos-CLU.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":16748,"url":"http:\/\/lahoradelcampo.com.uy\/site\/ovejeros-alcanzaron-us-398-en-el-operativo-corderos-de-clu\/","url_meta":{"origin":17872,"position":4},"title":"Ovejeros alcanzaron US$ 3,98 en el operativo corderos de CLU","author":"La Hora del Campo","date":"7 enero, 2020","format":false,"excerpt":"El pasado 23 de diciembre, Central Lanera Uruguaya (CLU), realiz\u00f3 el cierre del operativo Corderos Pesados 2019, alcanzando valores de punta de US$ 3,98 para aquellos productores que cumplieron con todos los puntos planteados en el acuerdo con la cooperativa. El operativo el a\u00f1o pasado comenz\u00f3 con un precio base\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Corderos-CLU.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Corderos-CLU.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Corderos-CLU.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Corderos-CLU.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":26410,"url":"http:\/\/lahoradelcampo.com.uy\/site\/clu-cerro-el-operativo-ovinos-alcanzando-maximos-de-us-340\/","url_meta":{"origin":17872,"position":5},"title":"CLU cerr\u00f3 el operativo ovinos alcanzando m\u00e1ximos de US$ 3,40","author":"La Hora del Campo","date":"29 diciembre, 2020","format":false,"excerpt":"La Cooperativa Central Lanera Uruguaya (CLU) cerr\u00f3 su operativo ovinos 2020, con la liquidaci\u00f3n a 450 productores que embarcaron sus corderos entre agosto y los primeros d\u00edas de diciembre de este a\u00f1o, alcanz\u00e1ndose valores de punta de US$ 3,40 para las mejores carcasas y con todos los beneficios. El operativo,\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Corderos-CLU.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Corderos-CLU.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Corderos-CLU.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2019\/04\/Corderos-CLU.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/17872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=17872"}],"version-history":[{"count":2,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/17872\/revisions"}],"predecessor-version":[{"id":17916,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/17872\/revisions\/17916"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/17874"}],"wp:attachment":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=17872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=17872"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=17872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}