{"id":17862,"date":"2020-03-09T06:52:37","date_gmt":"2020-03-09T09:52:37","guid":{"rendered":"http:\/\/lahoradelcampo.com.uy\/site\/?p=17862"},"modified":"2020-03-09T06:52:49","modified_gmt":"2020-03-09T09:52:49","slug":"buena-demanda-y-valores-para-el-poll-dorset-y-el-merino-en-la-agropecuaria-de-salto","status":"publish","type":"post","link":"http:\/\/lahoradelcampo.com.uy\/site\/buena-demanda-y-valores-para-el-poll-dorset-y-el-merino-en-la-agropecuaria-de-salto\/","title":{"rendered":"Buena demanda y valores para el Poll Dorset y el Merino en la Agropecuaria de Salto"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"405\" data-attachment-id=\"17864\" data-permalink=\"http:\/\/lahoradelcampo.com.uy\/site\/buena-demanda-y-valores-para-el-poll-dorset-y-el-merino-en-la-agropecuaria-de-salto\/los-manantiales-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/los-manantiales.jpg?fit=880%2C440\" data-orig-size=\"880,440\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"los manantiales\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/los-manantiales.jpg?fit=810%2C405\" src=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/los-manantiales.jpg?resize=810%2C405\" alt=\"\" class=\"wp-image-17864\" srcset=\"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/los-manantiales.jpg?w=880 880w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/los-manantiales.jpg?resize=300%2C150 300w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/los-manantiales.jpg?resize=768%2C384 768w, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/los-manantiales.jpg?resize=820%2C410 820w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El escritorio Zambrano &amp; C\u00eda, concret\u00f3 el viernes pasado, el remate anual de las caba\u00f1as Los Manantiales de Sylvia Jones de P\u00e9rez e hijos, La Corona de Mirtha Jones de Azambuja e hijos y Caba\u00f1a Salto de Limitour Srl. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bajo el martillo de Gerardo Zambrano, las ventas comenzaron con el Poll Dorset de Caba\u00f1a Salto donde el primer lote de borregas PPC se comercializ\u00f3 en US$ 180 y luego se comercializaron 10 borregas de pedigree en US$ 500, al igual que 50 ovejas PPC que alcanzaron el mismo valor. En la propuesta de las hembras se ofert\u00f3 el 50% de una borrega de pedigree que vuelve a la caba\u00f1a y continuar\u00e1 all\u00ed su preparaci\u00f3n para las pistas y posteriormente en la producci\u00f3n, que se pag\u00f3 US$ 1.000.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los machos, se ofert\u00f3 un carnero padre, hijo de Ripa, que se comercializ\u00f3 en US$ 1.600, mientras que el Gran Campe\u00f3n del Prado se pag\u00f3 US$ 1.200. Los borregos de pedigree hicieron un promedio de US$ 417 y los PPC promediaron los US$ 482, mientras que 5 carneros PPC se pagaron US$ 500. El promedio general para los machos fue de US$ 564. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Dr. Eduardo Texeira, de caba\u00f1a Salto, manifest\u00f3 su conformidad con las ventas, tanto en machos como en hembras. El profesional agradeci\u00f3 a las dem\u00e1s caba\u00f1as merinistas por permitir la participaci\u00f3n de esta raza carnicera en las ventas. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso de Los Manantiales y La Corona, se comercializaron 273 hembras en US$ 113 de promedio, mientras que los 89 carneros se pagaron en US$ 703 de promedio. En el detalle, las borregas merinas de 2-4 dientes se pagaron US$ 153, las ovejas MO en US$ 129, las ovejas generales en US$ 109 y las corderas generales en US$ 95. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para los machos las referencias de valores fueron de US$ 2.162 para los carneros doble tatuaje, US$ 685 para los borrego MO y US$ 539 para los carneros MO. En el destaque de los machos, se pag\u00f3 un carnero padre destacado en US$ 3.400.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Dr. Juan Perez Jones, al finalizar las ventas, dijo que \u00abel remate tiene la mejor carne y la mejor lana, creo que en cruzamientos terminales y para carniceros el Poll Dorset y este en particular, es lo mejor del pa\u00eds\u00bb. En cuanto a las ventas del merino, \u00absi se puede pedir algo m\u00e1s, hubi\u00e9semos preferido mejores valores por los vientres, pero como se sabe la caba\u00f1a nunca pone base y lo que se vende el precio lo pone el mercado\u00bb. <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte Juan Martinicorena, en nombre de La Corona, agradeci\u00f3 a las dem\u00e1s caba\u00f1as por permitir el retorno de esta prestigiosa caba\u00f1a a las ventas nuevamente, y a los clientes que volvieron a confiar en sus productos presentados en la pista. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El escritorio Zambrano &amp; C\u00eda, concret\u00f3 el viernes pasado, el remate anual de las caba\u00f1as Los Manantiales de Sylvia Jones de P\u00e9rez e hijos, La Corona de Mirtha Jones de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":17864,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,5],"tags":[],"class_list":["post-17862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-ganaderia"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/03\/los-manantiales.jpg?fit=880%2C440","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p99IaT-4E6","jetpack-related-posts":[{"id":6129,"url":"http:\/\/lahoradelcampo.com.uy\/site\/promedio-de-us-765-para-limitour-y-us-531-para-los-manantiales-ayer-en-la-agropecuaria\/","url_meta":{"origin":17862,"position":0},"title":"Promedio de US$ 765 para Limitour y US$ 531  para Los Manantiales ayer en la agropecuaria","author":"La Hora del Campo","date":"10 marzo, 2018","format":false,"excerpt":"En un remate \u00e1gil a cargo del martillo de Gerardo Zambrano, de la firma Zambrano & C\u00eda, se realiz\u00f3 ayer las ventas de las caba\u00f1as Los Manantiales en Merino Australiano y Caba\u00f1a Salto en Poll Dorset, con el plus de clientes de Brasil y Colombia invirtiendo en la gen\u00e9tica carnicera\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/03\/los-manantiales.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/03\/los-manantiales.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/03\/los-manantiales.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2018\/03\/los-manantiales.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":23450,"url":"http:\/\/lahoradelcampo.com.uy\/site\/poll-dorset-san-rafael-gano-en-po-y-cabana-salto-en-el-pedigree\/","url_meta":{"origin":17862,"position":1},"title":"Poll Dorset: San Rafael gan\u00f3 en PO  y Caba\u00f1a Salto en el Pedigree","author":"La Hora del Campo","date":"13 septiembre, 2020","format":false,"excerpt":"El viernes comenzaron las calificaciones de las razas ovinas en el marco de la Expo Prado 2020. En esta oportunidad el primer turno de calificaci\u00f3n fue en las razas carniceras, donde participaron las caba\u00f1as salte\u00f1as, San Rafael y Caba\u00f1a Salto alcanzando Grandes Campeonatos. El productor sanducero, Eduardo Filliiol fue el\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/09\/SanRafaelPollDorset.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/09\/SanRafaelPollDorset.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/09\/SanRafaelPollDorset.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2020\/09\/SanRafaelPollDorset.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":46007,"url":"http:\/\/lahoradelcampo.com.uy\/site\/poll-dorset-san-rafael-en-el-po-y-cabana-salto-en-el-pedigree\/","url_meta":{"origin":17862,"position":2},"title":"Poll Dorset: San Rafael en el PO y Caba\u00f1a Salto en el pedigree","author":"La Hora del Campo","date":"1 octubre, 2022","format":false,"excerpt":"Con cuatro caba\u00f1as y nueve ejemplares, la pista n\u00famero tres de ovinos fue inaugurada por la raza Poll Dorset, que present\u00f3 una excelente muestra y tuvo como jurado al criador Francisco Donagaray, quien estuvo acompa\u00f1ado por la Sra. Ana Araujo. Al igual que en la Expo Prado de este a\u00f1o,\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/10\/ExpoSalto-Polldorset.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/10\/ExpoSalto-Polldorset.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/10\/ExpoSalto-Polldorset.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/10\/ExpoSalto-Polldorset.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":45457,"url":"http:\/\/lahoradelcampo.com.uy\/site\/cabana-salto-y-san-rafael-ganaron-las-pistas-del-poll-dorset\/","url_meta":{"origin":17862,"position":3},"title":"Caba\u00f1a Salto y San Rafael ganaron las pistas del Poll Dorset","author":"La Hora del Campo","date":"12 septiembre, 2022","format":false,"excerpt":"Las caba\u00f1as salte\u00f1as deleitaron con su gen\u00e9tica al jurado brasile\u00f1o, Ronaldo Carpes Da Costa, qui\u00e9n remarc\u00f3 la pureza racial y el volumen de carne de los animales que definieron los grandes campeonatos en la pista. \"Vi la raza muy bien posicionada, animales importantes y principalmente con mucha carne\", dijo el\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/09\/Prado-sanrafael.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/09\/Prado-sanrafael.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/09\/Prado-sanrafael.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/09\/Prado-sanrafael.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":48879,"url":"http:\/\/lahoradelcampo.com.uy\/site\/el-merino-australiano-de-los-manantiales-promedio-us-729\/","url_meta":{"origin":17862,"position":4},"title":"El merino australiano de  \u201cLos Manantiales\u201d promedi\u00f3 U$S 729","author":"La Hora del Campo","date":"27 febrero, 2023","format":false,"excerpt":"Con un buen mercado, fluidez y alto porcentaje de colocaci\u00f3n, se realiz\u00f3 el viernes por la noche en el local de la Agropecuaria de Salto, el 18\u00b0 remate anual del Merino Australiano de caba\u00f1a \u201cLos Manantiales de P\u00e9rez Jones. Tambi\u00e9n se colocaron Poll Dorset de caba\u00f1a \u201cSalto\u201d de Limitour, con\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/02\/Los-Manantiales.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/02\/Los-Manantiales.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/02\/Los-Manantiales.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2023\/02\/Los-Manantiales.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]},{"id":46413,"url":"http:\/\/lahoradelcampo.com.uy\/site\/cabana-salto-y-la-plazoleta-vendieron-el-100-de-la-oferta\/","url_meta":{"origin":17862,"position":5},"title":"Caba\u00f1a Salto y La Plazoleta vendieron el 100% de la oferta","author":"La Hora del Campo","date":"18 octubre, 2022","format":false,"excerpt":"En el predio de la Asociaci\u00f3n Agropecuaria de Salto, se realiz\u00f3 el remate anual de \u201cCaba\u00f1a Salto\u201d del Joint Venture Limitour, con el martillo de la firma Zambrano & C\u00eda. Como caba\u00f1a invitada particip\u00f3 la caba\u00f1a \u201cLa Plazoleta\u201d de Daniel Constant\u00edn. Los negocios iniciaron con la venta vertical de una\u2026","rel":"","context":"En \u00abActualidad\u00bb","block_context":{"text":"Actualidad","link":"http:\/\/lahoradelcampo.com.uy\/site\/category\/actualidad\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/10\/Caba%C3%B1aSalto-Limitour.jpg?fit=880%2C440&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/10\/Caba%C3%B1aSalto-Limitour.jpg?fit=880%2C440&resize=350%2C200 1x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/10\/Caba%C3%B1aSalto-Limitour.jpg?fit=880%2C440&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/lahoradelcampo.com.uy\/site\/wp-content\/uploads\/2022\/10\/Caba%C3%B1aSalto-Limitour.jpg?fit=880%2C440&resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/17862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/comments?post=17862"}],"version-history":[{"count":1,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/17862\/revisions"}],"predecessor-version":[{"id":17866,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/posts\/17862\/revisions\/17866"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media\/17864"}],"wp:attachment":[{"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/media?parent=17862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/categories?post=17862"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/lahoradelcampo.com.uy\/site\/wp-json\/wp\/v2\/tags?post=17862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}